

{"id":75291,"date":"2019-07-11T10:38:54","date_gmt":"2019-07-11T13:38:54","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=75291"},"modified":"2019-07-11T10:39:12","modified_gmt":"2019-07-11T13:39:12","slug":"foragido-da-operacao-after-e-preso-em-goiatuba","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/foragido-da-operacao-after-e-preso-em-goiatuba\/","title":{"rendered":"Foragido da Opera\u00e7\u00e3o After \u00e9 preso em Goiatuba"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-75292\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg\" alt=\"\" width=\"258\" height=\"258\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg 1068w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-300x300.jpeg 300w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-500x500.jpeg 500w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-768x768.jpeg 768w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-696x696.jpeg 696w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-420x420.jpeg 420w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-840x840.jpeg 840w\" sizes=\"(max-width: 258px) 100vw, 258px\" \/><\/a>Policiais civis lotados na Delegacia de Goiatuba prenderam, no dia 10 de julho, Leonardo Andrade Souza Medeiros, de 31 anos, em raz\u00e3o de cumprimento de mandado de pris\u00e3o preventiva por tr\u00e1fico de drogas e associa\u00e7\u00e3o para o tr\u00e1fico.\u00a0Leonardo \u00e9 um dos tr\u00eas foragidos investigados na Opera\u00e7\u00e3o After, deflagrada no m\u00eas de junho na cidade de Goiatuba.<\/p>\n<p style=\"text-align: justify;\">Novas dilig\u00eancias est\u00e3o sendo realizadas no sentido de prender os foragidos Guilherme Fernandes e Norton Godoi.\u00a0Ap\u00f3s os procedimentos de praxe, o preso foi recolhido na Unidade Prisional de Goiatuba, onde se encontram a disposi\u00e7\u00e3o da justi\u00e7a.<\/p>\n<p><a href=\" https:\/\/goias.gov.br\/policiacivil\/delegacias\/operacao-after-policia-civil-conclui-inquerito-que-investigou-sofisticado-esquema-de-trafico-interestadual.html\" target=\"_blank\" rel=\"noopener\">Opera\u00e7\u00e3o After: Pol\u00edcia Civil conclui inqu\u00e9rito que investigou sofisticado esquema de tr\u00e1fico interestadual<\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Policiais civis lotados na Delegacia de Goiatuba prenderam, no dia 10 de julho, Leonardo Andrade Souza Medeiros, de 31 anos, em raz\u00e3o de cumprimento de mandado de pris\u00e3o preventiva por tr\u00e1fico de drogas e associa\u00e7\u00e3o para o tr\u00e1fico.\u00a0Leonardo \u00e9 um dos tr\u00eas foragidos investigados na Opera\u00e7\u00e3o After, deflagrada no m\u00eas de junho na cidade de [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":75292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3193,89,537],"tags":[7147,102,6986],"class_list":["post-75291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6a-regional","category-regionais","category-ultimo-segundo","tag-after","tag-goiatuba","tag-operacao-after"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg",1068,1068,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg",1068,1068,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg",1068,1068,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros-500x500.jpeg",300,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg",1024,1024,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg",1068,1068,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/07\/leo-nardo-medeiros.jpeg",1068,1068,false]},"rttpg_author":{"display_name":"claudiacury","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/claudiacury\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/6a-regional\/\" rel=\"category tag\">6\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"Policiais civis lotados na Delegacia de Goiatuba prenderam, no dia 10 de julho, Leonardo Andrade Souza Medeiros, de 31 anos, em raz\u00e3o de cumprimento de mandado de pris\u00e3o preventiva por tr\u00e1fico de drogas e associa\u00e7\u00e3o para o tr\u00e1fico.\u00a0Leonardo \u00e9 um dos tr\u00eas foragidos investigados na Opera\u00e7\u00e3o After, deflagrada no m\u00eas de junho na cidade de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/75291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=75291"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/75291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/75292"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=75291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=75291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=75291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}