

{"id":73762,"date":"2019-05-17T12:45:07","date_gmt":"2019-05-17T15:45:07","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=73762"},"modified":"2019-05-17T12:45:20","modified_gmt":"2019-05-17T15:45:20","slug":"suspeito-de-trafico-de-drogas-e-preso-em-goiatuba-4","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/suspeito-de-trafico-de-drogas-e-preso-em-goiatuba-4\/","title":{"rendered":"Suspeito de tr\u00e1fico de drogas \u00e9 preso em Goiatuba"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-73766\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg\" alt=\"\" width=\"291\" height=\"312\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg 958w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba-466x500.jpg 466w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba-768x825.jpg 768w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba-696x748.jpg 696w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba-391x420.jpg 391w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba-782x840.jpg 782w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/a>Policiais civis de Goiatuba prenderam, no dia 16 de maio, S\u00e9rgio Luiz do Carmo, de 32 anos, em raz\u00e3o de cumprimento de Mandado de Pris\u00e3o Preventiva por tr\u00e1fico de drogas e associa\u00e7\u00e3o para o tr\u00e1fico. Ele foi identificado como a pessoa que receberia parte da droga apreendida com seu primo Marcelo de Sousa Oliveira, preso em flagrante em abril \u00faltimo, transportando um tablete de meio quilo de crack, levado de Morrinhos para ser revendido em Goiatuba.<\/p>\n<p style=\"text-align: justify;\">Com base no depoimento do autor e outros elementos de prova colhidos, a autoridade policial representou pela pris\u00e3o preventiva de S\u00e9rgio, o qual foi v\u00edtima de tentativa de homic\u00eddio no ano passado em raz\u00e3o de disputa de territ\u00f3rio por drogas, mas ainda assim voltou a se envolver com a atividade il\u00edcita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais civis de Goiatuba prenderam, no dia 16 de maio, S\u00e9rgio Luiz do Carmo, de 32 anos, em raz\u00e3o de cumprimento de Mandado de Pris\u00e3o Preventiva por tr\u00e1fico de drogas e associa\u00e7\u00e3o para o tr\u00e1fico. Ele foi identificado como a pessoa que receberia parte da droga apreendida com seu primo Marcelo de Sousa Oliveira, preso [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":73766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3193,89,537],"tags":[102],"class_list":["post-73762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6a-regional","category-regionais","category-ultimo-segundo","tag-goiatuba"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg",958,1029,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg",958,1029,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg",958,1029,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba-300x300.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba-466x500.jpg",280,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg",953,1024,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg",958,1029,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/sergio-luiz-goiatuba.jpg",958,1029,false]},"rttpg_author":{"display_name":"claudiacury","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/claudiacury\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/6a-regional\/\" rel=\"category tag\">6\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"Policiais civis de Goiatuba prenderam, no dia 16 de maio, S\u00e9rgio Luiz do Carmo, de 32 anos, em raz\u00e3o de cumprimento de Mandado de Pris\u00e3o Preventiva por tr\u00e1fico de drogas e associa\u00e7\u00e3o para o tr\u00e1fico. Ele foi identificado como a pessoa que receberia parte da droga apreendida com seu primo Marcelo de Sousa Oliveira, preso&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/73762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=73762"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/73762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/73766"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=73762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=73762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=73762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}