

{"id":73456,"date":"2019-05-09T17:26:26","date_gmt":"2019-05-09T20:26:26","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=73456"},"modified":"2019-05-09T17:26:26","modified_gmt":"2019-05-09T20:26:26","slug":"preso-em-planaltina-suspeito-de-homicidio","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/preso-em-planaltina-suspeito-de-homicidio\/","title":{"rendered":"Preso em Planaltina suspeito de homic\u00eddio"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-73457 alignleft\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson-484x500.jpg\" alt=\"\" width=\"358\" height=\"370\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson-484x500.jpg 484w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson-407x420.jpg 407w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson.jpg 639w\" sizes=\"(max-width: 358px) 100vw, 358px\" \/>O Grupo de Investiga\u00e7\u00e3o de Homic\u00eddios (GIH) de Planaltina de Goi\u00e1s deu cumprimento ao mandado de pris\u00e3o, na \u00faltima ter\u00e7a-feira (7), contra o investigado Romilson Silva de Lima, vulgo &#8220;Catraca&#8221;.<\/p>\n<p style=\"text-align: justify;\">Segundo a investiga\u00e7\u00e3o, Romilson, Jos\u00e9 Maik Alves de Souza e Jheymison de Souza Oliveira mataram, no dia 6 de mar\u00e7o de 2017, a v\u00edtima Bernardo Costa da Silva, no bairro Paquet\u00e1. Ao perceber que os autores se aproximavam, Bernardo adentrou em uma loja de m\u00f3veis usados, mas, sem chances de rea\u00e7\u00e3o, foi atingido por diversos disparos de arma de fogo. Gravemente lesionado no rosto e na cabe\u00e7a, Bernardo faleceu ainda no com\u00e9rcio.<\/p>\n<p style=\"text-align: justify;\">\nJheymison de Souza foi morto no dia 16 de agosto de 2017 e Jos\u00e9 Maik, no dia 12 de outubro do ano passado. O autuado Romilson encontra-se \u00e0 disposi\u00e7\u00e3o do Poder Judici\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Grupo de Investiga\u00e7\u00e3o de Homic\u00eddios (GIH) de Planaltina de Goi\u00e1s deu cumprimento ao mandado de pris\u00e3o, na \u00faltima ter\u00e7a-feira (7), contra o investigado Romilson Silva de Lima, vulgo &#8220;Catraca&#8221;. Segundo a investiga\u00e7\u00e3o, Romilson, Jos\u00e9 Maik Alves de Souza e Jheymison de Souza Oliveira mataram, no dia 6 de mar\u00e7o de 2017, a v\u00edtima Bernardo [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":73457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3198,2538,537],"tags":[1291,23,754],"class_list":["post-73456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11a-regional","category-delegacias","category-ultimo-segundo","tag-gih","tag-homicidio","tag-planaltina"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson.jpg",639,660,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson.jpg",639,660,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson.jpg",639,660,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson-300x300.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson-484x500.jpg",290,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson.jpg",639,660,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson.jpg",639,660,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/05\/romilson.jpg",639,660,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/11a-regional\/\" rel=\"category tag\">11\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"O Grupo de Investiga\u00e7\u00e3o de Homic\u00eddios (GIH) de Planaltina de Goi\u00e1s deu cumprimento ao mandado de pris\u00e3o, na \u00faltima ter\u00e7a-feira (7), contra o investigado Romilson Silva de Lima, vulgo &#8220;Catraca&#8221;. Segundo a investiga\u00e7\u00e3o, Romilson, Jos\u00e9 Maik Alves de Souza e Jheymison de Souza Oliveira mataram, no dia 6 de mar\u00e7o de 2017, a v\u00edtima Bernardo&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/73456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=73456"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/73456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/73457"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=73456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=73456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=73456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}