{"id":67589,"date":"2018-08-16T09:44:52","date_gmt":"2018-08-16T12:44:52","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=67589"},"modified":"2018-08-16T09:44:52","modified_gmt":"2018-08-16T12:44:52","slug":"policiais-civis-e-militares-de-piranhas-prendem-dupla-que-assaltou-idoso","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/policiais-civis-e-militares-de-piranhas-prendem-dupla-que-assaltou-idoso\/","title":{"rendered":"Policiais civis e militares de Piranhas prendem dupla que assaltou idoso"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-67595\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg\" alt=\"\" width=\"320\" height=\"213\" \/><\/a>Uma a\u00e7\u00e3o envolvendo policiais civis e militares de Piranhas levou \u00e0 pris\u00e3o, na \u00faltima ter\u00e7a-feira (14\/08), de Rom\u00e1rio de Jesus Martins, 21 anos, e Sivaldo Lopes da Silva, 24 anos. Os dois foram autuados em flagrante pela pr\u00e1tica de um roubo contra um idoso de 81 anos.<\/p>\n<p style=\"text-align: justify;\">De acordo com o delegado Marlon Souza Luz, os criminosos, de posse de uma faca, invadiram a casa da v\u00edtima em plena luz do dia, ocasi\u00e3o em que anunciaram o assalto, subtraindo valores em dinheiro e um ve\u00edculo que foi abandonado ainda na garagem da resid\u00eancia. &#8220;Ap\u00f3s a not\u00edcia do crime, os dedicados policiais civis e militares lotados no munic\u00edpio empreenderam persegui\u00e7\u00e3o pela rodovia BR-158, sentido Bom Jardim de Goi\u00e1s, interceptando os autores e realizando a pris\u00e3o&#8221;, comentou o delegado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma a\u00e7\u00e3o envolvendo policiais civis e militares de Piranhas levou \u00e0 pris\u00e3o, na \u00faltima ter\u00e7a-feira (14\/08), de Rom\u00e1rio de Jesus Martins, 21 anos, e Sivaldo Lopes da Silva, 24 anos. Os dois foram autuados em flagrante pela pr\u00e1tica de um roubo contra um idoso de 81 anos. De acordo com o delegado Marlon Souza Luz, [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":67595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3194,89,537],"tags":[1766,1252,2664,3217],"class_list":["post-67589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7a-regional","category-regionais","category-ultimo-segundo","tag-assalto","tag-idoso","tag-marlon","tag-piranhas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg",320,213,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg",320,213,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg",320,213,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto-300x213.jpg",150,107,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg",300,200,false],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg",320,213,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg",320,213,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2018\/08\/foto.jpg",320,213,false]},"rttpg_author":{"display_name":"claudiacury","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/claudiacury\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/7a-regional\/\" rel=\"category tag\">7\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"Uma a\u00e7\u00e3o envolvendo policiais civis e militares de Piranhas levou \u00e0 pris\u00e3o, na \u00faltima ter\u00e7a-feira (14\/08), de Rom\u00e1rio de Jesus Martins, 21 anos, e Sivaldo Lopes da Silva, 24 anos. Os dois foram autuados em flagrante pela pr\u00e1tica de um roubo contra um idoso de 81 anos. De acordo com o delegado Marlon Souza Luz,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/67589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=67589"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/67589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/67595"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=67589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=67589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=67589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}