{"id":57050,"date":"2017-10-20T08:07:46","date_gmt":"2017-10-20T10:07:46","guid":{"rendered":"https:\/\/goias.gov.br\/policiacivil\/?p=57050"},"modified":"2017-10-20T08:07:46","modified_gmt":"2017-10-20T10:07:46","slug":"operacao-conjunta-entre-pc-e-pm-apreende-10-kg-de-maconha-em-aragarcas","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/operacao-conjunta-entre-pc-e-pm-apreende-10-kg-de-maconha-em-aragarcas\/","title":{"rendered":"Opera\u00e7\u00e3o conjunta entre PC e PM apreende 10 kg de maconha em Aragar\u00e7as"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-large wp-image-57051\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-350x263.jpeg\" alt=\"droga aragarcas\" width=\"350\" height=\"263\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-350x263.jpeg 350w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-220x165.jpeg 220w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-80x60.jpeg 80w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-160x120.jpeg 160w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-265x198.jpeg 265w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-530x396.jpeg 530w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-560x420.jpeg 560w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas.jpeg 620w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a>A terceira fase de uma opera\u00e7\u00e3o integrada entre a Pol\u00edcia Civil e a Pol\u00edcia Militar de Aragar\u00e7as e a Pol\u00edcia Militar de Barra do Gar\u00e7as culminou com a apreens\u00e3o de aproximadamente 10,75 quilos de subst\u00e2ncia entorpecente an\u00e1loga \u00e0 maconha. Segundo o delegado de Aragar\u00e7as, Ricardo Galv\u00e3o, a quantia foi localizada no Setor Nova Esperan\u00e7a, naquele munic\u00edpio. O pr\u00f3ximo passo \u00e9 identificar quem \u00e9 o dono da droga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A terceira fase de uma opera\u00e7\u00e3o integrada entre a Pol\u00edcia Civil e a Pol\u00edcia Militar de Aragar\u00e7as e a Pol\u00edcia Militar de Barra do Gar\u00e7as culminou com a apreens\u00e3o de aproximadamente 10,75 quilos de subst\u00e2ncia entorpecente an\u00e1loga \u00e0 maconha. Segundo o delegado de Aragar\u00e7as, Ricardo Galv\u00e3o, a quantia foi localizada no Setor Nova Esperan\u00e7a, naquele [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":57051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3194,537],"tags":[325],"class_list":["post-57050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7a-regional","category-ultimo-segundo","tag-aragarcas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas.jpeg",620,465,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas.jpeg",620,465,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas.jpeg",620,465,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-220x165.jpeg",220,165,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas-350x263.jpeg",350,263,true],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas.jpeg",620,465,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/10\/droga-aragarcas.jpeg",620,465,false]},"rttpg_author":{"display_name":"claudiacury","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/claudiacury\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/7a-regional\/\" rel=\"category tag\">7\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"A terceira fase de uma opera\u00e7\u00e3o integrada entre a Pol\u00edcia Civil e a Pol\u00edcia Militar de Aragar\u00e7as e a Pol\u00edcia Militar de Barra do Gar\u00e7as culminou com a apreens\u00e3o de aproximadamente 10,75 quilos de subst\u00e2ncia entorpecente an\u00e1loga \u00e0 maconha. Segundo o delegado de Aragar\u00e7as, Ricardo Galv\u00e3o, a quantia foi localizada no Setor Nova Esperan\u00e7a, naquele&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/57050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=57050"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/57050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/57051"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=57050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=57050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=57050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}