{"id":36075,"date":"2015-06-03T07:34:11","date_gmt":"2015-06-03T10:34:11","guid":{"rendered":"https:\/\/goias.gov.br\/policiacivil\/?p=36075"},"modified":"2015-06-03T07:34:11","modified_gmt":"2015-06-03T10:34:11","slug":"cultura-do-encarceramento","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/cultura-do-encarceramento\/","title":{"rendered":"Cultura do encarceramento"},"content":{"rendered":"<figure id=\"attachment_36076\" aria-describedby=\"caption-attachment-36076\" style=\"width: 318px\" class=\"wp-caption alignleft\"><a href=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-36076   \" alt=\"Jesseir Coelho de Alc\u00e2ntara\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg\" width=\"318\" height=\"211\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg 620w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11-300x200.jpg 300w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11-350x233.jpg 350w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11-220x147.jpg 220w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/><\/a><figcaption id=\"caption-attachment-36076\" class=\"wp-caption-text\">Jesseir Coelho de Alc\u00e2ntara<\/figcaption><\/figure>\n<p><em><strong>\u00a0\u00a0 Cultura do encarceramento<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>O Brasil tem hoje cerca de 600 mil presos, sendo 40% deles provis\u00f3rios. Isso equivale a 240 mil presos que n\u00e3o foram condenados por uma senten\u00e7a penal definitiva ou transitada em julgado e, mesmo assim, continuam encarcerados. Isto, a despeito da Constitui\u00e7\u00e3o Federal no t\u00edtulo que trata dos direitos e garantias fundamentais proclamar que: \u201cningu\u00e9m ser\u00e1 considerado culpado at\u00e9 o tr\u00e2nsito em julgado de senten\u00e7a penal condenat\u00f3ria\u201d (art. 5\u00ba, LVII).<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>No que pese toda essa f\u00faria punitiva, o aumento do encarceramento n\u00e3o reduz a criminalidade como alguns poderiam imaginar. N\u00e3o h\u00e1 correla\u00e7\u00e3o entre aprisionamento e diminui\u00e7\u00e3o dos \u00edndices de crimes. A pr\u00e1tica mostra isso.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>A quest\u00e3o da cultura do encarceramento no Brasil, a meu ver, est\u00e1 voltada aos efeitos e n\u00e3o \u00e0 causa do problema. Esse posicionamento est\u00e1 arraigado em nosso consciente ante a falta de pol\u00edticas p\u00fablicas de educa\u00e7\u00e3o e conscientiza\u00e7\u00e3o pela in\u00e9rcia estatal. O poder p\u00fablico n\u00e3o oferece condi\u00e7\u00f5es b\u00e1sicas para a preven\u00e7\u00e3o da alta criminalidade e, como consequ\u00eancia, temos de arrumar um paliativo para corrigir distor\u00e7\u00f5es. O resultado disso \u00e9 um apelo social e midi\u00e1tico para o crescimento das pris\u00f5es.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>Alguns juristas atacam o excesso de pris\u00f5es no pa\u00eds e a ideia de que quanto mais gente presa, mais seguran\u00e7a a sociedade ter\u00e1.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>O problema est\u00e1 voltado ao aumento da criminalidade e onde colocar transgressores da lei. O agente comete um delito e se ficar solto torna-se um risco para a sociedade. O que fazer? E a sociedade, como fica? Perguntas dif\u00edceis de respostas.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>Existem cr\u00edticas contundentes sobre o encarceramento exagerado de acusados da pr\u00e1tica de crime. O problema \u00e9 que os cr\u00edticos desse sistema se olvidam de que atualmente a sociedade \u00e9 que vive trancafiada e acuada com medo de sair de casa. E mesmo assim muitos s\u00e3o importunados por assaltantes dentro de seu pr\u00f3prio ref\u00fagio. O cidad\u00e3o de bem est\u00e1 esquecido e desprezado de que ele \u00e9 que \u00e9 vitima de um \u201cencarceramento\u201d em seu lar. Parece at\u00e9 que para bandido \u2018afago na cabe\u00e7a\u2019, mas para o homem honesto e trabalhador \u2018pau na moleira\u2019.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>\u00c9 evidente que n\u00e3o todo suspeito que comete um crime merece cadeia. Ali\u00e1s, a pr\u00f3pria legisla\u00e7\u00e3o brasileira \u00e9 extremamente garantista quanto a isso. N\u00e3o h\u00e1 motivos de preocupa\u00e7\u00e3o no que tange a esse aspecto. Claro que existem casos dignos de absolvi\u00e7\u00e3o. Justi\u00e7a seja feita.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>A \u201ccultura do encarceramento\u201d, em algumas situa\u00e7\u00f5es tem de mudar, mas n\u00e3o adianta arrumar paliativos como desculpa e faz de conta num formalismo exagerado. A quest\u00e3o da superlota\u00e7\u00e3o dos pres\u00eddios n\u00e3o \u00e9 problema do Poder Judici\u00e1rio. Cabe ao Executivo gerir e dele deve ser exigido.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>N\u00e3o se deve arrumar desculpas de excesso de encarceramento com prega\u00e7\u00e3o de garantismo demagogo e exagerado.<\/strong><\/em><\/p>\n<p><em><strong>Jesseir Coelho de Alc\u00e2ntara \u00e9 Juiz de Direito e Professor<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jesseir Coelho de Alc\u00e2ntara \u00e9 Juiz de Direito <\/p>\n","protected":false},"author":4,"featured_media":36076,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[1671,3780,1139,1431],"class_list":["post-36075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-brasil","tag-encarceramento","tag-jesseir","tag-juiz"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg",620,413,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg",620,413,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg",620,413,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11-300x200.jpg",300,200,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11-350x233.jpg",350,233,true],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg",620,413,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/06\/jesseir-coelho-11.jpg",620,413,false]},"rttpg_author":{"display_name":"","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/artigos\/\" rel=\"category tag\">Artigos<\/a>","rttpg_excerpt":"Jesseir Coelho de Alc\u00e2ntara \u00e9 Juiz de Direito","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/36075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=36075"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/36075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/36076"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=36075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=36075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=36075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}