{"id":35800,"date":"2015-05-19T14:19:15","date_gmt":"2015-05-19T17:19:15","guid":{"rendered":"https:\/\/goias.gov.br\/policiacivil\/?p=35800"},"modified":"2015-05-19T14:19:15","modified_gmt":"2015-05-19T17:19:15","slug":"flanelinha-crime","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/flanelinha-crime\/","title":{"rendered":"Flanelinha: Crime ?"},"content":{"rendered":"<figure id=\"attachment_35801\" aria-describedby=\"caption-attachment-35801\" style=\"width: 256px\" class=\"wp-caption alignleft\"><a href=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/sites\/71\/2015\/05\/jesseir-3.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-35801  \" alt=\"Jesseir Coelho de Alc\u00e2natara\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/sites\/71\/2015\/05\/jesseir-3.jpg\" width=\"256\" height=\"256\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3.jpg 400w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3-300x300.jpg 300w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3-150x150.jpg 150w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3-200x200.jpg 200w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/a><figcaption id=\"caption-attachment-35801\" class=\"wp-caption-text\">Jesseir Coelho de Alc\u00e2natara<\/figcaption><\/figure>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Flanelinha: Crime ?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Flanelinha \u00e9 o apelido dado a um indiv\u00edduo geralmente n\u00e3o regulamentado, que por norma se utiliza de coa\u00e7\u00e3o para conseguir remunera\u00e7\u00e3o pelos servi\u00e7os prestados no estacionamento, na limpeza ou na prote\u00e7\u00e3o de um ve\u00edculo em via p\u00fablica. A a\u00e7\u00e3o dos flanelinhas por si s\u00f3 n\u00e3o representa crime algum, pois n\u00e3o h\u00e1 na lei penal um dispositivo espec\u00edfico para sua tipifica\u00e7\u00e3o. Entretanto, a partir da an\u00e1lise de cada caso concreto \u00e9 poss\u00edvel o enquadramento da conduta dos guardadores clandestinos em algum delito.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Alguns ju\u00edzes entenderam pela tipifica\u00e7\u00e3o da conduta dos flanelinhas como crime. Um magistrado condenou um guardador clandestino de ve\u00edculos a quatro anos e seis meses de reclus\u00e3o pela pr\u00e1tica do crime de extors\u00e3o. Nesta decis\u00e3o, o magistrado aproveitou para chamar aten\u00e7\u00e3o do poder p\u00fablico para essa perturbadora situa\u00e7\u00e3o cotidiana, afirmando que &#8220;est\u00e1 passada a hora das autoridades assumirem uma postura desprovida de hipocrisia em rela\u00e7\u00e3o \u00e0 atua\u00e7\u00e3o nefasta dos chamados \u2018flanelinhas\u2019 que, a pretexto de trabalho, exigem dos motoristas pagamento por servi\u00e7os de vigil\u00e2ncia para estacionar em via p\u00fablica, arvorando-se \u2018donos\u2019 do espa\u00e7o p\u00fablico, quando se sabe que o que se cobra n\u00e3o \u00e9 vigil\u00e2ncia, mas pagamento para n\u00e3o ter o bem danificado\u201d.\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Outra decis\u00e3o foi proferida por uma Ju\u00edza de Balne\u00e1rio Cambori\u00fa, em que condenou um flanelinha a quatro anos de pris\u00e3o em regime aberto por tentativa de extors\u00e3o. Ela tamb\u00e9m criticou a a\u00e7\u00e3o de guardadores de carros nas metr\u00f3poles e asseverou que &#8220;n\u00e3o h\u00e1 d\u00favidas de que vivemos em um pa\u00eds de grandes desigualdades sociais e onde o emprego \u00e9 escasso. Todavia, tal fato n\u00e3o implica em flanelinhas lotearem grande parte das vias p\u00fablicas, exigindo pre\u00e7os alt\u00edssimos para que os ve\u00edculos permane\u00e7am inc\u00f3lumes&#8221;.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Sobre o enquadramento da conduta como crime, h\u00e1 diverg\u00eancias at\u00e9 mesmo entre os \u00f3rg\u00e3os Policiais, conforme noticiado pelo O Globo: \u201cOs comandos das Pol\u00edcias Civil e Militar discordam sobre a poss\u00edvel conduta criminosa na abordagem dos flanelinhas. Para a Pol\u00edcia Militar, no simples fato de pedir dinheiro para guardar os carros, os flanelinhas j\u00e1 amea\u00e7am os motoristas, pois est\u00e1 subentendido que, se a pessoa n\u00e3o pagar, algo pode acontecer com o ve\u00edculo. Isso caracteriza extors\u00e3o, segundo a PM.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0J\u00e1 a Pol\u00edcia Civil afirma que, para se caracterizar a extors\u00e3o, o flanelinha teria que amea\u00e7ar o motorista ao pedir o dinheiro\u201d. H\u00e1 ainda juristas que entendem que a a\u00e7\u00e3o se enquadra em constrangimento ilegal, estelionato ou amea\u00e7a.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>A Pol\u00edcia Civil em Goi\u00e1s recentemente autuou alguns homens pela contraven\u00e7\u00e3o penal de exerc\u00edcio ilegal da profiss\u00e3o lavrando-se TCO e liberando-os em seguida. Havia gente com envolvimento em furtos, roubos e extors\u00f5es. Esses continuaram presos. Na realidade o que se conclui \u00e9 que, crime ou n\u00e3o, a pr\u00e1tica de vigiar carros por parte dos flanelinhas constitui\u00a0 constrangimento.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p><strong>Jesseir Coelho de Alc\u00e2ntara \u00e9 Juiz de Direito e Professor<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jesseir Coelho de Alc\u00e2ntara \u00e9 Juiz de Direito<\/p>\n","protected":false},"author":4,"featured_media":35801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[3173,3754,1139,1431],"class_list":["post-35800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-extorsao","tag-flanelinha","tag-jesseir","tag-juiz"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3.jpg",400,400,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3.jpg",400,400,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3.jpg",400,400,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3-300x300.jpg",300,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3-300x300.jpg",300,300,true],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3.jpg",400,400,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2015\/05\/jesseir-3.jpg",400,400,false]},"rttpg_author":{"display_name":"","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/artigos\/\" rel=\"category tag\">Artigos<\/a>","rttpg_excerpt":"Jesseir Coelho de Alc\u00e2ntara \u00e9 Juiz de Direito","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/35800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=35800"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/35800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/35801"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=35800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=35800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=35800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}