{"id":2681,"date":"2018-02-20T14:30:06","date_gmt":"2018-02-20T17:30:06","guid":{"rendered":"http:\/\/identificacao.policiacivil.go.gov.br\/?p=2681"},"modified":"2026-06-02T22:25:55","modified_gmt":"2026-06-03T01:25:55","slug":"o-popular-publica-artigo-de-datiloscopista-do-instituto-de-identificacao-sobre-o-crime-organizado","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/o-popular-publica-artigo-de-datiloscopista-do-instituto-de-identificacao-sobre-o-crime-organizado\/","title":{"rendered":"O Popular publica artigo de datiloscopista do Instituto de Identifica\u00e7\u00e3o sobre o crime organizado"},"content":{"rendered":"<p><strong>O NOVO MINIST\u00c9RIO<\/strong><\/p>\n<p><em>Por Ant\u00f4nio Maciel Aguiar Filho*<\/em><\/p>\n<p>O crime organizado possui uma estrutura e organiza\u00e7\u00e3o que muitas vezes falta ao Estado. Eles se armam, roubam, traficam armas, drogas e at\u00e9 pessoas, matam de forma disciplinada e cruel, dificultando a a\u00e7\u00e3o dos \u00f3rg\u00e3os e agentes p\u00fablicos, carentes, via de regra, de informa\u00e7\u00f5es, de sistemas de intelig\u00eancias e, o mais grave, de falta de recursos para adquirir.<\/p>\n<p>Neste contexto o servi\u00e7o de intelig\u00eancia do pa\u00eds ou de qualquer unidade federativa deve ser priorizado, e a uni\u00e3o deve assumir este papel, afinal o crime ganhou dimens\u00e3o nacional e se tornou banal. Em Goi\u00e1s o governo deu demonstra\u00e7\u00e3o desta necessidade ao instituir recentemente a Ag\u00eancia de Intelig\u00eancia estadual mais abrangente do pa\u00eds, criando por decreto, o Sistema de Intelig\u00eancia de Seguran\u00e7a P\u00fablica (SISP GO) que visa dentre outros objetivos, a inclus\u00e3o de todas as for\u00e7as de seguran\u00e7a e, tamb\u00e9m, a cria\u00e7\u00e3o de um subsistema especifico para efetivar parcerias e coopera\u00e7\u00e3o com outras institui\u00e7\u00f5es para a produ\u00e7\u00e3o de informa\u00e7\u00f5es de maior qualidade.<\/p>\n<p>Temer anunciou a cria\u00e7\u00e3o do Minist\u00e9rio da Seguran\u00e7a P\u00fablica, incorporando ao novo Minist\u00e9rio a PF (Pol\u00edcia Federal), PRF (Pol\u00edcia Rodovi\u00e1ria Federal), Depen (Departamento Penitenci\u00e1rio Nacional) e Senasp (Secretaria Nacional de Seguran\u00e7a P\u00fablica). Acontece que somente dividir Minist\u00e9rio n\u00e3o significa melhor enfrentamento a criminalidade, \u00e9 preciso admitir que o crime organizado tupiniquim esparramou-se pelo pais e que hoje j\u00e1 se associa ao crime organizado internacional, sobretudo os traficantes de armas, de drogas ou de pessoas, criando um ciclo de enriquecimento e poder que afronta as for\u00e7as policiais, a autonomia dos pa\u00edses e, por que n\u00e3o dizer ao pr\u00f3prio estado de direito. Portanto, s\u00e3o necess\u00e1rias a\u00e7\u00f5es integradas e inteligentes, capazes de reagir a este cen\u00e1rio extremamente preocupante e desolador.<\/p>\n<p>Neste contexto, uma das principais solu\u00e7\u00f5es a ser buscada por meio deste novo Minist\u00e9rio, al\u00e9m, \u00e9 claro, de indicar um t\u00e9cnico competente e n\u00e3o um pol\u00edtico para ocupar a nova fun\u00e7\u00e3o, \u00e9 convergir esfor\u00e7os de interoperabilidade na \u00e1rea de intelig\u00eancia e entre os sistemas de identifica\u00e7\u00e3o biom\u00e9tricos e biogr\u00e1ficos existentes no pa\u00eds (TRE, Detran, Institutos de Identifica\u00e7\u00e3o e Cart\u00f3rios) e mesmo entre os pa\u00edses vizinhos que j\u00e1 disp\u00f5em destas tecnologias<\/p>\n<p>S\u00f3 assim, alavancando a capacidade de intelig\u00eancia investigativa das for\u00e7as policiais, pode surgir uma luz no fim do t\u00fanel, diante da total inseguran\u00e7a p\u00fablica no Pa\u00eds.<\/p>\n<p><em>* Datiloscopista Policial e Presidente da Federa\u00e7\u00e3o Nacional dos Peritos Oficiais em Identifica\u00e7\u00e3o \u2013 FENAPPI, especialista em pericia criminal e ambiental, Atualmente lotado na CIT- Coordena\u00e7\u00e3o de Inova\u00e7\u00e3o e Tecnologia da Policia Civil.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datiloscopista Policial e Presidente da Federa\u00e7\u00e3o Nacional dos Peritos Oficiais em Identifica\u00e7\u00e3o \u2013 FENAPPI, especialista em pericia criminal e ambiental, Atualmente lotado na CIT- Coordena\u00e7\u00e3o de Inova\u00e7\u00e3o e Tecnologia da Policia Civil.<\/p>\n","protected":false},"author":969,"featured_media":3000,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11648,11640],"tags":[],"class_list":["post-2681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-goias-biometrico","category-superintendencia-de-identificacao-humana"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado.jpg",400,400,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado.jpg",400,400,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado.jpg",400,400,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado-300x300.jpg",300,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado-300x300.jpg",300,300,true],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado.jpg",400,400,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/12\/furtado.jpg",400,400,false]},"rttpg_author":{"display_name":"","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/goias-biometrico\/\" rel=\"category tag\">Goi\u00e1s Biom\u00e9trico<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/superintendencia-de-identificacao-humana\/\" rel=\"category tag\">Superintend\u00eancia de Identifica\u00e7\u00e3o Humana<\/a>","rttpg_excerpt":"Datiloscopista Policial e Presidente da Federa\u00e7\u00e3o Nacional dos Peritos Oficiais em Identifica\u00e7\u00e3o \u2013 FENAPPI, especialista em pericia criminal e ambiental, Atualmente lotado na CIT- Coordena\u00e7\u00e3o de Inova\u00e7\u00e3o e Tecnologia da Policia Civil.","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/2681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/969"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=2681"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/2681\/revisions"}],"predecessor-version":[{"id":231337,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/2681\/revisions\/231337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/3000"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=2681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=2681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=2681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}