{"id":202294,"date":"2021-12-06T18:40:06","date_gmt":"2021-12-06T21:40:06","guid":{"rendered":"http:\/\/identificacao.policiacivil.go.gov.br\/?p=3958"},"modified":"2026-06-02T22:26:08","modified_gmt":"2026-06-03T01:26:08","slug":"quais-documentos-levar-para-o-requerimento-do-rg-goias","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/quais-documentos-levar-para-o-requerimento-do-rg-goias\/","title":{"rendered":"Quais documentos levar para o Requerimento do RG Goi\u00e1s?"},"content":{"rendered":"<p><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-3959 alignright\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2021\/12\/documentos-620x376.jpg\" alt=\"\" width=\"358\" height=\"217\">Para emitir o RG em Goi\u00e1s \u00e9 obrigat\u00f3rio apresentar <strong>Certid\u00e3o Original<\/strong>\u00a0de Nascimento ou de Casamento (incluindo caso de averba\u00e7\u00e3o de div\u00f3rcio) e comprovante de endere\u00e7o, bem como podem ser inclu\u00eddos, opcionalmente, outras informa\u00e7\u00f5es, como dispostas no Art. 8\u00ba, do decreto mencionado.<\/p>\n<p>Ser\u00e1 inclu\u00eddo na Carteira de Identidade, mediante solicita\u00e7\u00e3o:<br \/>\nI \u2013 o n\u00famero do DNI;<br \/>\nII \u2013 o N\u00famero de Identifica\u00e7\u00e3o Social \u2013 NIS, o n\u00famero no Programa de Integra\u00e7\u00e3o Social \u2013 PIS ou o n\u00famero no Programa de Forma\u00e7\u00e3o do Patrim\u00f4nio do Servidor P\u00fablico \u2013 PASEP;<br \/>\nIII \u2013 o n\u00famero do Cart\u00e3o Nacional de Sa\u00fade;<br \/>\nIV \u2013 o n\u00famero do T\u00edtulo de Eleitor;<br \/>\nV \u2013 o n\u00famero do documento de identidade profissional expedido por \u00f3rg\u00e3o ou entidade legalmente autorizado;<br \/>\nVI \u2013 o n\u00famero da Carteira de Trabalho e Previd\u00eancia Social;<br \/>\nVII \u2013 o n\u00famero da Carteira Nacional de Habilita\u00e7\u00e3o;<br \/>\nVIII \u2013 o n\u00famero do Certificado Militar;<br \/>\nIX \u2013 o tipo sangu\u00edneo e o fator Rh;<br \/>\nX \u2013 as condi\u00e7\u00f5es espec\u00edficas de sa\u00fade cuja divulga\u00e7\u00e3o possa contribuir para preservar a sa\u00fade ou salvar a vida do titular; e<br \/>\nXI \u2013 o nome social.<\/p>\n<ul>\n<li>1\u00ba A comprova\u00e7\u00e3o das informa\u00e7\u00f5es de que tratam os incisos I a VIII do\u00a0<strong>caput\u00a0<\/strong>ser\u00e1 feita por meio, respectivamente:<\/li>\n<\/ul>\n<p>I \u2013 da valida\u00e7\u00e3o biom\u00e9trica com a base de dados da ICN;<br \/>\nII \u2013 dos cart\u00f5es de inscri\u00e7\u00e3o no NIS, no PIS ou no PASEP;<br \/>\nIII \u2013 do Cart\u00e3o Nacional de Sa\u00fade;<br \/>\nIV \u2013 do T\u00edtulo de Eleitor;<br \/>\nV \u2013 do documento de identidade profissional expedido por \u00f3rg\u00e3o ou entidade legalmente autorizado;<br \/>\nVI \u2013 da Carteira de Trabalho e Previd\u00eancia Social;<br \/>\nVII \u2013 da Carteira Nacional de Habilita\u00e7\u00e3o;<br \/>\nVIII \u2013 do Certificado Militar;<br \/>\nIX \u2013 do resultado de exame laboratorial; e<br \/>\nX \u2013 do atestado m\u00e9dico ou documento oficial que comprove a vulnerabilidade ou a condi\u00e7\u00e3o particular de sa\u00fade que se deseje preservar, nos termos do inciso X do\u00a0<strong>caput\u00a0<\/strong>.<\/p>\n<ul>\n<li>2\u00ba Em substitui\u00e7\u00e3o aos documentos de que tratam os incisos I a VIII do<strong>caput<\/strong>,\u00a0ser\u00e1 aceita a apresenta\u00e7\u00e3o de documento de identidade v\u00e1lido para todos os fins legais do qual constem as informa\u00e7\u00f5es a serem comprovadas.<\/li>\n<li>3\u00ba A comprova\u00e7\u00e3o pelo interessado das informa\u00e7\u00f5es de que tratam os incisos II a X do<strong>caput<\/strong>ser\u00e1 dispensada na hip\u00f3tese do \u00f3rg\u00e3o de identifica\u00e7\u00e3o ter acesso \u00e0s informa\u00e7\u00f5es por meio de base eletr\u00f4nica de dados de \u00f3rg\u00e3o ou entidade p\u00fablicos.<\/li>\n<li>4\u00ba O nome social de que trata o inciso XI do<strong>caput<\/strong>:<\/li>\n<\/ul>\n<p>I \u2013 ser\u00e1 inclu\u00eddo:<\/p>\n<ol>\n<li>mediante requerimento escrito do interessado;<\/li>\n<li>com a express\u00e3o \u201cnome social\u201d;<\/li>\n<li>sem preju\u00edzo da men\u00e7\u00e3o ao nome do registro civil no verso da Carteira de Identidade; e<\/li>\n<li>sem a exig\u00eancia de documenta\u00e7\u00e3o comprobat\u00f3ria; e<\/li>\n<\/ol>\n<p>II \u2013 poder\u00e1 ser exclu\u00eddo por meio de requerimento escrito do interessado.<\/p>\n<ul>\n<li>5\u00ba O requerimento de que trata a al\u00ednea \u201ca\u201d do inciso I do \u00a7 4\u00ba ser\u00e1 arquivado no \u00f3rg\u00e3o de identifica\u00e7\u00e3o, juntamente com o hist\u00f3rico de altera\u00e7\u00f5es do nome social.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Para emitir o RG em Goi\u00e1s \u00e9 obrigat\u00f3rio apresentar Certid\u00e3o Original\u00a0de Nascimento ou de Casamento (incluindo caso de averba\u00e7\u00e3o de div\u00f3rcio) e comprovante de endere\u00e7o, bem como podem ser inclu\u00eddos, opcionalmente, outras informa\u00e7\u00f5es, como dispostas no Art. 8\u00ba, do decreto mencionado. Ser\u00e1 inclu\u00eddo na Carteira de Identidade, mediante solicita\u00e7\u00e3o: I \u2013 o n\u00famero do DNI; [&hellip;]<\/p>\n","protected":false},"author":969,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11641,11767,11640],"tags":[7310,5003,9451],"class_list":["post-202294","post","type-post","status-publish","format-standard","hentry","category-gerencia-identificacao-civil","category-rg","category-superintendencia-de-identificacao-humana","tag-carteira-de-identidade","tag-rg","tag-rg-goias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/gerencia-identificacao-civil\/\" rel=\"category tag\">Ger\u00eancia de Identifica\u00e7\u00e3o Civil<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/rg\/\" rel=\"category tag\">RG<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/superintendencia-de-identificacao-humana\/\" rel=\"category tag\">Superintend\u00eancia de Identifica\u00e7\u00e3o Humana<\/a>","rttpg_excerpt":"Para emitir o RG em Goi\u00e1s \u00e9 obrigat\u00f3rio apresentar Certid\u00e3o Original\u00a0de Nascimento ou de Casamento (incluindo caso de averba\u00e7\u00e3o de div\u00f3rcio) e comprovante de endere\u00e7o, bem como podem ser inclu\u00eddos, opcionalmente, outras informa\u00e7\u00f5es, como dispostas no Art. 8\u00ba, do decreto mencionado. Ser\u00e1 inclu\u00eddo na Carteira de Identidade, mediante solicita\u00e7\u00e3o: I \u2013 o n\u00famero do DNI;&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/202294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/969"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=202294"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/202294\/revisions"}],"predecessor-version":[{"id":231389,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/202294\/revisions\/231389"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=202294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=202294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=202294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}