{"id":154792,"date":"2017-06-27T21:15:54","date_gmt":"2017-06-28T00:15:54","guid":{"rendered":"http:\/\/identificacao.policiacivil.go.gov.br\/?p=924"},"modified":"2017-06-27T21:15:54","modified_gmt":"2017-06-28T00:15:54","slug":"instituto-promove-acao-social-na-regiao-noroeste-de-goiania","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/instituto-promove-acao-social-na-regiao-noroeste-de-goiania\/","title":{"rendered":"Instituto promove a\u00e7\u00e3o social na regi\u00e3o noroeste de Goi\u00e2nia"},"content":{"rendered":"<p>No \u00faltimo final de semana , o Instituto de Identifica\u00e7\u00e3o realizou uma a\u00e7\u00e3o social no Bairro Vit\u00f3ria, regi\u00e3o Noroeste de Goi\u00e2nia. O evento foi realizado em parceria com a rede Record e aconteceu no Col\u00e9gio Estadual Ismael Silva de Jesus.<\/p>\n<p>A a\u00e7\u00e3o de cunho social da Pol\u00edcia Civil visa levar acessibilidade a toda popula\u00e7\u00e3o para que ela possa requerer o RG, um documento t\u00e3o importante na vida civil do cidad\u00e3o. O programa j\u00e1 est\u00e1 trabalhando com o novo sistema de biometria &#8211; o Goi\u00e1s Biom\u00e9trico &#8211; no qual todos os dados ser\u00e3o informatizados, desde a foto at\u00e9 a assinatura.<\/p>\n<p>A equipe do Instituto conseguiu protocolar mais de 50 processos de identidades gratuitamente na a\u00e7\u00e3o. O novo sistema trar\u00e1 mais agilidade na emiss\u00e3o do documento que ser\u00e1 entregue no Vapt Vupt mais pr\u00f3ximo da regi\u00e3o, nesse caso o Vap Vupt Mangal\u00f4.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Bruna Ramos<\/strong><\/p>\n<p><strong>Departamento de Comunica\u00e7\u00e3o do Instituto de Identifica\u00e7\u00e3o<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Regi\u00e3o Noroeste recebe a\u00e7\u00e3o social do Instituto de Identifica\u00e7\u00e3o em parceria com a rede Record<\/p>\n","protected":false},"author":82,"featured_media":935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[106,11648],"tags":[9172,4915],"class_list":["post-154792","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-galeria-de-fotos","category-goias-biometrico","tag-acao-social","tag-goias-biometrico","post_format-post-format-gallery"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54.jpg",500,335,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54.jpg",500,335,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54.jpg",500,335,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54-300x201.jpg",300,201,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54.jpg",500,335,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54.jpg",500,335,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/C\u00e2mara-Municipal-realiza-sess\u00e3o-solene-54.jpg",500,335,false]},"rttpg_author":{"display_name":"andredutton","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/andre-duttonfornecedores-goias-gov-br\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/galeria-de-fotos\/\" rel=\"category tag\">Galeria de fotos<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/goias-biometrico\/\" rel=\"category tag\">Goi\u00e1s Biom\u00e9trico<\/a>","rttpg_excerpt":"Regi\u00e3o Noroeste recebe a\u00e7\u00e3o social do Instituto de Identifica\u00e7\u00e3o em parceria com a rede Record","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/154792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=154792"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/154792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/935"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=154792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=154792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=154792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}