{"id":154791,"date":"2017-06-26T18:51:25","date_gmt":"2017-06-26T21:51:25","guid":{"rendered":"http:\/\/identificacao.policiacivil.go.gov.br\/?p=907"},"modified":"2026-06-02T22:25:09","modified_gmt":"2026-06-03T01:25:09","slug":"papiloscopistas-detectam-uso-de-rg-falso-na-central-de-flagrantes","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/papiloscopistas-detectam-uso-de-rg-falso-na-central-de-flagrantes\/","title":{"rendered":"Papiloscopistas detectam uso de RG falso na Central de Flagrantes"},"content":{"rendered":"<p data-raofz=\"13\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-908\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/06\/hugo-2-307x300.png\" alt=\"hugo\" width=\"307\" height=\"300\">Papiloscopistas policiais flagraram um suspeito portando carteira de identidade falsa na sexta-feira (23). Ele foi conduzido \u00e0 Central de Flagrantes com carteira de identidade em nome de Hugo Batista Rezende e carteira de trabalho em nome de David Soares de Souza (foto), ambos com foto da mesma pessoa e impress\u00f5es digitais divergentes.<\/p>\n<div id=\"attachment_53799\" class=\"wp-caption alignright\" style=\"width: 139px\" data-raofz=\"13\">\n<p><a class=\"zoomLink cboxElement\" href=\"http:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/2017\/06\/rg-falsa.png\" data-raofz=\"13\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-53799 colorbox-manual\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/06\/rg-falsa-110x200.png\" alt=\"rg falsa\" width=\"129\" height=\"235\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/06\/rg-falsa-110x200.png 110w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/06\/rg-falsa-165x300.png 165w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2017\/06\/rg-falsa.png 408w\" sizes=\"auto, (max-width: 129px) 100vw, 129px\"><\/a><\/p>\n<p class=\"wp-caption-text\" data-raofz=\"13\">Identidade falsa<\/p>\n<\/div>\n<p data-raofz=\"13\">Os Papiloscopistas Policiais Alexandre F\u00e9lix e Fl\u00e1via Felter logo verificaram que a impress\u00e3o digital da carteira de identidade apresentada n\u00e3o pertencia ao suspeito. Al\u00e9m disso, a data de expedi\u00e7\u00e3o e o n\u00famero sequencial do documento estavam diferentes daqueles que constavam na base de dados. Portanto, o documento era falso.<\/p>\n<p data-raofz=\"13\">As impress\u00f5es digitais do suspeito foram coletadas e consultadas no sistema Goi\u00e1s Biom\u00e9trico, o qual identificou como nome verdadeiro David Soares de Souza. Ap\u00f3s ser questionado, o suspeito confessou aos papiloscopistas que havia encomendado o documento a um terceiro pela internet. Al\u00e9m disso, foi detectado pelos policiais que o suspeito possu\u00eda uma ficha extensa de crimes cometidos e ainda dois mandados de pris\u00e3o em seu desfavor.<\/p>\n<p data-raofz=\"13\">Fonte: Site da Policia Civil GO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papiloscopistas detectam identidade falsa na Central de Flagrantes<\/p>\n","protected":false},"author":969,"featured_media":231202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11644,11640],"tags":[5130,3757,9],"class_list":["post-154791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia-civil","category-superintendencia-de-identificacao-humana","tag-identidade-falsa","tag-papiloscopista","tag-policia-civil"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170.jpg",300,450,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170.jpg",300,450,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170.jpg",300,450,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170-200x300.jpg",200,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170.jpg",300,450,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170.jpg",300,450,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2011\/11\/Adpego-presta-homenagem-\u00e0s-m\u00e3es-170.jpg",300,450,false]},"rttpg_author":{"display_name":"","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/policia-civil\/\" rel=\"category tag\">Pol\u00edcia Civil<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/superintendencia-de-identificacao-humana\/\" rel=\"category tag\">Superintend\u00eancia de Identifica\u00e7\u00e3o Humana<\/a>","rttpg_excerpt":"Papiloscopistas detectam identidade falsa na Central de Flagrantes","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/154791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/969"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=154791"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/154791\/revisions"}],"predecessor-version":[{"id":231205,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/154791\/revisions\/231205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/231202"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=154791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=154791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=154791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}