{"id":151388,"date":"2025-09-25T10:52:37","date_gmt":"2025-09-25T13:52:37","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=151388"},"modified":"2025-09-25T10:52:37","modified_gmt":"2025-09-25T13:52:37","slug":"pcgo-prende-tres-integrantes-de-associacao-para-o-trafico-de-drogas-em-quirinopolis","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/pcgo-prende-tres-integrantes-de-associacao-para-o-trafico-de-drogas-em-quirinopolis\/","title":{"rendered":"PCGO prende tr\u00eas integrantes de associa\u00e7\u00e3o para o tr\u00e1fico de drogas em Quirin\u00f3polis"},"content":{"rendered":"<p style=\"text-align: justify;\">Na data de hoje (23), a Pol\u00edcia Civil, por meio do Grupo Especial de Investiga\u00e7\u00e3o Criminal (Geic) de Quirin\u00f3polis &#8211; 8\u00aa DRP, realizou a pris\u00e3o em flagrante de tr\u00eas indiv\u00edduos pelos crimes de tr\u00e1fico de drogas, associa\u00e7\u00e3o para o tr\u00e1fico e posse de muni\u00e7\u00f5es.\u00a0A pris\u00e3o ocorreu em Quirin\u00f3polis, ap\u00f3s a equipe tomar conhecimento de irregularidades, em um im\u00f3vel, e da suspeita de que o local estaria sendo utilizado para a pr\u00e1tica de tr\u00e1fico de entorpecentes.<\/p>\n<p style=\"text-align: justify;\">Durante as buscas, foram localizadas por\u00e7\u00f5es de maconha j\u00e1 embaladas, por\u00e7\u00e3o grande de maconha ainda n\u00e3o fragmentada destinada \u00e0 venda, uma balan\u00e7a de precis\u00e3o, uma m\u00e1quina de cart\u00e3o, diversos sacos tipo ziplock utilizados para acondicionamento da droga, 22 muni\u00e7\u00f5es calibre .38 e outros objetos que indicam trafic\u00e2ncia.<\/p>\n<p style=\"text-align: justify;\"><b>PCGO: investigar para proteger \ud83d\ude94<\/b><\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-151388 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-54.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-54-300x300.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\".jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55-300x300.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\".jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Na data de hoje (23), a Pol\u00edcia Civil, por meio do Grupo Especial de Investiga\u00e7\u00e3o Criminal (Geic) de Quirin\u00f3polis &#8211; 8\u00aa DRP, realizou a pris\u00e3o em flagrante de tr\u00eas indiv\u00edduos pelos crimes de tr\u00e1fico de drogas, associa\u00e7\u00e3o para o tr\u00e1fico e posse de muni\u00e7\u00f5es.\u00a0A pris\u00e3o ocorreu em Quirin\u00f3polis, ap\u00f3s a equipe tomar conhecimento de irregularidades, [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":151390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3195,2538,89,537],"tags":[277],"class_list":["post-151388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-8a-regional","category-delegacias","category-regionais","category-ultimo-segundo","tag-quirinopolis"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55.jpeg",900,1200,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55.jpeg",900,1200,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55.jpeg",900,1200,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55-375x500.jpeg",225,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55-801x1068.jpeg",768,1024,true],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55.jpeg",900,1200,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/09\/unnamed-file-55.jpeg",900,1200,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/8a-regional\/\" rel=\"category tag\">8\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"Na data de hoje (23), a Pol\u00edcia Civil, por meio do Grupo Especial de Investiga\u00e7\u00e3o Criminal (Geic) de Quirin\u00f3polis &#8211; 8\u00aa DRP, realizou a pris\u00e3o em flagrante de tr\u00eas indiv\u00edduos pelos crimes de tr\u00e1fico de drogas, associa\u00e7\u00e3o para o tr\u00e1fico e posse de muni\u00e7\u00f5es.\u00a0A pris\u00e3o ocorreu em Quirin\u00f3polis, ap\u00f3s a equipe tomar conhecimento de irregularidades,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/151388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=151388"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/151388\/revisions"}],"predecessor-version":[{"id":151391,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/151388\/revisions\/151391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/151390"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=151388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=151388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=151388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}