{"id":139822,"date":"2025-01-19T15:46:34","date_gmt":"2025-01-19T18:46:34","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=139822"},"modified":"2025-01-19T15:46:34","modified_gmt":"2025-01-19T18:46:34","slug":"mulher-e-presa-apos-abandonar-cao-animal-foi-resgatado-por-testemunha-na-rua","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/mulher-e-presa-apos-abandonar-cao-animal-foi-resgatado-por-testemunha-na-rua\/","title":{"rendered":"Mulher \u00e9 presa ap\u00f3s abandonar c\u00e3o; animal foi resgatado por testemunha na rua"},"content":{"rendered":"<p style=\"text-align: justify;\">A Pol\u00edcia Civil, por meio do Grupo de Prote\u00e7\u00e3o Animal (GPA) da 1\u00aa DRP\/Goi\u00e2nia, atuou em uma ocorr\u00eancia de maus-tratos ap\u00f3s receber uma den\u00fancia. A equipe policial dirigiu-se \u00e0 UPAVET, onde um cachorro estava sendo atendido. O animal havia sido resgatado por uma testemunha que o encontrou ca\u00eddo na rua em estado cr\u00edtico.<\/p>\n<p style=\"text-align: justify;\">O c\u00e3o apresentava uma infesta\u00e7\u00e3o severa de carrapatos, fraturas na pata e no cr\u00e2nio, al\u00e9m de estar ap\u00e1tico e incapaz de se levantar. De posse das informa\u00e7\u00f5es colhidas, os policiais localizaram a tutora do animal no setor Parque Tremend\u00e3o, em Goi\u00e2nia.\u00a0Durante as investiga\u00e7\u00f5es, ficou comprovado que o animal j\u00e1 sofria de graves problemas de sa\u00fade, mas foi privado de qualquer tipo de assist\u00eancia, configurando o crime de maus-tratos.\u00a0A respons\u00e1vel, uma mulher de 51 anos de idade, foi presa em flagrante, com a qualifica\u00e7\u00e3o agravada por envolver um c\u00e3o como v\u00edtima.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-139822 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.40.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.40-300x300.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Mulher \u00e9 presa ap\u00f3s abandonar c\u00e3o; animal foi resgatado por testemunha na rua\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39-300x300.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Mulher \u00e9 presa ap\u00f3s abandonar c\u00e3o; animal foi resgatado por testemunha na rua\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.38.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.38-300x300.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Mulher \u00e9 presa ap\u00f3s abandonar c\u00e3o; animal foi resgatado por testemunha na rua\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil, por meio do Grupo de Prote\u00e7\u00e3o Animal (GPA) da 1\u00aa DRP\/Goi\u00e2nia, atuou em uma ocorr\u00eancia de maus-tratos ap\u00f3s receber uma den\u00fancia. A equipe policial dirigiu-se \u00e0 UPAVET, onde um cachorro estava sendo atendido. O animal havia sido resgatado por uma testemunha que o encontrou ca\u00eddo na rua em estado cr\u00edtico. O c\u00e3o [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":139824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3188,2538,89,537],"tags":[5978],"class_list":["post-139822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1a-regional","category-delegacias","category-regionais","category-ultimo-segundo","tag-cao"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg",675,1200,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg",675,1200,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg",675,1200,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg",169,300,false],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg",576,1024,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg",675,1200,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2025\/01\/whatsapp-image-2025-01-18-at-19.57.39.jpeg",675,1200,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/1a-regional\/\" rel=\"category tag\">1\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"A Pol\u00edcia Civil, por meio do Grupo de Prote\u00e7\u00e3o Animal (GPA) da 1\u00aa DRP\/Goi\u00e2nia, atuou em uma ocorr\u00eancia de maus-tratos ap\u00f3s receber uma den\u00fancia. A equipe policial dirigiu-se \u00e0 UPAVET, onde um cachorro estava sendo atendido. O animal havia sido resgatado por uma testemunha que o encontrou ca\u00eddo na rua em estado cr\u00edtico. O c\u00e3o&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/139822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=139822"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/139822\/revisions"}],"predecessor-version":[{"id":139827,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/139822\/revisions\/139827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/139824"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=139822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=139822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=139822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}