{"id":131046,"date":"2024-05-24T13:17:37","date_gmt":"2024-05-24T16:17:37","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=131046"},"modified":"2024-05-24T13:17:37","modified_gmt":"2024-05-24T16:17:37","slug":"pcgo-prende-suspeito-de-trafico-de-drogas-em-flagrante-em-uruacu","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/pcgo-prende-suspeito-de-trafico-de-drogas-em-flagrante-em-uruacu\/","title":{"rendered":"PCGO prende suspeito de tr\u00e1fico de drogas em flagrante, em Urua\u00e7u"},"content":{"rendered":"<p style=\"text-align: justify;\">A Pol\u00edcia Civil, por meio da Delegacia de Pol\u00edcia de Urua\u00e7u, prendeu em flagrante ontem (23) um homem de 31 anos de idade, no momento em que acabara de vender uma por\u00e7\u00e3o de coca\u00edna a um usu\u00e1rio de drogas, fato ocorrido no Setor Oeste, conhecido como &#8220;Solta Gato&#8221;, em Urua\u00e7u. Durante os procedimentos do flagrante, com apoio do grupo de opera\u00e7\u00f5es com c\u00e3es da PRF e do Genarc de Urua\u00e7u, foram apreendidos cerca de 300g de pasta base de coca\u00edna, duas por\u00e7\u00f5es de crack e materiais usados para preparar a droga.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil, por meio da Delegacia de Pol\u00edcia de Urua\u00e7u, prendeu em flagrante ontem (23) um homem de 31 anos de idade, no momento em que acabara de vender uma por\u00e7\u00e3o de coca\u00edna a um usu\u00e1rio de drogas, fato ocorrido no Setor Oeste, conhecido como &#8220;Solta Gato&#8221;, em Urua\u00e7u. Durante os procedimentos do flagrante, [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":81077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6760,2538,89,537],"tags":[5509],"class_list":["post-131046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-18a-regional","category-delegacias","category-regionais","category-ultimo-segundo","tag-trafico-de-drogas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",208,233,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",208,233,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",208,233,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",134,150,false],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",208,233,false],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",208,233,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",208,233,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/06\/logo-pc.png",208,233,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/18a-regional\/\" rel=\"category tag\">18\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"A Pol\u00edcia Civil, por meio da Delegacia de Pol\u00edcia de Urua\u00e7u, prendeu em flagrante ontem (23) um homem de 31 anos de idade, no momento em que acabara de vender uma por\u00e7\u00e3o de coca\u00edna a um usu\u00e1rio de drogas, fato ocorrido no Setor Oeste, conhecido como &#8220;Solta Gato&#8221;, em Urua\u00e7u. Durante os procedimentos do flagrante,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/131046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=131046"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/131046\/revisions"}],"predecessor-version":[{"id":131047,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/131046\/revisions\/131047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/81077"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=131046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=131046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=131046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}