{"id":130392,"date":"2024-05-09T11:07:33","date_gmt":"2024-05-09T14:07:33","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=130392"},"modified":"2024-05-09T11:07:33","modified_gmt":"2024-05-09T14:07:33","slug":"operacao-evali-apreende-mais-de-10-mil-cigarros-eletronicos-e-prende-libaneses-por-venda-ilegal","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/operacao-evali-apreende-mais-de-10-mil-cigarros-eletronicos-e-prende-libaneses-por-venda-ilegal\/","title":{"rendered":"Opera\u00e7\u00e3o Evali apreende mais de 10 mil cigarros eletr\u00f4nicos e prende libaneses por venda ilegal"},"content":{"rendered":"<p style=\"text-align: justify;\">Na \u00faltima segunda-feira (06), policiais civis da Central-Geral de Flagrantes (CGF) da 1\u00aa DRP de Goi\u00e2nia prenderam em flagrante mais dois libaneses que chefiavam o com\u00e9rcio de cigarros eletr\u00f4nicos (\u201cvapes\u201d) em todo Estado de Goi\u00e1s. Ap\u00f3s uma investiga\u00e7\u00e3o, policiais civis deflagraram a 2\u00aa fase da opera\u00e7\u00e3o Evali (Les\u00e3o Pulmonar Associada ao Uso de Cigarro Eletr\u00f4nico) em tr\u00eas lojas no Camel\u00f3dromo de Campinas, em Goi\u00e2nia, onde foram apreendidos mais de 10 mil cigarros eletr\u00f4nicos avaliados em mais de R$ 1 milh\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Os propriet\u00e1rios das lojas, que s\u00e3o libaneses, s\u00e3o os principais respons\u00e1veis pelo fornecimento dos dispositivos eletr\u00f4nicos em todo estado de Goi\u00e1s, principalmente para tabacarias em Goi\u00e2nia e no interior, as quais j\u00e1 est\u00e3o sendo identificadas. No local ainda foram apreendidos diversos documentos, in\u00fameras m\u00e1quinas de cart\u00f5es de cr\u00e9dito e dinheiro oriundo da venda dos produtos.\u00a0Ambos foram autuados em flagrante pela pr\u00e1tica dos crimes previstos no artigo 7\u00ba, inciso IX, da Lei n\u00ba 8.137\/90, nos artigos 273, par\u00e1grafo 1\u00ba B, inciso I e 278 do C\u00f3digo Penal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima segunda-feira (06), policiais civis da Central-Geral de Flagrantes (CGF) da 1\u00aa DRP de Goi\u00e2nia prenderam em flagrante mais dois libaneses que chefiavam o com\u00e9rcio de cigarros eletr\u00f4nicos (\u201cvapes\u201d) em todo Estado de Goi\u00e1s. Ap\u00f3s uma investiga\u00e7\u00e3o, policiais civis deflagraram a 2\u00aa fase da opera\u00e7\u00e3o Evali (Les\u00e3o Pulmonar Associada ao Uso de Cigarro Eletr\u00f4nico) [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":130390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3188,2538,89,537],"tags":[1335,10850],"class_list":["post-130392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1a-regional","category-delegacias","category-regionais","category-ultimo-segundo","tag-goiania","tag-operacao-evali"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50.jpeg",675,1200,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50.jpeg",675,1200,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50.jpeg",675,1200,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50.jpeg",169,300,false],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50.jpeg",576,1024,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50.jpeg",675,1200,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2024\/05\/whatsapp-image-2024-05-09-at-10.55.50.jpeg",675,1200,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/1a-regional\/\" rel=\"category tag\">1\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"Na \u00faltima segunda-feira (06), policiais civis da Central-Geral de Flagrantes (CGF) da 1\u00aa DRP de Goi\u00e2nia prenderam em flagrante mais dois libaneses que chefiavam o com\u00e9rcio de cigarros eletr\u00f4nicos (\u201cvapes\u201d) em todo Estado de Goi\u00e1s. Ap\u00f3s uma investiga\u00e7\u00e3o, policiais civis deflagraram a 2\u00aa fase da opera\u00e7\u00e3o Evali (Les\u00e3o Pulmonar Associada ao Uso de Cigarro Eletr\u00f4nico)&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/130392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=130392"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/130392\/revisions"}],"predecessor-version":[{"id":130398,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/130392\/revisions\/130398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/130390"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=130392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=130392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=130392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}