{"id":116602,"date":"2023-05-31T11:03:36","date_gmt":"2023-05-31T14:03:36","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=116602"},"modified":"2023-05-31T11:03:36","modified_gmt":"2023-05-31T14:03:36","slug":"pc-prende-pai-investigado-por-estuprar-filha-de-10-anos-em-doverlandia","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/pc-prende-pai-investigado-por-estuprar-filha-de-10-anos-em-doverlandia\/","title":{"rendered":"PC prende pai investigado por estuprar filha de 10 anos, em Doverl\u00e2ndia"},"content":{"rendered":"<p style=\"text-align: justify;\">A Delegacia de Caiap\u00f4nia recebeu a not\u00edcia de que um pai de uma crian\u00e7a de apenas 10 anos de idade, na cidade de Doverl\u00e2ndia, estava praticando atos libidinosos contra ela. A crian\u00e7a foi submetida a acompanhamento e escuta especializada na qual deu detalhes, narrando que era costumeiro seu pai passar as m\u00e3os em seu corpo, desejando-o, principalmente em seus seios e genit\u00e1lia, quando ela estava sozinha. A crian\u00e7a afirmou que chegou a ser aconselhada por um l\u00edder religioso a esquecer o fato e n\u00e3o denunciar o caso, pois seu pai precisava era de Deus, e que Deus ia o perdoar e o transformar em um homem bom novamente.<\/p>\n<p style=\"text-align: justify;\">Visando garantir a seguran\u00e7a e integridade f\u00edsica da crian\u00e7a, foi representado pela pris\u00e3o preventiva do investigado, deferida pelo Poder Judici\u00e1rio e cumprida hoje (31\/5). Esta \u00e9 a terceira pris\u00e3o, em menos de 10 dias, da Delegacia de Caiap\u00f4nia contra investigados por estupro de crian\u00e7as.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Delegacia de Caiap\u00f4nia recebeu a not\u00edcia de que um pai de uma crian\u00e7a de apenas 10 anos de idade, na cidade de Doverl\u00e2ndia, estava praticando atos libidinosos contra ela. A crian\u00e7a foi submetida a acompanhamento e escuta especializada na qual deu detalhes, narrando que era costumeiro seu pai passar as m\u00e3os em seu corpo, [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":116603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3194,2538,89,537],"tags":[1267,10385],"class_list":["post-116602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7a-regional","category-delegacias","category-regionais","category-ultimo-segundo","tag-doverlandia","tag-estupro-crianca"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia.jpeg",768,1024,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia.jpeg",768,1024,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia.jpeg",768,1024,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia-375x500.jpeg",225,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia.jpeg",768,1024,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia.jpeg",768,1024,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/05\/caiaponia.jpeg",768,1024,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/7a-regional\/\" rel=\"category tag\">7\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"A Delegacia de Caiap\u00f4nia recebeu a not\u00edcia de que um pai de uma crian\u00e7a de apenas 10 anos de idade, na cidade de Doverl\u00e2ndia, estava praticando atos libidinosos contra ela. A crian\u00e7a foi submetida a acompanhamento e escuta especializada na qual deu detalhes, narrando que era costumeiro seu pai passar as m\u00e3os em seu corpo,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/116602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=116602"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/116602\/revisions"}],"predecessor-version":[{"id":116604,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/116602\/revisions\/116604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/116603"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=116602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=116602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=116602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}