{"id":114486,"date":"2023-04-17T15:30:41","date_gmt":"2023-04-17T18:30:41","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=114486"},"modified":"2023-04-17T15:30:41","modified_gmt":"2023-04-17T18:30:41","slug":"foragido-e-preso-por-roubo-em-petrolina","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/foragido-e-preso-por-roubo-em-petrolina\/","title":{"rendered":"Foragido \u00e9 preso por roubo em Petrolina"},"content":{"rendered":"<p style=\"text-align: justify;\">Nesse domingo, 16\/4, a Delegacia de Pol\u00edcia de Petrolina, junto com a Pol\u00edcia Militar (CPE Goian\u00e9sia), cumpriu pris\u00e3o preventiva de roubo majorado pelo concurso de duas pessoas em desfavor de um suspeito de ter cometido crime na zona rural de Petrolina. O crime ocorreu em junho de 2022. Ap\u00f3s a conclus\u00e3o das investiga\u00e7\u00f5es, restou comprovada a materialidade e autoria do delito como sendo que dois indiv\u00edduos invadiram a propriedade rural, fizeram a v\u00edtima de ref\u00e9m e roubaram o autom\u00f3vel, aparelho celular e outros objetos da resid\u00eancia. Diante disso, considerando a gravidade da conduta dos investigados e sua alta periculosidade, destacando que ambos possuem passagens por crimes previstos na Lei de Drogas e furto qualificado, ou seja, denunciados por diversos crimes, a autoridade policial representou pela pris\u00e3o preventiva dos indiv\u00edduos.<\/p>\n<p style=\"text-align: justify;\">No dia 11 de novembro de 2022, o juiz decretou a pris\u00e3o preventiva dos autores, sendo que, logo depois da publica\u00e7\u00e3o, foi cumprida a pris\u00e3o de um dos autores, pois esse j\u00e1 estava segregado em virtude de ordem prisional oriunda de outros processos. E o outro suspeito, apesar de possuir v\u00e1rias anota\u00e7\u00f5es criminais, n\u00e3o foi encontrado e desde ent\u00e3o era considerado foragido da justi\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesse domingo, 16\/4, a Delegacia de Pol\u00edcia de Petrolina, junto com a Pol\u00edcia Militar (CPE Goian\u00e9sia), cumpriu pris\u00e3o preventiva de roubo majorado pelo concurso de duas pessoas em desfavor de um suspeito de ter cometido crime na zona rural de Petrolina. O crime ocorreu em junho de 2022. Ap\u00f3s a conclus\u00e3o das investiga\u00e7\u00f5es, restou comprovada [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":72352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3202,2538,89,537],"tags":[3688,524],"class_list":["post-114486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-15a-regional","category-delegacias","category-regionais","category-ultimo-segundo","tag-petrolina","tag-roubo"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo-300x300.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",300,211,false],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/15a-regional\/\" rel=\"category tag\">15\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/regionais\/\" rel=\"category tag\">Regionais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"Nesse domingo, 16\/4, a Delegacia de Pol\u00edcia de Petrolina, junto com a Pol\u00edcia Militar (CPE Goian\u00e9sia), cumpriu pris\u00e3o preventiva de roubo majorado pelo concurso de duas pessoas em desfavor de um suspeito de ter cometido crime na zona rural de Petrolina. O crime ocorreu em junho de 2022. Ap\u00f3s a conclus\u00e3o das investiga\u00e7\u00f5es, restou comprovada&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/114486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=114486"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/114486\/revisions"}],"predecessor-version":[{"id":114487,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/114486\/revisions\/114487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/72352"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=114486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=114486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=114486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}