

{"id":113006,"date":"2023-03-14T10:29:25","date_gmt":"2023-03-14T13:29:25","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=113006"},"modified":"2023-03-14T10:29:38","modified_gmt":"2023-03-14T13:29:38","slug":"combate-a-corrupcao-operacao-custo-maximo-cumpre-37-mandados-em-go-rs-e-df","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/combate-a-corrupcao-operacao-custo-maximo-cumpre-37-mandados-em-go-rs-e-df\/","title":{"rendered":"Combate \u00e0 Corrup\u00e7\u00e3o: Opera\u00e7\u00e3o Custo M\u00e1ximo cumpre 37 mandados em GO, RS e DF"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-113037 alignleft\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo-375x500.jpeg\" alt=\"\" width=\"236\" height=\"315\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo-375x500.jpeg 375w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo-768x1024.jpeg 768w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo-696x928.jpeg 696w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo-315x420.jpeg 315w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo-630x840.jpeg 630w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo.jpeg 801w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/>A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia Estadual de Combate \u00e0 Corrup\u00e7\u00e3o (Deccor), realizou, na manh\u00e3 desta ter\u00e7a-feira (14), a Opera\u00e7\u00e3o Custo M\u00e1ximo, com o objetivo de cumprir 37 mandados judiciais em Goi\u00e1s, Rio Grande do Sul e Distrito Federal. Ao todo, s\u00e3o 21 mandados de busca e apreens\u00e3o, cinco mandados de afastamento da fun\u00e7\u00e3o p\u00fablica, seis mandados de proibi\u00e7\u00e3o de frequ\u00eancia a determinados lugares e\u00a0 quatro mandados de proibi\u00e7\u00e3o de contratar com o poder p\u00fablico. Al\u00e9m disso, um dos mandados prev\u00ea o bloqueio de valores na ordem de R$ 6,4 milh\u00f5es.<\/p>\n<p style=\"text-align: justify;\">A opera\u00e7\u00e3o \u00e9 relacionada a investiga\u00e7\u00e3o policial iniciada no ano de 2021, para apurar prov\u00e1veis crimes ocorridos durante o processo licitat\u00f3rio e a execu\u00e7\u00e3o do contrato formalizado entre uma empresa p\u00fablica e uma empresa de gerenciamento log\u00edstico sediada no Rio Grande do Sul. H\u00e1 evid\u00eancias de que a empresa contratada se utilizou de outras \u201cempresas fantasmas\u201d localizadas em Goi\u00e2nia\/GO e em Campo Bom\/RS para fornecer produtos \u00e0 contratante.<\/p>\n<p style=\"text-align: justify;\">S\u00e3o investigados crimes de fraude e direcionamento de procedimento licitat\u00f3rio e associa\u00e7\u00e3o criminosa.\u00a0Al\u00e9m da Pol\u00edcia Civil do Estado de Goi\u00e1s, houve tamb\u00e9m a participa\u00e7\u00e3o e apoio operacional da Pol\u00edcia Civil do Rio Grande do Sul, atrav\u00e9s da DCCOR\/DEIC, e da Pol\u00edcia Civil do Distrito Federal, atrav\u00e9s da DRCOR\/DECOR.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia Estadual de Combate \u00e0 Corrup\u00e7\u00e3o (Deccor), realizou, na manh\u00e3 desta ter\u00e7a-feira (14), a Opera\u00e7\u00e3o Custo M\u00e1ximo, com o objetivo de cumprir 37 mandados judiciais em Goi\u00e1s, Rio Grande do Sul e Distrito Federal. Ao todo, s\u00e3o 21 mandados de busca e apreens\u00e3o, cinco mandados de afastamento [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":113038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,6069],"tags":[10213,8021],"class_list":["post-113006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-especializadas","category-noticias-da-policia-civil","tag-custo-maximo","tag-deccor"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2.jpeg",1068,519,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2.jpeg",1068,519,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2.jpeg",1068,519,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2-500x243.jpeg",300,146,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2.jpeg",1024,498,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2.jpeg",1068,519,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/03\/custo-maximo2.jpeg",1068,519,false]},"rttpg_author":{"display_name":"claudiacury","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/claudiacury\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/especializadas\/\" rel=\"category tag\">Especializadas<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/noticias\/noticias-da-policia-civil\/\" rel=\"category tag\">Not\u00edcias da Pol\u00edcia Civil<\/a>","rttpg_excerpt":"A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia Estadual de Combate \u00e0 Corrup\u00e7\u00e3o (Deccor), realizou, na manh\u00e3 desta ter\u00e7a-feira (14), a Opera\u00e7\u00e3o Custo M\u00e1ximo, com o objetivo de cumprir 37 mandados judiciais em Goi\u00e1s, Rio Grande do Sul e Distrito Federal. Ao todo, s\u00e3o 21 mandados de busca e apreens\u00e3o, cinco mandados de afastamento&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/113006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=113006"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/113006\/revisions"}],"predecessor-version":[{"id":113039,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/113006\/revisions\/113039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/113038"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=113006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=113006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=113006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}