{"id":110127,"date":"2023-01-03T15:08:11","date_gmt":"2023-01-03T18:08:11","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=110127"},"modified":"2023-01-03T16:18:45","modified_gmt":"2023-01-03T19:18:45","slug":"9a-drp-recebe-nova-viatura-para-combate-ao-crime-na-regiao","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/9a-drp-recebe-nova-viatura-para-combate-ao-crime-na-regiao\/","title":{"rendered":"19\u00aa DRP recebe nova viatura para combate ao crime na regi\u00e3o"},"content":{"rendered":"<p>Na tarde desta ter\u00e7a-feira (03), a diretoria da Pol\u00edcia Civil de Goi\u00e1s, por meio do delegado-geral Alexandre Louren\u00e7o, da superintendente de Pol\u00edcia Judici\u00e1ria Ana Claudia Stoffel e pelo delegado-geral adjunto Reinaldo Koshiyama, entregou ao delegado da 9\u00aa DRP,\u00a0 Gustavo Carlos Ferreira, uma nova viatura zero km.<\/p>\n<p>O ve\u00edculo atende a demanda da regional de Caldas Novas para resolu\u00e7\u00e3o de crimes com ainda mais agilidade.<\/p>\n<div id='gallery-1' class='gallery galleryid-110127 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/goias.gov.br\/policiacivil\/9a-drp-recebe-nova-viatura-para-combate-ao-crime-na-regiao\/whatsapp-image-2023-01-03-at-12-02-29-1\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1-300x300.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/goias.gov.br\/policiacivil\/9a-drp-recebe-nova-viatura-para-combate-ao-crime-na-regiao\/whatsapp-image-2023-01-03-at-12-02-29\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-300x300.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Na tarde desta ter\u00e7a-feira (03), a diretoria da Pol\u00edcia Civil de Goi\u00e1s, por meio do delegado-geral Alexandre Louren\u00e7o, da superintendente de Pol\u00edcia Judici\u00e1ria Ana Claudia Stoffel e pelo delegado-geral adjunto Reinaldo Koshiyama, entregou ao delegado da 9\u00aa DRP,\u00a0 Gustavo Carlos Ferreira, uma nova viatura zero km. O ve\u00edculo atende a demanda da regional de Caldas [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":110128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3196,537],"tags":[9709,1100,3971],"class_list":["post-110127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-9a-regional","category-ultimo-segundo","tag-9-drp","tag-caldas-novas","tag-viatura"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1.jpeg",1068,601,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1.jpeg",1068,601,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1.jpeg",1068,601,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1-500x281.jpeg",300,169,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1.jpeg",1024,576,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1.jpeg",1068,601,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2023\/01\/whatsapp-image-2023-01-03-at-12.02.29-1.jpeg",1068,601,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/9a-regional\/\" rel=\"category tag\">9\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"Na tarde desta ter\u00e7a-feira (03), a diretoria da Pol\u00edcia Civil de Goi\u00e1s, por meio do delegado-geral Alexandre Louren\u00e7o, da superintendente de Pol\u00edcia Judici\u00e1ria Ana Claudia Stoffel e pelo delegado-geral adjunto Reinaldo Koshiyama, entregou ao delegado da 9\u00aa DRP,\u00a0 Gustavo Carlos Ferreira, uma nova viatura zero km. O ve\u00edculo atende a demanda da regional de Caldas&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/110127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=110127"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/110127\/revisions"}],"predecessor-version":[{"id":110131,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/110127\/revisions\/110131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/110128"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=110127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=110127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=110127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}