{"id":103355,"date":"2022-05-26T17:45:55","date_gmt":"2022-05-26T20:45:55","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=103355"},"modified":"2022-05-26T17:45:55","modified_gmt":"2022-05-26T20:45:55","slug":"mulher-e-presa-por-receptacao-apos-comprar-celular-roubado-em-petrolina","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/mulher-e-presa-por-receptacao-apos-comprar-celular-roubado-em-petrolina\/","title":{"rendered":"Mulher \u00e9 presa por recepta\u00e7\u00e3o ap\u00f3s comprar celular roubado, em Petrolina"},"content":{"rendered":"<p style=\"text-align: justify;\">A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia de Petrolina, prendeu em flagrante, nesta quarta-feira (25), uma mulher acusada de ter comprado um celular furtado.<\/p>\n<p style=\"text-align: justify;\">Uma v\u00edtima de um furto de celular compareceu \u00e0 delegacia, no \u00faltimo m\u00eas de mar\u00e7o, e registrou os fatos. A Pol\u00edcia Civil, em dilig\u00eancia desde ent\u00e3o, localizou o celular furtado na posse de uma mulher identificada como L.R.S., na cidade de Petrolina.<\/p>\n<p style=\"text-align: justify;\">Em interrogat\u00f3rio, L.R.S relatou que comprou o celular ciente de que ele estava muito abaixo do pre\u00e7o. Disse, ainda, que suspeitou que o celular poderia ser de origem criminosa. A autora acrescentou que comprou o aparelho celular de um indiv\u00edduo na cidade de Petrolina, identificado pela pol\u00edcia como G.G.A.N.<\/p>\n<p style=\"text-align: justify;\">Segundo a autora da recepta\u00e7\u00e3o, ela conhecia G.G.A.N j\u00e1 h\u00e1 algum tempo e tinha ci\u00eancia de que o mesmo era envolvido com atividades criminosas, inclusive com passagens por furto e tr\u00e1fico.<\/p>\n<p style=\"text-align: justify;\">Diante da situa\u00e7\u00e3o flagrancial, foi dada voz de pris\u00e3o para L.R.S e a mesma foi conduzida para a Central de Flagrante de Jaragu\u00e1 para as provid\u00eancias de praxe. Ela est\u00e1 \u00e0 disposi\u00e7\u00e3o do Judici\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia de Petrolina, prendeu em flagrante, nesta quarta-feira (25), uma mulher acusada de ter comprado um celular furtado. Uma v\u00edtima de um furto de celular compareceu \u00e0 delegacia, no \u00faltimo m\u00eas de mar\u00e7o, e registrou os fatos. A Pol\u00edcia Civil, em dilig\u00eancia desde ent\u00e3o, localizou o celular [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":72352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3202,537],"tags":[1473,3688,594],"class_list":["post-103355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-15a-regional","category-ultimo-segundo","tag-jaragua","tag-petrolina","tag-receptacao"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo-300x300.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",300,211,false],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/04\/logo-preta-pcgo.jpg",473,333,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/15a-regional\/\" rel=\"category tag\">15\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia de Petrolina, prendeu em flagrante, nesta quarta-feira (25), uma mulher acusada de ter comprado um celular furtado. Uma v\u00edtima de um furto de celular compareceu \u00e0 delegacia, no \u00faltimo m\u00eas de mar\u00e7o, e registrou os fatos. A Pol\u00edcia Civil, em dilig\u00eancia desde ent\u00e3o, localizou o celular&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/103355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=103355"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/103355\/revisions"}],"predecessor-version":[{"id":103356,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/103355\/revisions\/103356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/72352"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=103355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=103355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=103355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}