

{"id":851,"date":"2015-12-07T16:12:04","date_gmt":"2015-12-07T18:12:04","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/industriaecomercio\/mais-quatro-novas-empresas-chegam\/"},"modified":"2015-12-07T16:12:04","modified_gmt":"2015-12-07T18:12:04","slug":"mais-quatro-novas-empresas-chegam","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/industriaecomercio\/mais-quatro-novas-empresas-chegam\/","title":{"rendered":"Mais quatro novas empresas chegam a Goi\u00e1s"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-850\" src=\"https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg\" alt=\"\" width=\"800\" height=\"472\" srcset=\"https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg 800w, https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e-300x177.jpg 300w, https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e-768x453.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p style=\"text-align: left;\" align=\"center\"><em>Investimentos s&atilde;o da ordem de R$ 324 milh&otilde;es e devem gerar aproximadamente cinco mil novos empregos; Protocolos de Inten&ccedil;&otilde;es ser&atilde;o assinados nesta ter&ccedil;a-feira, &agrave;s 14 horas&nbsp;<\/em><\/p>\n<p style=\"text-align: left;\" align=\"center\">O governador Marconi Perillo e o vice-governador e secret&aacute;rio de Desenvolvimento Econ&ocirc;mico (SED), Jos&eacute; Eliton, assinam na tarde desta ter&ccedil;a-feira (08\/12) Protocolos de Inten&ccedil;&otilde;es que oficializar&atilde;o a vinda de quatro novas empresas para Goi&aacute;s. Juntas, os novos neg&oacute;cios v&atilde;o totalizar investimentos de R$ 324,7 milh&otilde;es que devem gerar 5.020 novas vagas de empregos no Estado.<\/p>\n<p style=\"text-align: left;\">A localiza&ccedil;&atilde;o, infraestrutura e uma log&iacute;stica privilegiada do Estado de Goi&aacute;s, aliados aos benef&iacute;cios disponibilizados pelo Programa de Desenvolvimento Industrial de Goi&aacute;s (Produzir), foram alguns dos atributos decisivos que influenciaram na decis&atilde;o das empresas em direcionar seus investimentos para Goi&aacute;s.&nbsp;&nbsp;<\/p>\n<p>O acordo para a instala&ccedil;&atilde;o dessas empresas em Goi&aacute;s contou tamb&eacute;m com o empenho do vice-governador e titular da SED, Jos&eacute; Eliton. Ele tem se destacado como mediador de v&aacute;rias negocia&ccedil;&otilde;es, apontando ainda a agilidade e estrat&eacute;gia assertiva da Assessoria de Atra&ccedil;&atilde;o de Investimentos da Superintend&ecirc;ncia Executiva de Ind&uacute;stria da SED como fundamental para que as articula&ccedil;&otilde;es fossem concretizadas de maneira satisfat&oacute;ria para as partes envolvidas.<\/p>\n<p><strong>Solis Solutions<\/strong><\/p>\n<p style=\"text-align: left;\"><strong><\/strong>A Solis Solutions vai montar, em Jata&iacute;, uma unidade industrial fotovoltaica para produ&ccedil;&atilde;o de pain&eacute;is solares e de solu&ccedil;&otilde;es t&eacute;cnicas para o setor de energias renov&aacute;veis no Estado de Goi&aacute;s. Os investimentos fixos ser&atilde;o de R$ 250 milh&otilde;es, com gera&ccedil;&atilde;o de 500 empregos diretos e 2.500 indiretos. Mas Jos&eacute; Eliton ressalta que o valor pode atingir R$ 1 bilh&atilde;o nos pr&oacute;ximos cinco anos.<\/p>\n<p style=\"text-align: left;\">A empresa ter&aacute; sua linha de montagem constru&iacute;da em &aacute;rea de 250 mil metros quadrados, e vai implantar em outra &aacute;rea de 200 mil&nbsp;metros quadrados um parque tecnol&oacute;gico solar que ser&aacute; transformado em &ldquo;exposi&ccedil;&atilde;o permanente&rdquo;, com o objetivo de mostrar as possibilidades de uso da tecnologia solar nas &aacute;reas urbanas e rurais.<\/p>\n<p style=\"text-align: left;\">Na unidade fabril, ser&atilde;o produzidas c&eacute;lulas fotovoltaicas, pain&eacute;is fotovoltaicos, inversores, transformadores, estruturas de suportes fixos, suportes m&oacute;veis, entre outros. De acordo com informa&ccedil;&otilde;es da SED, a empresa&nbsp;&nbsp;ter&aacute; um prazo de 40 meses para constru&ccedil;&atilde;o de suas instala&ccedil;&otilde;es e in&iacute;cio da produ&ccedil;&atilde;o industrial, por&eacute;m, a comercializa&ccedil;&atilde;o j&aacute; se inicia no in&iacute;cio de 2016, com a chegada de mercadorias importadas.<\/p>\n<p style=\"text-align: left;\"><strong>&Aacute;gua Mineral Bom Jesus<\/strong><\/p>\n<p style=\"text-align: left;\"><strong><\/strong>A f&aacute;brica de &Aacute;gua Mineral da Brasal vai se instalar em Luzi&acirc;nia. Ela utilizar&aacute; a fonte Bom Jesus, que tem uma vaz&atilde;o total de 800 metros c&uacute;bicos por hora. A Brasal vai investir R$ 46,9 milh&otilde;es, com a expectativa de gerar 80 novos empregos, entre diretos e indiretos.<\/p>\n<p>Um dos principais respons&aacute;veis pela vinda da empresa, o vice-governador e secret&aacute;rio disse que o novo empreendimento da Brasal em Goi&aacute;s &eacute; mais uma demonstra&ccedil;&atilde;o de que o estado apresenta hoje as condi&ccedil;&otilde;es favor&aacute;veis aos investimentos, com incentivos e est&iacute;mulos, log&iacute;stica e infraestrutura que permitem vislumbrar um horizonte seguro.<\/p>\n<p>A empresa &eacute; um dos maiores grupos empresariais da regi&atilde;o Centro-Oeste, com ind&uacute;strias e servi&ccedil;os nas &aacute;reas de distribui&ccedil;&atilde;o de bebidas, incorpora&ccedil;&atilde;o e constru&ccedil;&atilde;o imobili&aacute;ria, revenda de ve&iacute;culos, corretora de seguros, operadora de cons&oacute;rcio, comercializa&ccedil;&atilde;o de combust&iacute;veis e hotelaria. Com mais de 50 anos de tradi&ccedil;&atilde;o, o grupo vem investindo no Distrito Federal e nas regi&otilde;es sudeste e nordeste de Goi&aacute;s, noroeste de Minas Gerais e sul de Tocantins.&nbsp;<\/p>\n<p style=\"text-align: left;\">A empresa tem hoje 3.442 funcion&aacute;rios nas diferentes &aacute;reas de atua&ccedil;&atilde;o nos dois estados e Distrito Federal, 335 s&oacute; em Goi&aacute;s, e trabalha na perspectiva de chegar a um aumento de 50% no seu faturamento bruto neste ano em rela&ccedil;&atilde;o ao faturamento de 2010. Est&aacute; presente em 55 munic&iacute;pios goianos, atendendo aproximadamente 4 milh&otilde;es de habitantes.<\/p>\n<p style=\"text-align: left;\"><strong>Farmac&ecirc;utica Bifarma<\/strong><\/p>\n<p style=\"text-align: left;\"><strong><\/strong>A Bifarma, atacadista e lojas de varejo&nbsp;de f&aacute;rmacos e cosm&eacute;ticos, vai montar seu novo Centro de Distribui&ccedil;&atilde;o em Goi&aacute;s. A empresa optou pelo Estado ap&oacute;s diversas reuni&otilde;es e negocia&ccedil;&otilde;es feitas com o vice-governador Jos&eacute; Eliton. Com a montagem da filial, 450 empregos diretos e 1.350 indiretos ser&atilde;o acrescentados ao banco de empregos goiano. A empresa vai investir nesta planta o valor de R$ 22,5 milh&otilde;es. Ela garante&nbsp;&nbsp;que o projeto ser&aacute; executado em doze meses, mas n&atilde;o divulgou, ainda, o local onde ser&aacute; constru&iacute;do o novo empreendimento.<\/p>\n<p>A Bifarma opera fortemente nos mercados de S&atilde;o Paulo e Minas Gerais com lojas no mercado varejista, gerando, somente nestes dois estados, mais de tr&ecirc;s mil empregos diretos.<\/p>\n<p>Em maio &uacute;ltimo, o secret&aacute;rio e vice-governador recebeu os diretores da empresa e disse, na ocasi&atilde;o, que Goi&aacute;s estava pronto para receb&ecirc;-los.&nbsp;Em resposta, ouviu de Alexandre Della Cotella, diretor da empresa, que ele estava impressionado com o que encontrou aqui, com a estrutura que envolve a constru&ccedil;&atilde;o do Aeroporto de Cargas de An&aacute;polis e com todo o processo de log&iacute;stica para distribui&ccedil;&atilde;o dos produtos, que &eacute; um dos pilares das&nbsp;&nbsp;atividades da farmac&ecirc;utica.<\/p>\n<p><strong>Data Vision<\/strong><\/p>\n<p style=\"text-align: left;\"><strong><\/strong>Com investimentos fixos estimados em R$ 5,2 milh&otilde;es, a Data Vision vai implantar sua unidade industrial em Aparecida de Goi&acirc;nia. A empresa tecnol&oacute;gica vai fabricar equipamentos para sinaliza&ccedil;&atilde;o e alarme. Ser&atilde;o 160 novos empregos entre diretos e indiretos.<\/p>\n<p>Al&eacute;m de destacar a import&acirc;ncia da concretiza&ccedil;&atilde;o das negocia&ccedil;&otilde;es, Jos&eacute; Eliton fez quest&atilde;o de ressaltar a imprescind&iacute;vel ades&atilde;o das empresas &agrave;s a&ccedil;&otilde;es do Programa de Inova&ccedil;&atilde;o e Tecnologia do Estado de Goi&aacute;s (Inova Goi&aacute;s). Segundo ele, o programa vai atend&ecirc;-los nas ofertas de servi&ccedil;os tecnol&oacute;gicos (testes, ensaios e certifica&ccedil;&atilde;o), processo de pesquisa e desenvolvimento (P&amp;D), por meio da rede Itego, Universidade Estadual de Goi&aacute;s (UEG).<\/p>\n<p><strong>Comunica&ccedil;&atilde;o Setorial<br \/>Secretaria de Estado de Desenvolvimento Econ&ocirc;mico, Cient&iacute;fico e Tecnol&oacute;gico e de Agricultura, Pecu&aacute;ria e Irriga&ccedil;&atilde;o (SED)<br \/>(62) 3201-5463, 3201-5487, 3201-5488<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>&nbsp;<\/strong><\/p>\n<p style=\"text-align: left;\">&nbsp;<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investimentos s&atilde;o da ordem de R$ 324 milh&otilde;es e devem gerar aproximadamente cinco mil novos empregos; Protocolos de Inten&ccedil;&otilde;es ser&atilde;o assinados nesta ter&ccedil;a-feira, &agrave;s 14 horas&nbsp; O governador Marconi Perillo e o vice-governador e secret&aacute;rio de Desenvolvimento Econ&ocirc;mico (SED), Jos&eacute; Eliton, assinam na tarde desta ter&ccedil;a-feira (08\/12) Protocolos de Inten&ccedil;&otilde;es que oficializar&atilde;o a vinda de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":850,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg",800,472,false],"landscape":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg",800,472,false],"portraits":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg",800,472,false],"thumbnail":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e-300x177.jpg",300,177,true],"large":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg",800,472,false],"1536x1536":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg",800,472,false],"2048x2048":["https:\/\/goias.gov.br\/industriaecomercio\/wp-content\/uploads\/sites\/32\/2015\/12\/99-58e.jpg",800,472,false]},"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/industriaecomercio\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/industriaecomercio\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Investimentos s&atilde;o da ordem de R$ 324 milh&otilde;es e devem gerar aproximadamente cinco mil novos empregos; Protocolos de Inten&ccedil;&otilde;es ser&atilde;o assinados nesta ter&ccedil;a-feira, &agrave;s 14 horas&nbsp; O governador Marconi Perillo e o vice-governador e secret&aacute;rio de Desenvolvimento Econ&ocirc;mico (SED), Jos&eacute; Eliton, assinam na tarde desta ter&ccedil;a-feira (08\/12) Protocolos de Inten&ccedil;&otilde;es que oficializar&atilde;o a vinda de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/posts\/851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/comments?post=851"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/posts\/851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/media\/850"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/media?parent=851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/categories?post=851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/industriaecomercio\/wp-json\/wp\/v2\/tags?post=851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}