{"id":9812,"date":"2018-12-27T10:44:55","date_gmt":"2018-12-27T12:44:55","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/imb\/goias-apresenta-o-pior-saldo-do-pais-pelo-segundo-mes-consecutivo\/"},"modified":"2018-12-27T10:44:55","modified_gmt":"2018-12-27T12:44:55","slug":"goias-apresenta-o-pior-saldo-do-pais-pelo-segundo-mes-consecutivo","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/imb\/goias-apresenta-o-pior-saldo-do-pais-pelo-segundo-mes-consecutivo\/","title":{"rendered":"Goi\u00e1s apresenta o pior saldo do pa\u00eds pelo segundo m\u00eas consecutivo &#8211; Novembro\/2018"},"content":{"rendered":"<p>Embora o Brasil como um todo apresente o quinto m\u00eas seguido de crescimento l\u00edquido na gera\u00e7\u00e3o de empregos com carteira assinada e o melhor novembro desde de 2010, o estado de Goi\u00e1s obteve saldo negativo, apresentando o pior saldo nacional pelo segundo m\u00eas consecutivo.<\/p>\n<p><!--more--><\/p>\n<p class=\"btn btn-primary\"><a href=\"https:\/\/goias.gov.br\/imb\/wp-content\/uploads\/sites\/29\/2018\/12\/caged201811-f03.pdf\" id=\"\" style=\"color: white\" target=\"_blank\" title=\"\" rel=\"noopener\">Clique aqui para baixar a publica\u00e7\u00e3o: CAGED&nbsp;&#8211; Novembro\/2018&nbsp;em arquivo no formato PDF<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embora o Brasil como um todo apresente o quinto m\u00eas seguido de crescimento l\u00edquido na gera\u00e7\u00e3o de empregos com carteira assinada e o melhor novembro desde de 2010, o estado de Goi\u00e1s obteve saldo negativo, apresentando o pior saldo nacional pelo segundo m\u00eas consecutivo.<\/p>\n","protected":false},"author":470,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[710],"tags":[],"class_list":["post-9812","post","type-post","status-publish","format-standard","hentry","category-caged-cadastro-geral-de-empregados"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"imprensassp","author_link":"https:\/\/goias.gov.br\/imb\/author\/imprensassp\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/imb\/categoria\/publicacoes\/analises-conjunturais\/caged-cadastro-geral-de-empregados\/\" rel=\"category tag\">CAGED - Cadastro Geral de Empregados e Desempregados<\/a>","rttpg_excerpt":"Embora o Brasil como um todo apresente o quinto m\u00eas seguido de crescimento l\u00edquido na gera\u00e7\u00e3o de empregos com carteira assinada e o melhor novembro desde de 2010, o estado de Goi\u00e1s obteve saldo negativo, apresentando o pior saldo nacional pelo segundo m\u00eas consecutivo.","_links":{"self":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts\/9812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/users\/470"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/comments?post=9812"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts\/9812\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/media?parent=9812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/categories?post=9812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/tags?post=9812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}