{"id":6188,"date":"2007-12-18T08:19:47","date_gmt":"2007-12-18T10:19:47","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/imb\/emprego-cai-em-novembro-em-goias-mas-2007-ainda-e-o-melhor-ano-da-serie-do-caged\/"},"modified":"2007-12-18T08:19:47","modified_gmt":"2007-12-18T10:19:47","slug":"emprego-cai-em-novembro-em-goias-mas-2007-ainda-e-o-melhor-ano-da-serie-do-caged","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/imb\/emprego-cai-em-novembro-em-goias-mas-2007-ainda-e-o-melhor-ano-da-serie-do-caged\/","title":{"rendered":"Emprego cai em novembro em Goi\u00e1s, mas 2007 ainda \u00e9 o melhor ano da s\u00e9rie do Caged"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p class=\"MsoNormal\" style=\"margin-top:6.0pt;text-align:justify;line-height:150%\"><font face=\"Arial\">Dados<br \/>\ndo Caged &#8211; Cadastro Geral de Empregados e Desempregados &#8211; do Minist&Atilde;&copy;rio do<br \/>\nTrabalho e Emprego mostraram que houve redu&Atilde;&sect;&Atilde;&pound;o de 6.294 empregos no m&Atilde;&ordf;s de<br \/>\nnovembro em Goi&Atilde;&iexcl;s. O decl&Atilde;&shy;nio do n&Atilde;&ordm;mero do emprego formal &Atilde;&copy; fruto da<br \/>\nsazonalidade negativa do final de ano no Estado, provocada pela demiss&Atilde;&pound;o nos<br \/>\nsetores da ind&Atilde;&ordm;stria de transforma&Atilde;&sect;&Atilde;&pound;o e agricultura. No acumulado do ano, o<br \/>\npercentual de crescimento do emprego formal atingiu 7,81%, equivalente &Atilde;&nbsp; cria&Atilde;&sect;&Atilde;&pound;o<br \/>\nde 55.943 postos com carteira assinada, o maior registrado na s&Atilde;&copy;rie hist&Atilde;&sup3;rica<br \/>\ndo Caged para o per&Atilde;&shy;odo. No acumulado dos &Atilde;&ordm;ltimos 12 meses o n&Atilde;&ordm;mero de novos<br \/>\ncontratados foi de 39.165. Em termos absolutos, Goi&Atilde;&iexcl;s teve o melhor desempenho<br \/>\nda regi&Atilde;&pound;o Centro-Oeste nos 11 meses do ano de 2007. <\/p>\n<p><\/font><\/p>\n<h5 align=\"center\"><font face=\"Arial\">&nbsp;Gr&Atilde;&iexcl;fico<br \/>\n1<\/p>\n<p><\/font><\/h5>\n<h5 style=\"mso-layout-grid-align: none; text-autospace: none; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"center\"><span style=\"mso-bidi-font-weight: normal\"><font face=\"Arial\">Estado<br \/>\nde Goi&Atilde;&iexcl;s: Saldo &acirc;&#8364;&#8220; Admitidos\/Desligados &acirc;&#8364;&#8220; 2006\/07<\/p>\n<p><\/font><\/span><\/h5>\n<p class=\"MsoNormal\" align=\"center\" style=\"line-height: 100%; margin-top: 0; margin-bottom: 0\"><font face=\"Arial\"><img decoding=\"async\" src=\"images\/imagens_migradas\/\"><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Fonte:<br \/>\nMTE\/Cadastro Geral de Empregados e Desempregados lei 4.923\/65<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<h5><font face=\"Arial\">&nbsp;<\/p>\n<p><\/font><\/h5>\n<h5 style=\"line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"center\"><font face=\"Arial\">Gr&Atilde;&iexcl;fico<br \/>\n2<\/p>\n<p><\/font><\/h5>\n<h5 style=\"line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"center\"><font face=\"Arial\">Estado<br \/>\nde Goi&Atilde;&iexcl;s: Saldo &acirc;&#8364;&#8220; Admitidos\/Desligados &acirc;&#8364;&#8220; Primeiros onze meses do ano<br \/>\n2000\/07<\/p>\n<p><\/font><\/h5>\n<p align=\"center\" style=\"line-height: 100%; margin-top: 0; margin-bottom: 0\" class=\"MsoNormal\"><img decoding=\"async\" src=\"images\/imagens_migradas\/\"><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Fonte:<br \/>\nMTE\/Cadastro Geral de Empregados e Desempregados lei 4.923\/65<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p style=\"margin:0cm;margin-bottom:.0001pt\"><span style=\"mso-fareast-font-family: Times New Roman\"><font face=\"Arial\">&nbsp;<\/p>\n<p><\/font><\/span><\/p>\n<p class=\"MsoHeading7\"><font face=\"Arial\">Setores de atividades<\/p>\n<p><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin-top:6.0pt;text-align:justify;line-height:18.0pt;\nmso-line-height-rule:exactly\"><font face=\"Arial\">Os principais setores<br \/>\nrespons&Atilde;&iexcl;veis pela redu&Atilde;&sect;&Atilde;&pound;o no emprego no m&Atilde;&ordf;s de novembro foram: Ind&Atilde;&ordm;stria de<br \/>\ntransforma&Atilde;&sect;&Atilde;&pound;o, com redu&Atilde;&sect;&Atilde;&pound;o de 4.751 postos de trabalhos, agropecu&Atilde;&iexcl;ria com<br \/>\nqueda de 4.085 vagas e constru&Atilde;&sect;&Atilde;&pound;o civil, com decr&Atilde;&copy;scimo de 157 postos de<br \/>\ntrabalho. As atividades do com&Atilde;&copy;rcio e servi&Atilde;&sect;os evitaram queda maior e<br \/>\nregistraram a cria&Atilde;&sect;&Atilde;&pound;o de 2.361 e 500 postos de trabalho, respectivamente.<\/p>\n<p><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin-top:6.0pt;text-align:justify;line-height:18.0pt;\nmso-line-height-rule:exactly\"><font face=\"Arial\">A ind&Atilde;&ordm;stria de<br \/>\ntransforma&Atilde;&sect;&Atilde;&pound;o foi a atividade que teve o pior desempenho em novembro, quando<br \/>\nreduziu 4.751 vagas no mercado formal, fato explicado pelo perfil sazonal desta<br \/>\natividade no Estado.<span style=\"mso-spacerun: yes\">&nbsp; <\/span>&Atilde;&#8240; comum a<br \/>\ndispensa de trabalhadores nos &Atilde;&ordm;ltimos meses do ano, seja pelo fim da safra de<br \/>\ncana-de-a&Atilde;&sect;&Atilde;&ordm;car ou por ter atendido a maior parte das encomendas do com&Atilde;&copy;rcio.<br \/>\nA subatividade da ind&Atilde;&ordm;stria de transforma&Atilde;&sect;&Atilde;&pound;o que mais contribuiu para o<br \/>\ndesempenho negativo foi a de produtos aliment&Atilde;&shy;cios e bebidas (-4.954 vagas). A<br \/>\nagropecu&Atilde;&iexcl;ria &Atilde;&copy; outra importante atividade que tradicionalmente dispensa<br \/>\ntrabalhadores nos &Atilde;&ordm;ltimos meses do ano, caso da cultura da cana-de-a&Atilde;&sect;&Atilde;&ordm;car.<\/p>\n<p><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin-top:6.0pt;text-align:justify;line-height:150%\"><font face=\"Arial\">Em<br \/>\ncontrapartida, as principais atividades que apresentaram saldos positivos, no m&Atilde;&ordf;s<br \/>\nde novembro de 2007, foram com&Atilde;&copy;rcio (2.361 vagas) e servi&Atilde;&sect;os (500 vagas). No<br \/>\ncom&Atilde;&copy;rcio o destaque foi o varejista (2.114 vagas), devido &Atilde;&nbsp;s contrata&Atilde;&sect;&Atilde;&micro;es<br \/>\npara o per&Atilde;&shy;odo de fim de ano. No setor de servi&Atilde;&sect;os, o destaque ficou por conta<br \/>\nde alojamento e alimenta&Atilde;&sect;&Atilde;&pound;o (326 vagas) e servi&Atilde;&sect;os m&Atilde;&copy;dicos e odontol&Atilde;&sup3;gicos<br \/>\n(101 vagas).<span style=\"color:red\"><\/p>\n<p><\/span><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin-top:6.0pt;text-align:justify;line-height:150%\"><font face=\"Arial\">Ao<br \/>\nanalisar o resultado acumulado de 2007, nota-se que o setor da ind&Atilde;&ordm;stria de<br \/>\ntransforma&Atilde;&sect;&Atilde;&pound;o liderou a gera&Atilde;&sect;&Atilde;&pound;o de empregos. Entre janeiro e novembro deste<br \/>\nano foram computados 20.821 postos a mais no estoque de emprego do setor. <\/p>\n<p><\/font><\/p>\n<h5 style=\"mso-layout-grid-align: none; text-autospace: none; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"center\"><span style=\"mso-bidi-font-weight: normal\"><font face=\"Arial\">Tabela<br \/>\n1<\/p>\n<p><\/font><\/span><\/h5>\n<h5 style=\"mso-layout-grid-align: none; text-autospace: none; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"center\"><span style=\"mso-bidi-font-weight: normal\"><font face=\"Arial\">Estado<br \/>\nde Goi&Atilde;&iexcl;s: Saldo &acirc;&#8364;&#8220; Admitidos\/Desligados por setor de atividade econ&Atilde;&acute;mica &acirc;&#8364;&#8220;<br \/>\n2006\/07<\/p>\n<p><\/font><br \/>\n<\/span><\/h5>\n<p class=\"MsoNormal\" align=\"center\" style=\"line-height: 100%; margin-top: 0; margin-bottom: 0\"><img decoding=\"async\" src=\"images\/imagens_migradas\/\"><\/p>\n<p style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" class=\"MsoNormal\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Fonte:<br \/>\nMTE\/Cadastro Geral de Empregados e Desempregados lei 4.923\/65<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p class=\"MsoHeading7\"><font face=\"Arial\">&nbsp;<\/p>\n<p><\/font><\/p>\n<p class=\"MsoHeading7\"><font face=\"Arial\">Munic&Atilde;&shy;pios<\/p>\n<p><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin-top:6.0pt;text-align:justify;line-height:150%\"><font face=\"Arial\">Dos<br \/>\nmunic&Atilde;&shy;pios goianos com mais de 30 mil habitantes, os melhores desempenhos, em<br \/>\ntermos absolutos, no m&Atilde;&ordf;s de novembro de 2007, foram constatados em Goi&Atilde;&cent;nia,<br \/>\ncom 1.449 novas vagas, Aparecida de Goi&Atilde;&cent;nia, com 496, An&Atilde;&iexcl;polis, com 347 e<br \/>\nCatal&Atilde;&pound;o, com 263 novos postos de trabalho.<span style=\"mso-spacerun: yes\">&nbsp;<br \/>\n<\/span>J&Atilde;&iexcl; no acumulado do ano, os munic&Atilde;&shy;pios que mais destacaram foram Goi&Atilde;&cent;nia,<br \/>\ncom 12.457 novos postos, Aparecida de Goi&Atilde;&cent;nia, com 4.751, Rio Verde, com 3.098,<br \/>\ne An&Atilde;&iexcl;polis, com 3.159 novas oportunidades de trabalho. <span style=\"color:red\"><\/p>\n<p><\/span><\/font><\/p>\n<h5 style=\"margin-top:6.0pt;margin-right:0cm;margin-bottom:6.0pt;margin-left:\n0cm\"><span style=\"mso-bidi-font-weight: normal\"><font face=\"Arial\">&nbsp;<\/p>\n<p><\/font><\/span><\/h5>\n<h5 style=\"mso-layout-grid-align: none; text-autospace: none; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"center\"><span style=\"mso-bidi-font-weight: normal\"><font face=\"Arial\">Tabela<br \/>\n2<\/p>\n<p><\/font><\/span><\/h5>\n<h5 align=\"center\" style=\"mso-layout-grid-align: none; text-autospace: none; line-height: 100%; margin-top: 0; margin-bottom: 0\"><span style=\"mso-bidi-font-weight: normal\"><font face=\"Arial\">Estado<br \/>\nde Goi&Atilde;&iexcl;s: comportamento do mercado formal de trabalho, por munic&Atilde;&shy;pios com mais<br \/>\nde 30 mil habitantes &acirc;&#8364;&#8220; 2006\/07<\/p>\n<p><\/font><br \/>\n<\/span><\/h5>\n<p class=\"MsoNormal\" align=\"center\" style=\"line-height: 100%; margin-top: 0; margin-bottom: 0\"><img decoding=\"async\" src=\"images\/imagens_migradas\/\"><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Fonte:<br \/>\nMTE\/Cadastro Geral de Empregados e Desempregados lei 4.923\/65<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent:18.0pt\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\">&nbsp;&nbsp;<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 100%; margin-top: 0; margin-bottom: 0\"><b><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Equipe<br \/>\nde Conjuntura da Seplan:<\/p>\n<p><\/font><br \/>\n<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Dinamar<br \/>\nFerreira Marques<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Eduiges<br \/>\nRomanatto<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\" size=\"1\">Marcos<br \/>\nFernando Arriel<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\"><font size=\"1\">Maria<br \/>\nde F&Atilde;&iexcl;tima Mendon&Atilde;&sect;a Faleiro Rocha<\/p>\n<p><\/font><\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 0; line-height: 100%; margin-top: 0; margin-bottom: 0\" align=\"left\"><span style=\"mso-bidi-font-size: 12.0pt\"><font face=\"Arial\">&nbsp;<\/p>\n<p><\/font><br \/>\n<\/span><\/p>\n<p><\/font><\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dados do Caged &#8211; Cadastro Geral de Empregados e Desempregados &#8211; do Minist&Atilde;&copy;rio do Trabalho e Emprego mostraram que houve redu&Atilde;&sect;&Atilde;&pound;o de 6.294 empregos no m&Atilde;&ordf;s de novembro em Goi&Atilde;&iexcl;s. O decl&Atilde;&shy;nio do n&Atilde;&ordm;mero do emprego formal &Atilde;&copy; fruto da sazonalidade negativa do final de ano no Estado, provocada pela demiss&Atilde;&pound;o nos setores da ind&Atilde;&ordm;stria [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[710],"tags":[],"class_list":["post-6188","post","type-post","status-publish","format-standard","hentry","category-caged-cadastro-geral-de-empregados"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/imb\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/imb\/categoria\/publicacoes\/analises-conjunturais\/caged-cadastro-geral-de-empregados\/\" rel=\"category tag\">CAGED - Cadastro Geral de Empregados e Desempregados<\/a>","rttpg_excerpt":"Dados do Caged &#8211; Cadastro Geral de Empregados e Desempregados &#8211; do Minist&Atilde;&copy;rio do Trabalho e Emprego mostraram que houve redu&Atilde;&sect;&Atilde;&pound;o de 6.294 empregos no m&Atilde;&ordf;s de novembro em Goi&Atilde;&iexcl;s. O decl&Atilde;&shy;nio do n&Atilde;&ordm;mero do emprego formal &Atilde;&copy; fruto da sazonalidade negativa do final de ano no Estado, provocada pela demiss&Atilde;&pound;o nos setores da ind&Atilde;&ordm;stria&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts\/6188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/comments?post=6188"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts\/6188\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/media?parent=6188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/categories?post=6188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/tags?post=6188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}