
{"id":10248,"date":"2020-03-23T14:07:14","date_gmt":"2020-03-23T17:07:14","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/imb\/boletim-do-setor-lacteo-marco-2020\/"},"modified":"2020-03-23T14:07:14","modified_gmt":"2020-03-23T17:07:14","slug":"boletim-do-setor-lacteo-marco-2020","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/imb\/boletim-do-setor-lacteo-marco-2020\/","title":{"rendered":"Boletim do setor l\u00e1cteo &#8211; Mar\u00e7o\/2020"},"content":{"rendered":"<p style=\"text-align: justify;\">O Boletim de mercado do setor l\u00e1cteo goiano objetiva apresentar os resultados do \u00edndice de pre\u00e7os de derivados l\u00e1cteos definida pela C\u00e2mara T\u00e9cnica e de Concilia\u00e7\u00e3o da Cadeia L\u00e1ctea de Goi\u00e1s.&nbsp;A seguir, s\u00e3o apresentados os resultados para o m\u00eas de refer\u00eancia de mar\u00e7o e que foram levados \u00e0 reuni\u00e3o deliberativa da c\u00e2mara t\u00e9cnica no dia 23&nbsp;de mar\u00e7o de 2020.<\/p>\n<p><!--more--><\/p>\n<p class=\"btn btn-primary\"><a href=\"https:\/\/goias.gov.br\/imb\/wp-content\/uploads\/sites\/29\/2020\/03\/boletim-leite202003-b36.pdf\" style=\"color: white\" target=\"_blank\" rel=\"noopener\">Clique aqui para o Boletim do Setor L\u00e1cteo: 3 &#8211; Mar\u00e7o\/2020<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Boletim de mercado do setor l\u00e1cteo goiano objetiva apresentar os resultados do \u00edndice de pre\u00e7os de derivados l\u00e1cteos definida pela C\u00e2mara T\u00e9cnica e de Concilia\u00e7\u00e3o da Cadeia L\u00e1ctea de Goi\u00e1s.&nbsp;A seguir, s\u00e3o apresentados os resultados para o m\u00eas de refer\u00eancia de mar\u00e7o e que foram levados \u00e0 reuni\u00e3o deliberativa da c\u00e2mara t\u00e9cnica no dia [&hellip;]<\/p>\n","protected":false},"author":472,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[749],"tags":[],"class_list":["post-10248","post","type-post","status-publish","format-standard","hentry","category-boletim-do-setor-lacteo"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"3\u00ba SGT RENER","author_link":"https:\/\/goias.gov.br\/imb\/author\/renersantos\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/imb\/categoria\/publicacoes\/boletim-do-setor-lacteo\/\" rel=\"category tag\">Boletim do Setor L\u00e1cteo<\/a>","rttpg_excerpt":"O Boletim de mercado do setor l\u00e1cteo goiano objetiva apresentar os resultados do \u00edndice de pre\u00e7os de derivados l\u00e1cteos definida pela C\u00e2mara T\u00e9cnica e de Concilia\u00e7\u00e3o da Cadeia L\u00e1ctea de Goi\u00e1s.&nbsp;A seguir, s\u00e3o apresentados os resultados para o m\u00eas de refer\u00eancia de mar\u00e7o e que foram levados \u00e0 reuni\u00e3o deliberativa da c\u00e2mara t\u00e9cnica no dia&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts\/10248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/users\/472"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/comments?post=10248"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/posts\/10248\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/media?parent=10248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/categories?post=10248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/imb\/wp-json\/wp\/v2\/tags?post=10248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}