{"id":4200,"date":"2023-09-27T19:28:37","date_gmt":"2023-09-27T22:28:37","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/goiasprev\/convenios-e-transferencias-realizadas\/"},"modified":"2026-06-29T10:55:26","modified_gmt":"2026-06-29T13:55:26","slug":"convenios-e-transferencias-realizadas","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/goiasprev\/convenios-e-transferencias-realizadas\/","title":{"rendered":"Acordos sem Transfer\u00eancia de Recursos"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/acordos-sem-recursos-site-10.xlsx\" style=\"background-color:#219633;font-size:17px\">Exportar Dados<\/a><\/div>\n<\/div>\n\n\n\n<table class=\"planilhaview display\" style=\"width:100%\"><thead><tr><th>PART\u00cdCIPES<\/th><th>N\u00ba\/ANO<\/th><th>OBJETO<\/th><th>IN\u00cdCIO DA VIG\u00caNCIA<\/th><th>T\u00c9RMINO DA VIG\u00caNCIA<\/th><th>INTEIRO TEOR<\/th><\/tr><tr><th><input type=\"text\" placeholder=\"Filtrar PART\u00cdCIPES\"><\/th><th><input type=\"text\" placeholder=\"Filtrar N\u00ba\/ANO\"><\/th><th><input type=\"text\" placeholder=\"Filtrar OBJETO\"><\/th><th><input type=\"text\" placeholder=\"Filtrar IN\u00cdCIO DA VIG\u00caNCIA\"><\/th><th><input type=\"text\" placeholder=\"Filtrar T\u00c9RMINO DA VIG\u00caNCIA\"><\/th><th><input type=\"text\" placeholder=\"Filtrar INTEIRO TEOR\"><\/th><\/tr><\/thead><tbody><tr><td style=\"color: #2C2F34; background-color: #FFFFFF;\">Acordo de Coopera\u00e7\u00e3o T\u00e9cnica entre os Poderes do Estado de Goi\u00e1s e \u00d3rg\u00e3os Governamentais Aut\u00f4nomos e a Goi\u00e1s Previd\u00eancia <\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\">n\u00b0 1\/2024<\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\">Termo de Coopera\u00e7\u00e3o T\u00e9cnica que entre si celebram os Poderes do Estado de Goi\u00e1s e os \u00d3rg\u00e3os Governamentais Aut\u00f4nomos e a Goi\u00e1s Previd\u00eancia para garantir o gerenciamento indireto da Goiasprev na gest\u00e3o do Regime Pr\u00f3prio de Previd\u00eancia dos Servidores P\u00fablicos do Estado de Goi\u00e1s.<\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\">10.12.2024<\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\">10.12.2029<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/TERMO-DE-COOPERACAO-TECNICA-No-1.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/TERMO-DE-COOPERACAO-TECNICA-No-1.pdf<\/a><\/td><\/tr><tr><td style=\"color: #2C2F34; background-color: #FFFFFF;\">Acordo de Coopera\u00e7\u00e3o T\u00e9cnica entre Secretaria-Geral de Governo - SGG e Goi\u00e1s Previd\u00eancia - Goiasprev<\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\">n\u00b0 005\/2024<\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\"> Implementa\u00e7\u00e3o do \"Programa de Efici\u00eancia Energ\u00e9tica\nda administra\u00e7\u00e3o direta e indireta do Estado de Goi\u00e1s\", institu\u00eddo\npelo Decreto estadual n\u00ba 10.417, de 1\u00ba de mar\u00e7o de 2024, por\nmeio de a\u00e7\u00f5es destinadas \u00e0 redu\u00e7\u00e3o de custos com energia\nel\u00e9trica nas unidades consumidoras \u2013 UCs pertencentes ao Poder\nP\u00fablico Estadual.\n<\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\">30.10.2024<\/td><td style=\"color: #2C2F34; background-color: #FFFFFF;\">Vig\u00eancia por prazo indeterminado, a contar da data de\nsua assinatura por todos os signat\u00e1rios.<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/SEI_66755490_Extrato_de_Publicacao-1.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/SEI_66755490_Extrato_de_Publicacao-1.pdf<\/a><\/td><\/tr><tr><td style=\"color: #000000; background-color: #FFFFFF;\">Acordo de Coopera\u00e7\u00e3o T\u00e9cnica entre Goias Previd\u00eancia - Goiasprev e Defensoria P\u00fablica do Estado de Goi\u00e1s - DPE-GO<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">n\u00ba 01\/2024<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">O presente Acordo de Coopera\u00e7\u00e3o T\u00e9cnica tem por objeto o m\u00fatuo acordo para a realiza\u00e7\u00e3o de a\u00e7\u00f5es administrativas, a serem desenvolvidas pelas partes, voltadas \u00e0: I - pr\u00e1tica dos atos necess\u00e1rios \u00e0 aprecia\u00e7\u00e3o dos processos relativos \u00e0 mat\u00e9ria de que trata o Cap\u00edtulo VIII, arts. 138 e seguintes, da Lei Complementar n\u00ba 161\/2020, pela GOIASPREV, compreendendo an\u00e1lise t\u00e9cnica dos pedidos de averba\u00e7\u00e3o de tempo de contribui\u00e7\u00e3o efetuados pelos membros da Defensoria P\u00fablica e seus respectivos servidores; II - atividade de elabora\u00e7\u00e3o de c\u00e1lculo do valor dos proventos, equivalente \u00e0 m\u00e9dia dos sal\u00e1rios de contribui\u00e7\u00f5es e das remunera\u00e7\u00f5es adotadas como base de contribui\u00e7\u00e3o previdenci\u00e1ria, quando das aposentadorias dos membros da Defensoria P\u00fablica e seus respectivos servidores, utilizado para a fixa\u00e7\u00e3o dos proventos de aposentadoria concedidas com fundamento do art. 40 da Constitui\u00e7\u00e3o Federal, com reda\u00e7\u00e3o dada pela Emenda Constitucional n\u00ba 41\/2003, de acordo com a sistem\u00e1tica definida na Lei Federal n\u00ba 10.887\/2004 ou de acordo com as disposi\u00e7\u00f5es da Emenda Constitucional n\u00ba 103\/2019, da Emenda Constitucional Estadual n\u00ba 65\/2019 e da Lei Complementar n\u00ba 161\/2020.<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">07.03.2024<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">07.03.2029<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/ACORDO_DE_COOPERACAO_TECNICA_01_DPEGO.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/ACORDO_DE_COOPERACAO_TECNICA_01_DPEGO.pdf<\/a><\/td><\/tr><tr><td style=\"color: #000000; background-color: #FFFFFF;\">Acordo de Coopera\u00e7\u00e3o T\u00e9cnica entre Goi\u00e1s Previd\u00eancia - Goiasprev e Controladoria-Geral do Estado de Goi\u00e1s - CGE<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">n\u00ba 01\/2024<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">O presente instrumento tem por objeto a coopera\u00e7\u00e3o t\u00e9cnica entre os part\u00edcipes, visando a implementa\u00e7\u00e3o de medidas conjuntas para o cumprimento da a\u00e7\u00e3o\/requisito \u201cEstrutura de Controle Interno\u201d, subitem 3.1.4 do Manual do Pr\u00f3-Gest\u00e3o RPPS.\u201d<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">24.01.2024<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">24.01.2025<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/D.O.E-Acordo-de-Cooperacao-Tecnica_1_2024.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/D.O.E-Acordo-de-Cooperacao-Tecnica_1_2024.pdf<\/a><\/td><\/tr><tr><td style=\"color: #202D4F; background-color: #FFFFFF;\">Termo Aditivo de Prorroga\u00e7\u00e3o e Altera\u00e7\u00e3o do Termo de Cess\u00e3o de Uso entre o Instituto de Assist\u00eancia dos Servidores P\u00fablicos do Estado de Goi\u00e1s - Ipasgo e a Goi\u00e1s Previd\u00eancia - Goiasprev<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">n\u00ba 01\/2024<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">O presente Termo Aditivo tem por finalidade a\nprorroga\u00e7\u00e3o do prazo de vig\u00eancia em car\u00e1ter excepcional e a\naltera\u00e7\u00e3o ao TERMO DE CESS\u00c3O DE USO Origin\u00e1rio, do im\u00f3vel\nlocalizado nas depend\u00eancias do Servi\u00e7o Social Aut\u00f4nomo de\nAssist\u00eancia \u00e0 Sa\u00fade dos Servidores P\u00fablicos e Militares do Estado\nde Goi\u00e1s - IPASGO SA\u00daDE, pertencente ao CEDENTE.<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">11.12.2023<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">11.12.2024<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/SEI_54723826_Aditivo-Termo-de-cessao-de-uso.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/SEI_54723826_Aditivo-Termo-de-cessao-de-uso.pdf<\/a><\/td><\/tr><tr><td style=\"color: #000000; background-color: #FFFFFF;\">Termo de Coopera\u00e7\u00e3o entre Goi\u00e1s Previd\u00eancia - Goiasprev e Funda\u00e7\u00e3o de Previd\u00eancia Complementar do Brasil Central<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">n\u00b0 001\/2022<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">Este Termo de Coopera\u00e7\u00e3o tem por objeto aux\u00edlio\nt\u00e9cnico visando o cumprimento de obriga\u00e7\u00f5es legais referentes \u00e0 elabora\u00e7\u00e3o anual, por atu\u00e1rio devidamente habilitado, do Plano de Custeio para o ano de 2023, Parecer Atuarial referente ao ano de 2022 e 2023, Demonstra\u00e7\u00e3o Atuarial Simplificada referente ao ano de 2022 e 2023 a serem encaminhados \u00e0 Superintend\u00eancia Nacional de Previd\u00eancia Complementar \u2013 PREVIC, relat\u00f3rio atuarial semestral da entidade em 2022 e 2023 e eventuais documentos relativos \u00e0 transfer\u00eancia de gest\u00e3o do plano.\n<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">20.06.2022<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">31.03.2024<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/Termo_de_Cooperacao_Goiasprev_Prevcom-BrC.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/Termo_de_Cooperacao_Goiasprev_Prevcom-BrC.pdf<\/a><\/td><\/tr><tr><td style=\"color: #000000; background-color: #FFFFFF;\">Acordo de Coopera\u00e7\u00e3o T\u00e9cnica entre Goi\u00e1s Previd\u00eancia - Goiasprev e Controladoria-Geral do Estado de Goi\u00e1s - CGE<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">n\u00b0 1-2021\/2021<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">O presente instrumento tem por objeto a coopera\u00e7\u00e3o t\u00e9cnica entre os part\u00edcipes, visando a implementa\u00e7\u00e3o de medidas conjuntas para o cumprimento no n\u00edvel II da a\u00e7\u00e3o\/requisito \u201cEstrutura de Controle Interno\u201d, subitem 3.1.4 do Manual do Pr\u00f3-Gest\u00e3o RPPS.<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">06.10.2021<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">07.10.2022<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/SEI_GOVERNADORIA-000025781963-Acordo-de-Cooperacao-Tecnica-2.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/SEI_GOVERNADORIA-000025781963-Acordo-de-Cooperacao-Tecnica-2.pdf<\/a><\/td><\/tr><tr><td style=\"color: #202D4F; background-color: #FFFFFF;\">Termo de Cess\u00e3o de Uso entre o Instituto de Assist\u00eancia dos Servidores P\u00fablicos do Estado de Goi\u00e1s - Ipasgo e a Goi\u00e1s Previd\u00eancia - Goiasprev<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">n\u00b0 01\/2018<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">O presente Termo de Cess\u00e3o de Uso tem por objeto a formaliza\u00e7\u00e3o a transfer\u00eancia gratuita da posse de espa\u00e7o fisico \u00e1 CESSION\u00c1RIA, para desenvolver suas atividades segundo a sua destina\u00e7\u00e3o, no funcionamento de suas compet\u00eancias intitucionais.<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">11.12.2018<\/td><td style=\"color: #000000; background-color: #FFFFFF;\">12.12.2023<\/td><td style=\"color: #0563C1; background-color: #FFFFFF;text-decoration: underline;\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/Termo-de-Cessao-de-Uso.pdf\" target=\"_blank\">https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/Termo-de-Cessao-de-Uso.pdf<\/a><\/td><\/tr><\/tbody><\/table><div class=\"wp-block-file\"><a href=\"https:\/\/goias.gov.br\/goiasprev\/wp-content\/uploads\/sites\/36\/2023\/09\/acordos-sem-recursos-site-10.xlsx\">acordos-sem-recursos-site-10.xlsx&nbsp; <span class=\"wp-block-file__button wp-element-button\">Baixar<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":711,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4200","post","type-post","status-publish","format-standard","hentry","category-institucional"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"allder.ramos@fornecedores.goias.gov.br","author_link":"https:\/\/goias.gov.br\/goiasprev\/author\/allder-ramosfornecedores-goias-gov-br\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/goiasprev\/categoria\/institucional\/\" rel=\"category tag\">Institucional<\/a>","rttpg_excerpt":null,"_links":{"self":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/4200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/users\/711"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/comments?post=4200"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/4200\/revisions"}],"predecessor-version":[{"id":30990,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/4200\/revisions\/30990"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/media?parent=4200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/categories?post=4200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/tags?post=4200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}