{"id":2978,"date":"2018-09-11T16:16:02","date_gmt":"2018-09-11T19:16:02","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/goiasprev\/aposentadoria-voluntaria\/"},"modified":"2024-02-28T09:50:57","modified_gmt":"2024-02-28T12:50:57","slug":"aposentadoria-voluntaria-post","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/goiasprev\/aposentadoria-voluntaria-post\/","title":{"rendered":"Aposentadoria Volunt\u00e1ria"},"content":{"rendered":"<p style=\"text-align: justify;\">A aposentadoria volunt&aacute;ria &eacute; uma das esp&eacute;cies de vac&acirc;ncia do cargo p&uacute;blico que encerra o v&iacute;nculo administrativo do servidor p&uacute;blico efetivo e inicia o seu v&iacute;nculo previdenci&aacute;rio com o RPPS. Ela poder&aacute; ser requerida a partir do atendimento simult&acirc;neo dos requisitos exigidos pelas leis vigentes.<\/p>\n<p style=\"text-align: justify;\">Os requisitos da aposentadoria volunt&aacute;ria s&atilde;o definidos conforme a data em que o servidor implementar o direito. Assim, ap&oacute;s a publica&ccedil;&atilde;o da <u><a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/emendas\/emc\/emc103.htm\">EC n&ordm; 103\/2019<\/a>&nbsp;<\/u>e da&nbsp;<a href=\"https:\/\/legisla.casacivil.go.gov.br\/pesquisa_legislacao\/103151\"><u>EC estadual n&ordm; 65\/2019<\/u><\/a>, h&aacute; tr&ecirc;s possibilidades temporais:<\/p>\n<p style=\"text-align: justify;\"><strong>1 &#8211; Servidores amparados pelo direito adquirido<\/strong> <strong>at&eacute; 29\/12\/2019*<\/strong> &#8211; os segurados do RPPS\/GO que implementaram os requisitos para obter qualquer esp&eacute;cie de aposentadoria, at&eacute; a *data da publica&ccedil;&atilde;o da EC estadual n&ordm; 65\/2019, podem pedir o benef&iacute;cio a qualquer tempo, com garantia do c&aacute;lculo e reajuste com base na legisla&ccedil;&atilde;o vigente &agrave;quela &eacute;poca, conforme o art. 2&ordm; da EC estadual n&ordm; 65\/2019.<\/p>\n<p style=\"text-align: justify;\"><strong>2 &#8211; Servidores que j&aacute; haviam ingressado no servi&ccedil;o p&uacute;blico em cargo efetivo at&eacute; 29\/12\/2019* &#8211; regras de transi&ccedil;&atilde;o&nbsp;&#8211; <\/strong>os segurados do RPPS\/GO, em geral,&nbsp;que j&aacute; tinham ingressado no servi&ccedil;o p&uacute;blico em cargo efetivo,&nbsp;at&eacute; a *data da publica&ccedil;&atilde;o da EC estadual n&ordm; 65\/2019, e ainda faltavam os requisitos para aposentar, podem optar&nbsp;por uma das duas regras de transi&ccedil;&atilde;o abaixo descritas, a saber: regra dos&nbsp;pontos&nbsp;ou&nbsp;do&nbsp;per&iacute;odo adicional de contribui&ccedil;&atilde;o, tamb&eacute;m chamada de regra do ped&aacute;gio, como segue:<\/p>\n<p style=\"text-align: left;\"><strong><a href=\"https:\/\/legisla.casacivil.go.gov.br\/pesquisa_legislacao\/103671\">Lei Complementar n&ordm; 161\/2020<\/a>&nbsp;&#8211;&nbsp;REGRA DE TRANSI&Ccedil;&Atilde;O&nbsp;DOS PONTOS<\/strong><\/p>\n<div style=\"text-align: left;\">Art. 71.&nbsp; O segurado do RPPS\/GO que tenha ingressado no servi&ccedil;o p&uacute;blico em cargo efetivo at&eacute; a data de entrada em vigor da Emenda Constitucional estadual n&ordm; 65, de 21 de dezembro de 2019, poder&aacute; aposentar-se voluntariamente quando preencher, cumulativamente, os seguintes requisitos:<\/div>\n<div style=\"text-align: left;\">I &#8211; 56 (cinquenta e seis) anos de idade, se for mulher, e 61 (sessenta e um) anos de idade, se for homem, observado o disposto no &sect; 1&ordm; deste artigo;<\/div>\n<div style=\"text-align: left;\">II &#8211; 30 (trinta) anos de contribui&ccedil;&atilde;o, se for mulher, e 35 (trinta e cinco) anos de contribui&ccedil;&atilde;o, se for homem;<\/div>\n<div style=\"text-align: left;\">III &#8211; 20 (vinte) anos de efetivo exerc&iacute;cio no servi&ccedil;o p&uacute;blico;<\/div>\n<div style=\"text-align: left;\">IV &#8211; 5 (cinco) anos no cargo efetivo em que se der a aposentadoria; e<\/div>\n<div style=\"text-align: left;\">V &#8211; somat&oacute;rio da idade e do tempo de contribui&ccedil;&atilde;o, inclu&iacute;das as fra&ccedil;&otilde;es, equivalente a 86 (oitenta e seis) pontos, se for mulher, e 96 (noventa e seis) pontos, se for homem, observado o disposto nos &sect;&sect; 2&ordm; e 3&ordm; deste artigo.<\/div>\n<div style=\"text-align: left;\">&sect; 1&ordm;&nbsp; A partir de 1&ordm; de janeiro de 2022, a idade m&iacute;nima a que se refere o inciso I do caput deste artigo ser&aacute; de 57 (cinquenta e sete) anos de idade, se for mulher, e 62 (sessenta e dois) anos de idade, se for homem.<\/div>\n<div style=\"text-align: left;\">&sect; 2&ordm;&nbsp; A partir do ano de 2020, a pontua&ccedil;&atilde;o a que se refere o inciso V do caput deste artigo ser&aacute; acrescida de 1 (um) ponto, a cada ano, at&eacute; atingir o limite de 100 (cem) pontos, se for mulher, e de 105 (cento e cinco) pontos, se for homem.<\/div>\n<div style=\"text-align: left;\">&sect; 3&ordm;&nbsp; A idade e o tempo de contribui&ccedil;&atilde;o ser&atilde;o apurados em dias para o c&aacute;lculo do somat&oacute;rio de pontos a que se refere o inciso V do caput e o &sect; 2&ordm; deste artigo.[&#8230;]<\/div>\n<div style=\"text-align: left;\">&nbsp;<\/div>\n<div style=\"text-align: left;\"><strong><a href=\"https:\/\/legisla.casacivil.go.gov.br\/pesquisa_legislacao\/103671\">Lei Complementar n&ordm; 161\/2020<\/a>&nbsp; &#8211; REGRA DE TRANSI&Ccedil;&Atilde;O DO PED&Aacute;GIO<\/strong><\/div>\n<div style=\"text-align: left;\">Art. 72. O segurado do RPPS\/GO que tenha ingressado no servi&ccedil;o p&uacute;blico em cargo efetivo at&eacute; a data de entrada em vigor da Emenda Constitucional estadual n&ordm; 65, de 2019, poder&aacute; aposentar-se voluntariamente quando preencher, cumulativamente, os seguintes requisitos:<\/div>\n<div style=\"text-align: left;\">I &#8211; 57 (cinquenta e sete) anos de idade, se for mulher, e 60 (sessenta) anos de idade, se for homem;<\/div>\n<div style=\"text-align: left;\">II &#8211; 30 (trinta) anos de contribui&ccedil;&atilde;o, se for mulher, e 35 (trinta e cinco) anos de contribui&ccedil;&atilde;o, se for homem;<\/div>\n<div style=\"text-align: left;\">III &#8211; 20 (vinte) anos de efetivo exerc&iacute;cio no servi&ccedil;o p&uacute;blico e 5 (cinco) anos no cargo efetivo em que se der a aposentadoria; e<\/div>\n<div style=\"text-align: left;\">IV &#8211;&nbsp; per&iacute;odo adicional de contribui&ccedil;&atilde;o correspondente ao tempo que, na data de entrada em vigor da Emenda Constitucional estadual n&ordm; 65, de 2019, faltaria para atingir o tempo m&iacute;nimo de contribui&ccedil;&atilde;o referido no inciso II deste artigo. [&#8230;]<\/div>\n<p style=\"text-align: justify;\"><strong>3 &#8211;&nbsp;Servidores que ingressaram no servi&ccedil;o p&uacute;blico ap&oacute;s 29\/12\/2019*<\/strong> &#8211;&nbsp;<strong>regra permanente<\/strong> &#8211; os segurados do RPPS\/GO, em geral,&nbsp;que tenham ingressado no servi&ccedil;o p&uacute;blico em cargo efetivo, ap&oacute;s a *data da publica&ccedil;&atilde;o da EC estadual n&ordm; 65\/2019, far&atilde;o jus &agrave; aposentadoria volunt&aacute;ria conforme os requisitos da regra permanente, como segue:<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/legisla.casacivil.go.gov.br\/pesquisa_legislacao\/103671\">Lei Complementar n&ordm; 161\/2020<\/a>&nbsp; &#8211; REGRA PERMANENTE<\/strong><\/p>\n<p style=\"text-align: justify;\">Art. 68. O segurado ativo far&aacute; jus &agrave; aposentadoria volunt&aacute;ria por idade e tempo de contribui&ccedil;&atilde;o, desde que preencha,<br \/>\ncumulativamente, os seguintes requisitos:<br \/>\nI &#8211;&nbsp;&nbsp;62 (sessenta e dois) anos de idade, se for mulher, e 65 (sessenta e cinco) anos de idade, se for homem; e<br \/>\nII &#8211;&nbsp;25 (vinte e cinco) anos de contribui&ccedil;&atilde;o, desde que cumprido o tempo m&iacute;nimo de 10 (dez) anos de efetivo exerc&iacute;cio no servi&ccedil;o<br \/>\np&uacute;blico e de 5 (cinco) anos no cargo efetivo em que for concedida a aposentadoria.<\/p>\n<p style=\"text-align: justify;\">Al&eacute;m das regras j&aacute; mencionadas, h&aacute; os servidores p&uacute;blicos efetivos que, em virtude de&nbsp;autoriza&ccedil;&atilde;o constitucional, podem se aposentar com requisitos diferenciados para concess&atilde;o do&nbsp;benef&iacute;cio, s&atilde;o eles:<\/p>\n<ol>\n<li style=\"text-align: justify;\">servidores com defici&ecirc;ncia;<\/li>\n<li style=\"text-align: justify;\">servidores ocupantes dos cargos estaduais de agente penitenci&aacute;rio, de agente socioeducativo ou de policial civil;<\/li>\n<li style=\"text-align: justify;\">servidores estaduais cujas atividades sejam exercidas com efetiva exposi&ccedil;&atilde;o a agentes nocivos qu&iacute;micos, f&iacute;sicos e biol&oacute;gicos prejudiciais &agrave; sa&uacute;de, ou associa&ccedil;&atilde;o destes agentes;<\/li>\n<li style=\"text-align: justify;\">os servidores ocupantes do cargo estadual de professor que comprovem tempo de efetivo exerc&iacute;cio das fun&ccedil;&otilde;es de magist&eacute;rio na educa&ccedil;&atilde;o infantil e no ensino fundamental e m&eacute;dio.<\/li>\n<\/ol>\n<p>Os requisitos das aposentadorias especiais supracitadas s&atilde;o os descritos no art. 69 da <a href=\"https:\/\/legisla.casacivil.go.gov.br\/pesquisa_legislacao\/103671\">Lei Complementar n&ordm; 161\/2020.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A aposentadoria volunt&aacute;ria &eacute; uma das esp&eacute;cies de vac&acirc;ncia do cargo p&uacute;blico que encerra o v&iacute;nculo administrativo do servidor p&uacute;blico efetivo e inicia o seu v&iacute;nculo previdenci&aacute;rio com o RPPS. Ela poder&aacute; ser requerida a partir do atendimento simult&acirc;neo dos requisitos exigidos pelas leis vigentes. Os requisitos da aposentadoria volunt&aacute;ria s&atilde;o definidos conforme a data [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-2978","post","type-post","status-publish","format-standard","hentry","category-aposentadorias-e-beneficios"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"barbaracb","author_link":"https:\/\/goias.gov.br\/goiasprev\/author\/barbaracb\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/goiasprev\/categoria\/aposentadorias-e-beneficios\/\" rel=\"category tag\">Aposentadorias e Benef\u00edcios<\/a>","rttpg_excerpt":"A aposentadoria volunt&aacute;ria &eacute; uma das esp&eacute;cies de vac&acirc;ncia do cargo p&uacute;blico que encerra o v&iacute;nculo administrativo do servidor p&uacute;blico efetivo e inicia o seu v&iacute;nculo previdenci&aacute;rio com o RPPS. Ela poder&aacute; ser requerida a partir do atendimento simult&acirc;neo dos requisitos exigidos pelas leis vigentes. Os requisitos da aposentadoria volunt&aacute;ria s&atilde;o definidos conforme a data&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/2978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/comments?post=2978"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/2978\/revisions"}],"predecessor-version":[{"id":4375,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/2978\/revisions\/4375"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/media?parent=2978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/categories?post=2978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/tags?post=2978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}