

{"id":2300,"date":"2012-05-22T06:05:31","date_gmt":"2012-05-22T09:05:31","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/goiasprev\/servidores-receberao-reajuste-a-partir-de-maio\/"},"modified":"2012-05-22T06:05:31","modified_gmt":"2012-05-22T09:05:31","slug":"servidores-receberao-reajuste-a-partir-de-maio","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/goiasprev\/servidores-receberao-reajuste-a-partir-de-maio\/","title":{"rendered":"Servidores receber\u00e3o reajuste a partir de maio"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p>O governador Marconi Perillo sancionou a Lei da Data Base, que concede reajuste linear de 9,56% aos cerca de 82 mil servidores p&uacute;blicos efetivos, civis e militares, ativos e inativos, al&eacute;m de pensionistas e empregados da administra&ccedil;&atilde;o direta, aut&aacute;rquica e fundacional do Poder Executivo. O aumento come&ccedil;a a ser pago na folha do m&ecirc;s de maio, sendo 6,28% de 2012 e 3,28% referente a duas parcelas da reposi&ccedil;&atilde;o do ano passado. A diferen&ccedil;a remanescente da primeira parcela de 1,68%, retroativa a maio de 2011 ser&aacute; paga em uma folha complementar a ser quitada no dia 9.<\/p>\n<p>Na oportunidade foi anunciado ainda um conjunto de propostas de apoio ao servidor, que est&aacute; sendo formatado pela Secretaria de Gest&atilde;o e Planejamento e deve ser apresentado no pr&oacute;ximo m&ecirc;s. &ldquo;Ser&aacute; um&nbsp; programa ancorado basicamente em projetos de habita&ccedil;&atilde;o, aux&iacute;lio-funeral e&nbsp;aux&iacute;lio creche, al&eacute;m do lan&ccedil;amento de um programa de capacita&ccedil;&atilde;o dos servidores&rdquo;, adiantou o secret&aacute;rio Giuseppe Vecci, ao garantir que agora os servidores p&uacute;blicos ter&atilde;o a data-base todo ano e at&eacute; 2014 receber&atilde;o todas as diferen&ccedil;as relativas &agrave; data-base de 2011. <\/p>\n<p>O governador Marconi Perillo, por sua vez, lembrou que o servidor vai comemorar o dia do trabalhador com a not&iacute;cia do aumento e o sal&aacute;rio na conta, j&aacute; que o pagamento ser&aacute; depositado nesta sexta-feira. &ldquo;No meu segundo governo, em 2006, institu&iacute;mos a lei da data-base para os servidores, que no governo passado n&atilde;o foi cumprida. Agora estamos resgatando esse compromisso com os servidores. Volto a garantir que nesse governo a prioridade &eacute; com o pagamento dos servidores&rdquo;, destacou. <\/p>\n<p>Para o presidente da Uni&atilde;o Goiana de Policiais Civis, Ademar Nunes, o reajuste &eacute; o resgate de um compromisso. &ldquo;Embora seja constitucional, o servidor muitas vezes pensa que &eacute; uma obriga&ccedil;&atilde;o do Governo, no entanto depende de uma vontade pol&iacute;tica e por isso somos gratos&rdquo;, declarou durante a solenidade de san&ccedil;&atilde;o da lei. O presidente do Sindip&uacute;blico, Dom&iacute;cio Lima Cardoso, considerou o dia importante para a categoria e disse&nbsp; esperar que continue o di&aacute;logo aberto e fraterno entre o Governo e os representantes dos servidores. &ldquo;Dessa forma vamos poder garantir melhores condi&ccedil;&otilde;es de trabalho para a categoria e um melhor servi&ccedil;o a&agrave;sociedade&rdquo;. <\/p>\n<p>O reajuste salarial linear deve gerar um impacto de R$ 400 milh&otilde;es por ano na folha de pagamento do Estado. De acordo com Vecci, se somado ao aumento concedido aos professores e o b&ocirc;nus para os servidores da Sa&uacute;de, o impacto anual na folha pode chegar a R$ 950 milh&otilde;es.<\/p>\n<p>FONTE: GOI&Aacute;S AGORA<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Marconi Perillo sancionou a Lei da Data Base, que concede reajuste linear de 9,56% aos cerca de 82 mil servidores p&uacute;blicos efetivos, civis e militares, ativos e inativos, al&eacute;m de pensionistas e empregados da administra&ccedil;&atilde;o direta, aut&aacute;rquica e fundacional do Poder Executivo. O aumento come&ccedil;a a ser pago na folha do m&ecirc;s de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2300","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/goiasprev\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/goiasprev\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"O governador Marconi Perillo sancionou a Lei da Data Base, que concede reajuste linear de 9,56% aos cerca de 82 mil servidores p&uacute;blicos efetivos, civis e militares, ativos e inativos, al&eacute;m de pensionistas e empregados da administra&ccedil;&atilde;o direta, aut&aacute;rquica e fundacional do Poder Executivo. O aumento come&ccedil;a a ser pago na folha do m&ecirc;s de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/2300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/comments?post=2300"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/posts\/2300\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/media?parent=2300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/categories?post=2300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/goiasprev\/wp-json\/wp\/v2\/tags?post=2300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}