{"id":77484,"date":"2026-05-26T14:51:47","date_gmt":"2026-05-26T17:51:47","guid":{"rendered":"https:\/\/goias.gov.br\/esporte\/historico-do-cargo-superintendente-de-seguranca-e-infraestrutura-esportiva\/"},"modified":"2026-05-26T14:51:47","modified_gmt":"2026-05-26T17:51:47","slug":"historico-do-cargo-superintendente-de-seguranca-e-infraestrutura-esportiva","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/esporte\/historico-do-cargo-superintendente-de-seguranca-e-infraestrutura-esportiva\/","title":{"rendered":"Hist\u00f3rico do Cargo Superintendente de Seguran\u00e7a e Infraestrutura Esportiva"},"content":{"rendered":"<div class=\"accordion\" id=\"accordionExample\">\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-0'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-0' aria-expanded='false' aria-controls='collapse-0' style='border: none; background-color: transparent;'><br \/>\n                        NILTON CEZAR MOREIRA: de: 01-04-2024 at\u00e9 06-02-2026<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-0' class='accordion-collapse collapse' aria-labelledby='heading-0' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" data-args=\"0b5a9043d0339961369ef84977a837a9a8af481d\" data-js-args=\"{&quot;debug&quot;:null}\" data-r34icsym=\"202607\" data-view-is-list-long=\"0\" data-view-is-list-style=\"0\" data-view=\"month\" id=\"historico-agenda-autoridades\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-1'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-1' aria-expanded='false' aria-controls='collapse-1' style='border: none; background-color: transparent;'><br \/>\n                        RUDSON ROSA GUERRA: de: 06-02-2026 at\u00e9 09-02-2026<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-1' class='accordion-collapse collapse' aria-labelledby='heading-1' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" data-args=\"60aa6a6e79063bc87b3c0f6dbe102e4ce63aa9e6\" data-js-args=\"{&quot;debug&quot;:null}\" data-r34icsym=\"202607\" data-view-is-list-long=\"0\" data-view-is-list-style=\"0\" data-view=\"month\" id=\"historico-agenda-autoridades\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-2'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-2' aria-expanded='false' aria-controls='collapse-2' style='border: none; background-color: transparent;'><br \/>\n                        RUDSON ROSA GUERRA: de: 06-02-2026 at\u00e9 09-02-2026<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-2' class='accordion-collapse collapse' aria-labelledby='heading-2' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" data-args=\"60aa6a6e79063bc87b3c0f6dbe102e4ce63aa9e6\" data-js-args=\"{&quot;debug&quot;:null}\" data-r34icsym=\"202607\" data-view-is-list-long=\"0\" data-view-is-list-style=\"0\" data-view=\"month\" id=\"historico-agenda-autoridades\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<style>\n        .accordion-button:hover {\n            background-color: #f8f9fa; \/* Cor cinza claro *\/\n            color: #6c757d; \/* Cor cinza do texto *\/\n        }\n        <\/style>\n","protected":false},"excerpt":{"rendered":"<p>NILTON CEZAR MOREIRA: de: 01-04-2024 at\u00e9 06-02-2026 RUDSON ROSA GUERRA: de: 06-02-2026 at\u00e9 09-02-2026 RUDSON ROSA GUERRA: de: 06-02-2026 at\u00e9 09-02-2026<\/p>\n","protected":false},"author":423,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-77484","post","type-post","status-publish","format-standard","hentry","category-historico-de-agenda"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"igorpereira","author_link":"https:\/\/goias.gov.br\/esporte\/author\/igorpereira\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/esporte\/categoria\/historico-de-agenda\/\" rel=\"category tag\">historico-de-agenda<\/a>","rttpg_excerpt":"NILTON CEZAR MOREIRA: de: 01-04-2024 at\u00e9 06-02-2026 RUDSON ROSA GUERRA: de: 06-02-2026 at\u00e9 09-02-2026 RUDSON ROSA GUERRA: de: 06-02-2026 at\u00e9 09-02-2026","_links":{"self":[{"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/posts\/77484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/users\/423"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/comments?post=77484"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/posts\/77484\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/media?parent=77484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/categories?post=77484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/esporte\/wp-json\/wp\/v2\/tags?post=77484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}