{"id":9560,"date":"2017-12-08T09:12:20","date_gmt":"2017-12-08T11:12:20","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/servidor-da-sest-sus-e-eleito-o-melhor-arbitro-assistente-do-campeonato-brasileiro-2017\/"},"modified":"2017-12-08T09:12:20","modified_gmt":"2017-12-08T11:12:20","slug":"servidor-da-sest-sus-e-eleito-o-melhor-arbitro-assistente-do-campeonato-brasileiro-2017","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/escoladesaude\/servidor-da-sest-sus-e-eleito-o-melhor-arbitro-assistente-do-campeonato-brasileiro-2017\/","title":{"rendered":"Servidor da SEST-SUS \u00e9 eleito o melhor \u00e1rbitro assistente do Campeonato Brasileiro 2017"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9559\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/12\/servidor-da-sest-sus-e-eleito-melhor-arbitro-assistente-dde.jpg\" alt=\"\" width=\"550\" height=\"366\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>O servidor Bruno Pires, aqui da Superintend&ecirc;ncia de Educa&ccedil;&atilde;o em Sa&uacute;de e Trabalho para o SUS, provou que &eacute; bom de servi&ccedil;o n&atilde;o s&oacute; aqui na SEST-SUS. &Eacute; que no &uacute;ltimo dia 04 de dezembro ele foi eleito o melhor &aacute;rbitro assistente do Campeonato Brasileiro S&eacute;rie A de 2017. A premia&ccedil;&atilde;o foi realizada na sede da Confedera&ccedil;&atilde;o Brasileira de Futebol, no Rio de Janeiro.<\/p>\n<p>&nbsp;Natural de Bela Vista de Goi&aacute;s, Bruno tem 32 anos de idade e se formou no curso de arbitragem em 2009 J&aacute; no ano seguinte atuou em sua primeira partida profissional. Em 2012 entrou no quadro de arbitragem da CBF e em Dezembro de 2015 foi integrado &agrave; Federa&ccedil;&atilde;o Internacional de Futebol (FIFA).<\/p>\n<p>&nbsp;Aqui na superintend&ecirc;ncia ele tamb&eacute;m &eacute; muito elogiado por seu trabalho. Servidor efetivo do Estado de Goi&aacute;s desde 2010, Bruno &eacute; Analista de Sa&uacute;de e faz parte da equipe de execu&ccedil;&atilde;o de Eventos desde 2013. &ldquo;&Eacute; uma vida corrida, mas d&aacute; pra conciliar. Fa&ccedil;o o que gosto e conto sempre com o apoio dos colegas de trabalho que entendem minha rotina&rdquo;, afirma o servidor, que recebeu os cumprimentos da Dra Rafaela Veronezi ap&oacute;s a premia&ccedil;&atilde;o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; O servidor Bruno Pires, aqui da Superintend&ecirc;ncia de Educa&ccedil;&atilde;o em Sa&uacute;de e Trabalho para o SUS, provou que &eacute; bom de servi&ccedil;o n&atilde;o s&oacute; aqui na SEST-SUS. &Eacute; que no &uacute;ltimo dia 04 de dezembro ele foi eleito o melhor &aacute;rbitro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[13],"tags":[],"class_list":["post-9560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vigilancia-em-saude"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"wagner.viana","author_link":"https:\/\/goias.gov.br\/escoladesaude\/author\/wagner-viana\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/escoladesaude\/categoria\/vigilancia-em-saude\/\" rel=\"category tag\">Vigil\u00e2ncia em Sa\u00fade<\/a>","rttpg_excerpt":"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; O servidor Bruno Pires, aqui da Superintend&ecirc;ncia de Educa&ccedil;&atilde;o em Sa&uacute;de e Trabalho para o SUS, provou que &eacute; bom de servi&ccedil;o n&atilde;o s&oacute; aqui na SEST-SUS. &Eacute; que no &uacute;ltimo dia 04 de dezembro ele foi eleito o melhor &aacute;rbitro&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/posts\/9560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/comments?post=9560"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/posts\/9560\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/media?parent=9560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/categories?post=9560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/tags?post=9560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}