{"id":204481,"date":"2026-08-11T08:58:34","date_gmt":"2026-08-11T11:58:34","guid":{"rendered":"https:\/\/goias.gov.br\/escoladesaude\/?page_id=204481"},"modified":"2026-08-11T11:23:01","modified_gmt":"2026-08-11T14:23:01","slug":"lideranca-estrategica-cursos","status":"publish","type":"page","link":"https:\/\/goias.gov.br\/escoladesaude\/lideranca-estrategica-cursos\/","title":{"rendered":"Lideran\u00e7a Estrat\u00e9gica &#8211; cursos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"204481\" class=\"elementor elementor-204481\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19c29dce e-con e-atomic-element e-flexbox-base e-19c29dce-8d1f896 \" data-id=\"19c29dce\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"19c29dce\">\n    <div class=\"elementor-element elementor-element-11e0f3a0 e-con e-atomic-element e-flexbox-base e-11e0f3a0-9cc1c58 \" data-id=\"11e0f3a0\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"11e0f3a0\">\n    \t\t\t<img fetchpriority=\"high\" decoding=\"async\" class=\"e-image-base e-439717cd-d8ae2be\" data-interaction-id=\"439717cd\" id=\"204486\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-55-300x203.png\" width=\"300\" height=\"203\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-55-300x203.png 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-55.png 365w\" alt=\"\"\/>\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-68605b3d e-con e-atomic-element e-flexbox-base e-68605b3d-7e630f7 \" data-id=\"68605b3d\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"68605b3d\">\n    \t\t\t<img decoding=\"async\" class=\"e-image-base e-607f45f-8a6bbe0\" data-interaction-id=\"607f45f\" id=\"204488\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg\" width=\"300\" height=\"91\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images.jpg 407w\" alt=\"\"\/>\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-94a8b9c e-con e-atomic-element e-flexbox-base e-94a8b9c-1a741df \" data-id=\"94a8b9c\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"94a8b9c\">\n    <div class=\"elementor-element elementor-element-7dfe7695 e-con e-atomic-element e-flexbox-base e-7dfe7695-d252305 \" data-id=\"7dfe7695\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"7dfe7695\">\n    \t\t<div class=\"elementor-element elementor-element-2090c6b2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2090c6b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.154a9d5cfd5cf880_259\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.59a13bd48295c7d_12\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_167\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Facilita\u00e7\u00e3o de Reuni\u00f5es, Times e Workshops no Ambiente Online<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.c3b1d75f3fac136_169\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Voc\u00ea quer adquirir conhecimentos para conduzir times online? O seu desenvolvimento \u00e9 fundamental para seu desempenho no contexto organizacional p\u00fablico e privado. Venha conhecer din\u00e2micas e recursos de facilita\u00e7\u00e3o, al\u00e9m de ferramentas e plataformas que viabilizam as intera\u00e7\u00f5es remotas e que podem tornar os encontros mais interessantes e produtivos. Inscreva-se agora e n\u00e3o perca essa oportunidade.\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a class=\"XqQF9c\" href=\"https:\/\/www.escolavirtual.gov.br\/curso\/538\" target=\"_blank\" rel=\"noopener\"><span class=\"C9DxTc aw5Odc \">https:\/\/www.escolavirtual.gov.br\/curso\/538<\/span><\/a><span class=\"C9DxTc \">\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 1: Jornada de Conhecimento;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 2: Jornada Pr\u00e1tica e Ferramental.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-70f92ca9 e-con e-atomic-element e-flexbox-base e-70f92ca9-a6a54dd \" data-id=\"70f92ca9\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"70f92ca9\">\n    \t\t<div class=\"elementor-element elementor-element-7687cdb1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7687cdb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_106\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\" style=\"text-align: justify;\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_76\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_95\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Implementa\u00e7\u00e3o do Modelo de Governan\u00e7a e Gest\u00e3o P\u00fablica<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.c3b1d75f3fac136_97\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Capacitar os participantes a implementar o Modelo Gestaopublicagov.br, garantindo a compreens\u00e3o conceitual s\u00f3lida e capacidade de realizar a primeira aplica\u00e7\u00e3o do Instrumento de Maturidade de Governan\u00e7a e Gest\u00e3o (IMGG 100 pontos) sem erros estruturais.<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a href=\"https:\/\/goias.gov.br\/escoladegoverno\/implementacao-do-modelo-de-governanca-e-gestao-publica-gestaopublicagov-br-iniciante\/\"><span class=\"C9DxTc \">https:\/\/goias.gov.br\/escoladegoverno\/implementacao-do-modelo-de-governanca-e-gestao-publica-gestaopublicagov-br-iniciante\/<\/span><\/a><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conceitua\u00e7\u00e3o e fundamenta\u00e7\u00e3o legal.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Evolu\u00e7\u00e3o e prop\u00f3sito do Gestaop\u00fablicagov.br.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Defini\u00e7\u00e3o de Governan\u00e7a e Gest\u00e3o.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Do ciclo de melhoria ao IMGG<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Requisitos de Certifica\u00e7\u00e3o.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Avalia\u00e7\u00e3o dos crit\u00e9rios.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Atividade, pr\u00e1tica de gest\u00e3o e processo.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Erros comuns na aplica\u00e7\u00e3o do IMGG.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.1df5b4fd44e252d_78\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\">\u00a0<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-c0fcb9e e-con e-atomic-element e-flexbox-base e-c0fcb9e-f8f6bb9 \" data-id=\"c0fcb9e\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"c0fcb9e\">\n    <div class=\"elementor-element elementor-element-151ac58e e-con e-atomic-element e-flexbox-base e-151ac58e-b4a1184 \" data-id=\"151ac58e\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"151ac58e\">\n    \t\t\t<img decoding=\"async\" class=\"e-image-base e-5469b75b-bf289a0\" data-interaction-id=\"5469b75b\" id=\"204488\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg\" width=\"300\" height=\"91\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images.jpg 407w\" alt=\"\"\/>\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-53c1a838 e-con e-atomic-element e-flexbox-base e-53c1a838-d651766 \" data-id=\"53c1a838\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"53c1a838\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-7bd2a64e-eddf86f\" data-interaction-id=\"7bd2a64e\" id=\"204488\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg\" width=\"300\" height=\"91\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images.jpg 407w\" alt=\"\"\/>\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-2e90b9ec e-con e-atomic-element e-flexbox-base e-2e90b9ec-ee757db \" data-id=\"2e90b9ec\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"2e90b9ec\">\n    <div class=\"elementor-element elementor-element-2f5d9f17 e-con e-atomic-element e-flexbox-base e-2f5d9f17-620ef4b \" data-id=\"2f5d9f17\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"2f5d9f17\">\n    \t\t<div class=\"elementor-element elementor-element-c95c09c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c95c09c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.154a9d5cfd5cf880_259\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_84\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_92\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_62\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span style=\"color: #000000;\"><span class=\"jgG6ef C9DxTc \">I<\/span><span class=\"jgG6ef C9DxTc \">ndicadores de Desempenho<\/span><\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.33f787cd19efe78e_64\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \"><span style=\"color: #000000;\">Entender os conceitos necess\u00e1rios para a constru\u00e7\u00e3o de indicadores de desempenho, contribuindo para a forma\u00e7\u00e3o de um sistema de medi\u00e7\u00e3o de desempenho na administra\u00e7\u00e3o p\u00fablica estadual<\/span>\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a href=\"https:\/\/goias.gov.br\/escoladegoverno\/indicadores-de-desempenho-ead\/\"><span class=\"C9DxTc \">https:\/\/goias.gov.br\/escoladegoverno\/indicadores-de-desempenho-ead\/<\/span><\/a><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conceitos fundamentais;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Vis\u00e3o geral do uso de indicadores de desempenho;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Propriedades;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Constru\u00e7\u00e3o de indicadores de desempenho;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Utiliza\u00e7\u00e3o do Canvas para a cria\u00e7\u00e3o de indicadores;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Indicadores para monitorar o plano de a\u00e7\u00e3o;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Crit\u00e9rios para estabelecimento de metas;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">An\u00e1lise de resultados;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Classifica\u00e7\u00e3o de Indicadores.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-5294b09f e-con e-atomic-element e-flexbox-base e-5294b09f-225581a \" data-id=\"5294b09f\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"5294b09f\">\n    \t\t<div class=\"elementor-element elementor-element-1c73dd57 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1c73dd57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_106\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\" style=\"text-align: justify;\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_146\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_51\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span style=\"color: #000000;\"><span class=\"jgG6ef C9DxTc \">I<\/span><span class=\"jgG6ef C9DxTc \">ntelig\u00eancia Artificial e Ferramentas Generativas<\/span><\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.33f787cd19efe78e_53\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Capacitar servidores p\u00fablicos estaduais na compreens\u00e3o dos conceitos fundamentais de Intelig\u00eancia Artificial e Ferramentas Generativas, promovendo a aplica\u00e7\u00e3o dessas tecnologias em suas atividades rotineiras para otimizar processos, melhorar a efici\u00eancia operacional e fomentar a inova\u00e7\u00e3o no setor p\u00fablico.\u00a0<\/span><\/p><a href=\"https:\/\/goias.gov.br\/escoladegoverno\/inteligencia-artificial-e-ferramentas-generativas\/\">https:\/\/goias.gov.br\/escoladegoverno\/inteligencia-artificial-e-ferramentas-generativas\/<\/a><br \/><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Introdu\u00e7\u00e3o \u00e0 Intelig\u00eancia Artifical e Ferramentas Generativas.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Ferramentas Generativas e Cria\u00e7\u00e3o de Prompts.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Aplica\u00e7\u00f5es Pr\u00e1ticas de Intelig\u00eancia Artifical.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Instru\u00e7\u00f5es Personalizadas e An\u00e1lise Especializada.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Futuro da Intelig\u00eancia Artifical e Inova\u00e7\u00e3o no Servi\u00e7o P\u00fablico.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-c3d4dbb e-con e-atomic-element e-flexbox-base e-c3d4dbb-c21faa2 \" data-id=\"c3d4dbb\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"c3d4dbb\">\n    <div class=\"elementor-element elementor-element-127da72 e-con e-atomic-element e-flexbox-base e-127da72-8b707f9 \" data-id=\"127da72\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"127da72\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-594082e-c61e3bf\" data-interaction-id=\"594082e\" id=\"204488\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg\" width=\"300\" height=\"91\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images.jpg 407w\" alt=\"\"\/>\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-fe8285f e-con e-atomic-element e-flexbox-base e-fe8285f-7e81024 \" data-id=\"fe8285f\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"fe8285f\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-38f00ef-3101731\" data-interaction-id=\"38f00ef\" id=\"204175\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-300x156.jpg\" width=\"300\" height=\"156\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-300x156.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-768x400.jpg 768w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed.jpg 800w\" alt=\"\"\/>\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-747be6f e-con e-atomic-element e-flexbox-base e-747be6f-9ffddba \" data-id=\"747be6f\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"747be6f\">\n    <div class=\"elementor-element elementor-element-e52b492 e-con e-atomic-element e-flexbox-base e-e52b492-730c8ac \" data-id=\"e52b492\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"e52b492\">\n    \t\t<div class=\"elementor-element elementor-element-fca1816 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fca1816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.154a9d5cfd5cf880_259\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_84\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_92\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_62\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Governan\u00e7a Corporativa para Estatais<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.33f787cd19efe78e_75\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Proporcionar ao aluno conhecimentos sobre os principais aspectos da Governan\u00e7a Corporativa para Estatais, discutir os crit\u00e9rios e assuntos que comumente s\u00e3o abordados na pr\u00e1tica, bem como pontos de aten\u00e7\u00e3o em rela\u00e7\u00e3o aos \u00f3rg\u00e3os de controle, para que a atua\u00e7\u00e3o em temas relacionados ao assunto possa refletir aos aspectos legais e jurisprudenciais, com o prop\u00f3sito de evitar as ressalvas dos \u00f3rg\u00e3os de controles e consequentemente oportunizar maior precis\u00e3o t\u00e9cnica na atua\u00e7\u00e3o.\u00a0<\/span><\/p><p dir=\"ltr\"><a href=\"https:\/\/goias.gov.br\/escoladegoverno\/governanca-corporativa-para-estatais\/\">Acesse aqui<\/a><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a0Contextualiza\u00e7\u00e3o e o cen\u00e1rio da\u00a0 Governan\u00e7a Corporativa para Estatais.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">O Estado como controlador, Interesse p\u00fablico e desempenho econ\u00f4mico.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Melhores Pr\u00e1ticas de Governan\u00e7a para as Estatais.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Lei Anticorrup\u00e7\u00e3o e seus Impactos.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00c9tica e Integridade.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Melhores Pr\u00e1ticas para o Conselho de Administra\u00e7\u00e3o \/ Deliberativo.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Melhores Pr\u00e1ticas para o Conselho Fiscal.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Legisla\u00e7\u00e3o societ\u00e1ria e de mercado de capitais.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-a83e0a3 e-con e-atomic-element e-flexbox-base e-a83e0a3-8596805 \" data-id=\"a83e0a3\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"a83e0a3\">\n    \t\t<div class=\"elementor-element elementor-element-49dbe38 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"49dbe38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_106\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\" style=\"text-align: justify;\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_146\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_51\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Gest\u00e3o da Mudan\u00e7a<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.c3b1d75f3fac136_75\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Gerencie de forma eficaz as mudan\u00e7as do seu contexto de trabalho. Neste curso, voc\u00ea ter\u00e1 acesso aos princ\u00edpios de Gest\u00e3o de Mudan\u00e7as Organizacionais e ser\u00e1 orientado como impulsionar os resultados organizacionais.\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a class=\"XqQF9c\" href=\"https:\/\/suap.enap.gov.br\/vitrine\/curso\/2057\/\" target=\"_blank\" rel=\"noopener\"><span class=\"C9DxTc aw5Odc \">https:\/\/suap.enap.gov.br\/vitrine\/curso\/2057\/<\/span><\/a><span class=\"C9DxTc \">\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Principais t\u00f3picos<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Gest\u00e3o da mudan\u00e7a;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Papel do agente de mudan\u00e7a;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Negocia\u00e7\u00e3o e Conflitos;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Capacidade versus Demanda;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Maturidade para Mudan\u00e7a.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-4379f9b e-con e-atomic-element e-flexbox-base e-4379f9b-095aedc \" data-id=\"4379f9b\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"4379f9b\">\n    <div class=\"elementor-element elementor-element-c5554b5 e-con e-atomic-element e-flexbox-base e-c5554b5-938c3df \" data-id=\"c5554b5\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"c5554b5\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-3a8617a-c524057\" data-interaction-id=\"3a8617a\" id=\"204488\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg\" width=\"300\" height=\"91\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images.jpg 407w\" alt=\"\"\/>\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-da81d0b e-con e-atomic-element e-flexbox-base e-da81d0b-f0c9877 \" data-id=\"da81d0b\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"da81d0b\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-eb87d4b-bd50074\" data-interaction-id=\"eb87d4b\" id=\"204488\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg\" width=\"300\" height=\"91\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images.jpg 407w\" alt=\"\"\/>\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-8e9d692 e-con e-atomic-element e-flexbox-base e-8e9d692-5109059 \" data-id=\"8e9d692\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"8e9d692\">\n    <div class=\"elementor-element elementor-element-21c61da e-con e-atomic-element e-flexbox-base e-21c61da-e164df4 \" data-id=\"21c61da\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"21c61da\">\n    \t\t<div class=\"elementor-element elementor-element-028cd42 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"028cd42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.154a9d5cfd5cf880_259\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_84\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_92\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_62\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Fundamentos de Lideran\u00e7a P\u00fablica<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.33f787cd19efe78e_10\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \"><span style=\"color: #000000;\">Desenvolver o autoconhecimento, reconhecimento de for\u00e7as e prop\u00f3sito, com foco na intelig\u00eancia emocional, empatia, autorresponsabilidade e autodisciplina; desenvolver habilidades de comunica\u00e7\u00e3o consciente, gest\u00e3o relacional e negocia\u00e7\u00e3o com base em confian\u00e7a e desenvolver o uso inteligente do tempo, an\u00e1lise de dados e vis\u00e3o de futuro, para a entrega efetiva de valor p\u00fablico.<\/span>\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a class=\"XqQF9c\" href=\"https:\/\/goias.gov.br\/escoladegoverno\/fundamentos-da-lideranca-publica\/\" target=\"_blank\" rel=\"noopener\"><span class=\"C9DxTc aw5Odc \">https:\/\/goias.gov.br\/escoladegoverno\/fundamentos-da-lideranca-publica\/<\/span><\/a><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Quem sou eu na lideran\u00e7a?<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Intelig\u00eancia Emocional e intelig\u00eancia em Lideran\u00e7a.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Mapeamento de for\u00e7as, virtudes e valores.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Autodisciplina, autorresponsabilidade e prop\u00f3sito.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Comunica\u00e7\u00e3o do L\u00edder.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Comunica\u00e7\u00e3o Consciente e Escuta Ativa em M\u00faltiplos N\u00edveis.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Pr\u00e1ticas de Di\u00e1logo Estruturado e Media\u00e7\u00e3o Profissional.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Gest\u00e3o do tempo e entrega de valor p\u00fablico.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">An\u00e1lise dos Dados como ferramenta de Gest\u00e3o.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Lideran\u00e7a com adaptabilidade e vis\u00e3o de futuro.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-3806a7b e-con e-atomic-element e-flexbox-base e-3806a7b-c7a6e88 \" data-id=\"3806a7b\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"3806a7b\">\n    \t\t<div class=\"elementor-element elementor-element-1fca5a6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1fca5a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_106\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\" style=\"text-align: justify;\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_146\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_51\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_88\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Power BI para An\u00e1lise de dados -B\u00e1sico<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.33f787cd19efe78e_90\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conhecer a ferramenta Power BI, tratar e formatar dados e construir relat\u00f3rios e dashboards de qualidade, utilizando boas pr\u00e1ticas e conceitos de Business Intelligence (BI).\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/goias.gov.br\/escoladegoverno\/power-bi-para-analise-de-dados-basico\/\"><span class=\"C9DxTc \">https:\/\/goias.gov.br\/escoladegoverno\/power-bi-para-analise-de-dados-basico\/<\/span><\/a><\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Introdu\u00e7\u00e3o aos conceitos b\u00e1sicos de informa\u00e7\u00e3o, dados, Business Inteligence(BI), Data Warehouse, ETL e outros.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a0Introdu\u00e7\u00e3o aos principais conceitos, recursos e ferramentas do Power BI.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Primeiro projeto do curso: conectar a m\u00faltiplas fontes de dados, tratar e formatar os dados para criarmos relat\u00f3rios de qualidade.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Funcionalidades, recursos e ferramentas do Power query e Power BI.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Segundo projeto do curso: novas fontes de dados, novos recursos do Power Query e do Power BI.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Construindo relat\u00f3rios mais complexos com novos visuais.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Publica\u00e7\u00e3o de projeto na nuvem e suas particularidades.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a0Terceiro projeto do curso: novas fontes de dados, novas formas de visualizar os dados e novos recursos do Power Query e do Power BI.<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a0Utiliza\u00e7\u00e3o de temas dispon\u00edveis no Power BI e temas personalizados.\u00a0<\/span><\/p><\/li><\/ul><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-0f28ec8 e-con e-atomic-element e-flexbox-base e-0f28ec8-c35f0aa \" data-id=\"0f28ec8\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"0f28ec8\">\n    <div class=\"elementor-element elementor-element-702fd30 e-con e-atomic-element e-flexbox-base e-702fd30-78f2e87 \" data-id=\"702fd30\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"702fd30\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-2049917-0a6c3b4\" data-interaction-id=\"2049917\" id=\"204488\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg\" width=\"300\" height=\"91\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images-300x91.jpg 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/images.jpg 407w\" alt=\"\"\/>\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-30c72d8 e-con e-atomic-element e-flexbox-base e-30c72d8-4a7ff77 \" data-id=\"30c72d8\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"30c72d8\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-570b4c7-e246ca2\" data-interaction-id=\"570b4c7\" id=\"204485\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-56-300x199.png\" width=\"300\" height=\"199\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-56-300x199.png 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-56.png 514w\" alt=\"\"\/>\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-907161f e-con e-atomic-element e-flexbox-base e-907161f-ee42139 \" data-id=\"907161f\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"907161f\">\n    <div class=\"elementor-element elementor-element-eaa32f6 e-con e-atomic-element e-flexbox-base e-eaa32f6-2ce3e13 \" data-id=\"eaa32f6\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"eaa32f6\">\n    \t\t<div class=\"elementor-element elementor-element-55e34ab elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"55e34ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.154a9d5cfd5cf880_259\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_84\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_92\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_62\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_119\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Power BI para An\u00e1lise de dados &#8211; Avan\u00e7ado<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.33f787cd19efe78e_121\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conhecer a ferramenta Power BI e seus recursos mais avan\u00e7ados; aprender a carregar m\u00faltiplas fontes de dados e uso de banco de dados; construir relat\u00f3rios e dashboards de qualidade; criar projetos de alto n\u00edvel utilizando os recursos e funcionalidades do Power BI e aprofundar em conceitos e recursos mais avan\u00e7ados do Power BI, Power BI Servi\u00e7o, DAX, dentre outros recursos.\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a href=\"https:\/\/goias.gov.br\/escoladegoverno\/power-bi-para-analise-de-dados-avancado\/\"><span class=\"C9DxTc \">https:\/\/goias.gov.br\/escoladegoverno\/power-bi-para-analise-de-dados-avancado\/<\/span><\/a><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Apresenta\u00e7\u00e3o do curso;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Revis\u00e3o dos conceitos b\u00e1sicos de BI;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Prepara\u00e7\u00e3o do ambiente para o curso. SGBD que ser\u00e1 utilizado e configura\u00e7\u00e3o das ferramentas necess\u00e1rias;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Primeiro Projeto \u2013 conex\u00f5es ao SGBD instalado e utiliza\u00e7\u00e3o de dados j\u00e1 dispon\u00edveis atrav\u00e9s do ETL apresentado;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Segundo Projeto \u2013 conex\u00f5es ao SGBD instalado e utiliza\u00e7\u00e3o de uma nova fonte de dados j\u00e1 dispon\u00edveis atrav\u00e9s do ETL apresentado;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Apresenta\u00e7\u00e3o de recursos avan\u00e7ados do Power BI e Power BI Servi\u00e7o e como configurar melhor o ambiente da nuvem;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">Recapitula\u00e7\u00e3o das atividade feitas e sugest\u00f5es para evolu\u00e7\u00e3o do aprendizado.\u00a0<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-9bd7c5b e-con e-atomic-element e-flexbox-base e-9bd7c5b-fe20b77 \" data-id=\"9bd7c5b\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"9bd7c5b\">\n    \t\t<div class=\"elementor-element elementor-element-b12c5dc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b12c5dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_106\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\" style=\"text-align: justify;\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_146\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_51\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_88\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.4cdc8775bec4b176_248\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Cultura Organizacional \u00c1gil Aplicada ao Contexto P\u00fablico<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.4cdc8775bec4b176_250\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span style=\"color: #000000;\"><span class=\"C9DxTc \">Construa uma cultura organizacional \u00e1gil no setor p\u00fablico com estrat\u00e9gia e gest\u00e3o da mudan\u00e7a! O curso aborda a compreens\u00e3o da cultura organizacional, a cultura \u00e1gil e sua aplica\u00e7\u00e3o e a gest\u00e3o da mudan\u00e7a para a transi\u00e7\u00e3o. Destinado a gestores, l\u00edderes de transforma\u00e7\u00e3o e analistas que buscam cultivar uma cultura de agilidade nas organiza\u00e7\u00f5es p\u00fablicas, promovendo mentalidade de melhoria cont\u00ednua, colabora\u00e7\u00e3o e adapta\u00e7\u00e3o r\u00e1pida \u00e0s mudan\u00e7as do ambiente.<\/span><span class=\"C9DxTc \">\u00a0<\/span><\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a class=\"XqQF9c\" href=\"https:\/\/www.escolavirtual.gov.br\/curso\/525\" target=\"_blank\" rel=\"noopener\"><span class=\"C9DxTc aw5Odc \">https:\/\/www.escolavirtual.gov.br\/curso\/525<\/span><\/a><span class=\"C9DxTc \">\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 1: Compreendendo a Cultura Organizacional;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 2: A Cultura \u00c1gil e sua Aplica\u00e7\u00e3o ao Setor P\u00fablico;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 3: Gest\u00e3o de Mudan\u00e7a.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-00df74c e-con e-atomic-element e-flexbox-base e-00df74c-2c7ef20 \" data-id=\"00df74c\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"00df74c\">\n    <div class=\"elementor-element elementor-element-a1013c4 e-con e-atomic-element e-flexbox-base e-a1013c4-342fc31 \" data-id=\"a1013c4\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"a1013c4\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-00bf12a-41c80a9\" data-interaction-id=\"00bf12a\" id=\"204484\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-57-300x193.png\" width=\"300\" height=\"193\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-57-300x193.png 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-57.png 510w\" alt=\"\"\/>\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-3ca4a64 e-con e-atomic-element e-flexbox-base e-3ca4a64-6c9e2a5 \" data-id=\"3ca4a64\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"3ca4a64\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-541b8f0-3cae242\" data-interaction-id=\"541b8f0\" id=\"204483\" src=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-58-300x211.png\" width=\"300\" height=\"211\" srcset=\"https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-58-300x211.png 300w, https:\/\/goias.gov.br\/escoladesaude\/wp-content\/uploads\/sites\/59\/2026\/08\/unnamed-58.png 329w\" alt=\"\"\/>\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-0886bc2 e-con e-atomic-element e-flexbox-base e-0886bc2-58b1ba1 \" data-id=\"0886bc2\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"0886bc2\">\n    <div class=\"elementor-element elementor-element-b69b2e9 e-con e-atomic-element e-flexbox-base e-b69b2e9-e1e59c8 \" data-id=\"b69b2e9\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"b69b2e9\">\n    \t\t<div class=\"elementor-element elementor-element-9e7eb42 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9e7eb42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.154a9d5cfd5cf880_259\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_84\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_92\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_62\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_119\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.6fb2a33ad5589590_25\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Gest\u00e3o da Estrat\u00e9gia com BSC &#8211; Fundamentos<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.6fb2a33ad5589590_27\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Implemente a Gest\u00e3o Estrat\u00e9gica com o Balanced Scorecard e transforme a estrat\u00e9gia em resultados! O curso aborda a evolu\u00e7\u00e3o do planejamento estrat\u00e9gico, os fundamentos do BSC, a constru\u00e7\u00e3o do Mapa Estrat\u00e9gico e a implementa\u00e7\u00e3o e monitoramento da estrat\u00e9gia. Destinado a gestores, analistas e l\u00edderes que desejam utilizar o BSC como ferramenta para traduzir a vis\u00e3o estrat\u00e9gica em objetivos, indicadores e iniciativas mensur\u00e1veis e acompanh\u00e1veis.\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a class=\"XqQF9c\" href=\"https:\/\/www.escolavirtual.gov.br\/curso\/103\" target=\"_blank\" rel=\"noopener\"><span class=\"C9DxTc aw5Odc \">https:\/\/www.escolavirtual.gov.br\/curso\/103<\/span><\/a><span class=\"C9DxTc \">\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><strong><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/strong><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><strong><span class=\"C9DxTc \" style=\"color: #000000;\">1 Planejamento estrat\u00e9gico<\/span><\/strong><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a01.1 Conceito e evolu\u00e7\u00e3o nas organiza\u00e7\u00f5es<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a01.2 Planejamento em contexto de mudan\u00e7as<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a01.3 Fundamentos do planejamento estrat\u00e9gico<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a01.4 Gest\u00e3o estrat\u00e9gica como princ\u00edpio<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a01.5 Etapas do planejamento estrat\u00e9gico<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a01.6 Plano estrat\u00e9gico<\/span><\/p><\/li><\/ul><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><strong><span class=\"C9DxTc \" style=\"color: #000000;\">2 Balance Scorecard (BSC)<\/span><\/strong><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a02.1 M\u00e9todo<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a02.2 Perspectivas de desempenho<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a02.3 Benef\u00edcios e potencialidades<\/span><\/p><\/li><\/ul><\/li><\/ul><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><strong><span class=\"C9DxTc \" style=\"color: #000000;\">3 Gest\u00e3o do Plano<\/span><\/strong><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a03.1 Comit\u00ea de Gest\u00e3o Estrat\u00e9gica<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a03.2 Monitoramento do Plano<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">\u00a03.3 Avalia\u00e7\u00e3o e atualiza\u00e7\u00e3o do Plano<\/span><\/p><\/li><\/ul><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-1a511a4 e-con e-atomic-element e-flexbox-base e-1a511a4-9b159b6 \" data-id=\"1a511a4\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"1a511a4\">\n    \t\t<div class=\"elementor-element elementor-element-9360c9f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9360c9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_106\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\" style=\"text-align: justify;\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\" style=\"text-align: justify;\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_8\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.5a7102d3dda793b4_46\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.1df5b4fd44e252d_146\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_51\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_73\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.33f787cd19efe78e_88\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.4cdc8775bec4b176_248\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><div class=\"oKdM2c ZZyype Kzv0Me\"><div id=\"h.c3b1d75f3fac136_183\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec OjCsFc dmUFtb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><div class=\"CjVfdc\"><strong><span class=\"jgG6ef C9DxTc \" style=\"color: #000000;\">Lideran\u00e7a Estrat\u00e9gica com IA na Administra\u00e7\u00e3o P\u00fablica<\/span><\/strong><\/div><\/div><\/div><\/div><\/div><div class=\"oKdM2c ZZyype\"><div id=\"h.c3b1d75f3fac136_185\" class=\"hJDwNd-AhqUyc-Clt0zb Ft7HRd-AhqUyc-Clt0zb jXK9ad D2fZ2 zu5uec wHaque g5GTcb\"><div class=\"jXK9ad-SmKAyb\"><div class=\"tyJCtd mGzaTb Depvyb baZpAe\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span style=\"color: #000000;\"><span class=\"C9DxTc \">Lidere com intelig\u00eancia artificial e transforme a gest\u00e3o p\u00fablica! O curso aborda lideran\u00e7a p\u00fablica e IA, a IA como ferramenta estrat\u00e9gica para gestores, produtividade com IA na gest\u00e3o p\u00fablica, lideran\u00e7a e gest\u00e3o de equipes com IA e planejamento e aplica\u00e7\u00e3o de IA na administra\u00e7\u00e3o p\u00fablica. Destinado a l\u00edderes e gestores p\u00fablicos que desejam incorporar a IA \u00e0 sua estrat\u00e9gia de lideran\u00e7a e modernizar a entrega de resultados para a sociedade.<\/span><span class=\"C9DxTc \">\u00a0<\/span><\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><a class=\"XqQF9c\" href=\"https:\/\/www.escolavirtual.gov.br\/curso\/1498\" target=\"_blank\" rel=\"noopener\"><span class=\"C9DxTc aw5Odc \">https:\/\/www.escolavirtual.gov.br\/curso\/1498<\/span><\/a><span class=\"C9DxTc \">\u00a0<\/span><\/p><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\"><span class=\"C9DxTc \" style=\"color: #000000;\">Conte\u00fado Program\u00e1tico:<\/span><\/p><ul class=\"n8H08c UVNKR \"><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 1: Lideran\u00e7a P\u00fablica e IA: Contexto e Potencialidades;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 2: Intelig\u00eancia Artificial: Ferramenta Estrat\u00e9gica para L\u00edderes e Gestores;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 3: Produtividade com IA na Gest\u00e3o P\u00fablica;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 4: Lideran\u00e7a e Gest\u00e3o de Equipes com o uso da IA;<\/span><\/p><\/li><li class=\"zfr3Q TYR86d eD0Rn \" dir=\"ltr\"><p class=\"zfr3Q CDt4Ke \" dir=\"ltr\" role=\"presentation\"><span class=\"C9DxTc \" style=\"color: #000000;\">M\u00f3dulo 5: Planejamento e Aplica\u00e7\u00e3o de IA na Administra\u00e7\u00e3o P\u00fablica.<\/span><\/p><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Facilita\u00e7\u00e3o de Reuni\u00f5es, Times e Workshops no Ambiente Online Voc\u00ea quer adquirir conhecimentos para conduzir times online? O seu desenvolvimento \u00e9 fundamental para seu desempenho no contexto organizacional p\u00fablico e privado. Venha conhecer din\u00e2micas e recursos de facilita\u00e7\u00e3o, al\u00e9m de ferramentas e plataformas que viabilizam as intera\u00e7\u00f5es remotas e que podem tornar os encontros mais [&hellip;]<\/p>\n","protected":false},"author":584,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-204481","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"angelicaabadia","author_link":"https:\/\/goias.gov.br\/escoladesaude\/author\/angelicaabadia\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Facilita\u00e7\u00e3o de Reuni\u00f5es, Times e Workshops no Ambiente Online Voc\u00ea quer adquirir conhecimentos para conduzir times online? O seu desenvolvimento \u00e9 fundamental para seu desempenho no contexto organizacional p\u00fablico e privado. Venha conhecer din\u00e2micas e recursos de facilita\u00e7\u00e3o, al\u00e9m de ferramentas e plataformas que viabilizam as intera\u00e7\u00f5es remotas e que podem tornar os encontros mais&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/pages\/204481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/users\/584"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/comments?post=204481"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/pages\/204481\/revisions"}],"predecessor-version":[{"id":204552,"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/pages\/204481\/revisions\/204552"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/escoladesaude\/wp-json\/wp\/v2\/media?parent=204481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}