

{"id":340399,"date":"2025-03-12T16:02:16","date_gmt":"2025-03-12T19:02:16","guid":{"rendered":"https:\/\/goias.gov.br\/educacao\/?p=340399"},"modified":"2026-01-27T13:28:46","modified_gmt":"2026-01-27T16:28:46","slug":"mineiros-pedagogia","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/educacao\/mineiros-pedagogia\/","title":{"rendered":"Mineiros &#8211; Pedagogia"},"content":{"rendered":"\n<p>P\u00e1gina destinada \u00e0s postagens da sele\u00e7\u00e3o e contrata\u00e7\u00e3o tempor\u00e1ria de professores 2025<\/p>\n\n\n\n<div>\n        <h3 id=\"157021\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>LAGILSE PAES PEDROSA GUEDES<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>157021<\/b>, classificado em <b>1\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>ter\u00e7a-feira<\/b>, dia <b>15\/07\/2025<\/b>, \u00e0s <b>16:00<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"119347\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>ANGELA VANESSA CARVALHO MAGALHAES<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>119347<\/b>, classificado em <b>2\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>quinta-feira<\/b>, dia <b>17\/07\/2025<\/b>, \u00e0s <b>08:30<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"103245\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>VANIA DE PAULA ANEAS DA FONSECA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>103245<\/b>, classificado em <b>3\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>quinta-feira<\/b>, dia <b>17\/07\/2025<\/b>, \u00e0s <b>09:50<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"160222\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>RENATA DOS SANTOS<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>160222<\/b>, classificado em <b>4\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>quinta-feira<\/b>, dia <b>17\/07\/2025<\/b>, \u00e0s <b>10:10<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"120649\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>DEONICE RAFAEL DO NASCIMENTO ROCHA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>120649<\/b>, classificado em <b>5\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>18\/07\/2025<\/b>, \u00e0s <b>14:50<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"104803\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>MARILIA GABRIELA DE MOURA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>104803<\/b>, classificado em <b>6\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>18\/07\/2025<\/b>, \u00e0s <b>15:10<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"107210\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>DIRCE BIONDO DA SILVA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>107210<\/b>, classificado em <b>7\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>18\/07\/2025<\/b>, \u00e0s <b>15:30<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"103245\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>VANIA DE PAULA ANEAS DA FONSECA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>103245<\/b>, classificado em <b>3\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>ter\u00e7a-feira<\/b>, dia <b>22\/07\/2025<\/b>, \u00e0s <b>15:50<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"152006\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>ISABEL CRISTINA DADU NUNES<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>152006<\/b>, classificado em <b>8\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>ter\u00e7a-feira<\/b>, dia <b>22\/07\/2025<\/b>, \u00e0s <b>16:10<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"117853\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>EDUARDO MURILO FERNANDES DA MATA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>117853<\/b>, classificado em <b>9\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>ter\u00e7a-feira<\/b>, dia <b>22\/07\/2025<\/b>, \u00e0s <b>16:30<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"109831\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>IRIS RANCHEL CHERMONT NEGR\u00c3O<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>109831<\/b>, classificado em <b>10\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>segunda-feira<\/b>, dia <b>20\/10\/2025<\/b>, \u00e0s <b>08:10<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"143570\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>JOSIENE RIBEIRO DOS SANTOS<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>143570<\/b>, classificado em <b>11\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>ter\u00e7a-feira<\/b>, dia <b>21\/10\/2025<\/b>, \u00e0s <b>16:15<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"160489\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>ROSEMEIRE SILVA OLIVEIRA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>160489<\/b>, classificado em <b>12\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>quarta-feira<\/b>, dia <b>29\/10\/2025<\/b>, \u00e0s <b>15:30<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"123779\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>EOMAR CAMARGO CABRINI PONCHIO<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>123779<\/b>, classificado em <b>13\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>31\/10\/2025<\/b>, \u00e0s <b>09:05<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"103245\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>VANIA DE PAULA ANEAS DA FONSECA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>103245<\/b>, classificado em <b>3\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>quarta-feira<\/b>, dia <b>21\/01\/2026<\/b>, \u00e0s <b>10:20<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"117853\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>EDUARDO MURILO FERNANDES DA MATA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>117853<\/b>, classificado em <b>9\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>23\/01\/2026<\/b>, \u00e0s <b>09:35<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"92649\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>JANE RAFAELA DE JESUS<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>92649<\/b>, classificado em <b>14\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>segunda-feira<\/b>, dia <b>26\/01\/2026<\/b>, \u00e0s <b>14:00<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"112710\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>ALETIANE DIAS DA SILVA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>112710<\/b>, classificado em <b>15\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>ter\u00e7a-feira<\/b>, dia <b>27\/01\/2026<\/b>, \u00e0s <b>10:45<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n\n    <div>\n        <h3 id=\"104439\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>EUNICE BATISTA DOS SANTOS<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>104439<\/b>, classificado em <b>16\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>quarta-feira<\/b>, dia <b>28\/01\/2026<\/b>, \u00e0s <b>13:30<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n    \n\n","protected":false},"excerpt":{"rendered":"<p>P\u00e1gina destinada \u00e0s postagens da sele\u00e7\u00e3o e contrata\u00e7\u00e3o tempor\u00e1ria de professores 2025 CONVOCA\u00c7\u00c3O 2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024 ENTREVISTA A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, CONVOCA para a 2\u00aa fase do Processo Seletivo Simplificado, o candidato LAGILSE PAES PEDROSA GUEDES, [&hellip;]<\/p>\n","protected":false},"author":464,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-340399","post","type-post","status-publish","format-standard","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"hudsonoliveira","author_link":"https:\/\/goias.gov.br\/educacao\/author\/hudsonoliveira\/"},"rttpg_comment":0,"rttpg_category":"Sem categoria","rttpg_excerpt":"P\u00e1gina destinada \u00e0s postagens da sele\u00e7\u00e3o e contrata\u00e7\u00e3o tempor\u00e1ria de professores 2025 CONVOCA\u00c7\u00c3O 2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024 ENTREVISTA A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, CONVOCA para a 2\u00aa fase do Processo Seletivo Simplificado, o candidato LAGILSE PAES PEDROSA GUEDES,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/340399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/users\/464"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=340399"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/340399\/revisions"}],"predecessor-version":[{"id":665137,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/340399\/revisions\/665137"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=340399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/categories?post=340399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/tags?post=340399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}