

{"id":339973,"date":"2025-03-12T15:50:55","date_gmt":"2025-03-12T18:50:55","guid":{"rendered":"https:\/\/goias.gov.br\/educacao\/?p=339973"},"modified":"2025-08-28T14:06:02","modified_gmt":"2025-08-28T17:06:02","slug":"luziania-fisica","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/educacao\/luziania-fisica\/","title":{"rendered":"Luzi\u00e2nia &#8211; F\u00edsica"},"content":{"rendered":"\n<p>P\u00e1gina destinada \u00e0s postagens da sele\u00e7\u00e3o e contrata\u00e7\u00e3o tempor\u00e1ria de professores 2025<\/p>\n\n\n\n<div>\n        <h3 id=\"119258\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>FABRINE MOREIRA MAIA<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>119258<\/b>, classificado em <b>1\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>30\/05\/2025<\/b>, \u00e0s <b>14:20<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n<div>\n        <h3 id=\"139655\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>HELDER SANDY DA SILVA BASTOS<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>139655<\/b>, classificado em <b>2\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>08\/08\/2025<\/b>, \u00e0s <b>14:45<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n\n\n\n\n    <div>\n        <h3 id=\"99706\" align=\"center\"><strong>CONVOCA\u00c7\u00c3O<\/strong><\/h3>\n        <h4 align=\"center\">2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024<\/h4>\n        <pre style=\"text-align: center\">ENTREVISTA<\/pre>\n        <div style=\"text-align: justify\">\n            <p style=\"text-indent: 50px\">\n            A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, <b>CONVOCA<\/b> para a <b>2\u00aa fase<\/b> do Processo Seletivo Simplificado, o candidato <b>NEIDE DAIANA DE ALMEIDA WORREL<\/b>, inscri\u00e7\u00e3o n.\u00ba <b>99706<\/b>, classificado em <b>3\u00aa coloca\u00e7\u00e3o<\/b> da modalidade <b>Ampla Concorr\u00eancia<\/b>, visando cumprimento do item 10, do Edital n.\u00ba 020\/2024.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            Sendo assim, convoca o candidato acima, a comparecer \u00e0 entrevista on-line, por interm\u00e9dio de acesso ao link, que ser\u00e1 disponibilizada pelo email (verificar spam e lixo da caixa de entrada) cadastrado no portal do candidato, \u00e0 \u00e9poca da realiza\u00e7\u00e3o da inscri\u00e7\u00e3o, a ser realizada na <b>sexta-feira<\/b>, dia <b>29\/08\/2025<\/b>, \u00e0s <b>15:30<\/b> &#8211; Hor\u00e1rio de Bras\u00edlia.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            A presente convoca\u00e7\u00e3o justifica-se por necessidade de substitui\u00e7\u00e3o de servidor afastado, conforme disciplina o art. 208, da Lei n.\u00ba 13.909, de 25 de setembro de 2001 e possui prazo de <b>24 (vinte e quatro horas)<\/b>, a contar da publica\u00e7\u00e3o desta convoca\u00e7\u00e3o.\n            <\/p>\n            <p style=\"text-indent: 50px\">\n            N\u00e3o havendo nada mais a informar, encerra o expediente.\n            <\/p>\n        <\/div>\n        <br>\n        <p style=\"text-align: center;margin-top: 20px\">\n            <strong>SEDUC\/GO<\/strong><br>\n        <\/p>\n        <hr>\n    <\/div>\n    \n\n","protected":false},"excerpt":{"rendered":"<p>P\u00e1gina destinada \u00e0s postagens da sele\u00e7\u00e3o e contrata\u00e7\u00e3o tempor\u00e1ria de professores 2025 CONVOCA\u00c7\u00c3O 2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024 ENTREVISTA A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, CONVOCA para a 2\u00aa fase do Processo Seletivo Simplificado, o candidato FABRINE MOREIRA MAIA, inscri\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":464,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-339973","post","type-post","status-publish","format-standard","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"hudsonoliveira","author_link":"https:\/\/goias.gov.br\/educacao\/author\/hudsonoliveira\/"},"rttpg_comment":0,"rttpg_category":"Sem categoria","rttpg_excerpt":"P\u00e1gina destinada \u00e0s postagens da sele\u00e7\u00e3o e contrata\u00e7\u00e3o tempor\u00e1ria de professores 2025 CONVOCA\u00c7\u00c3O 2\u00aa FASE DO PROCESSO SELETIVO SIMPLIFICADO N.\u00ba 020\/2024 ENTREVISTA A Secretaria de Estado da Educa\u00e7\u00e3o, diante da aprova\u00e7\u00e3o na 1\u00aa Fase do Processo Seletivo Simplificado n.\u00ba 020\/2024, CONVOCA para a 2\u00aa fase do Processo Seletivo Simplificado, o candidato FABRINE MOREIRA MAIA, inscri\u00e7\u00e3o&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/339973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/users\/464"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=339973"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/339973\/revisions"}],"predecessor-version":[{"id":517356,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/339973\/revisions\/517356"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=339973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/categories?post=339973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/tags?post=339973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}