{"id":26903,"date":"2024-01-15T15:06:23","date_gmt":"2024-01-15T18:06:23","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/educacao\/?page_id=26903"},"modified":"2026-07-06T16:28:35","modified_gmt":"2026-07-06T19:28:35","slug":"novo-ensino-medio","status":"publish","type":"page","link":"https:\/\/goias.gov.br\/educacao\/novo-ensino-medio\/","title":{"rendered":"Novo Ensino M\u00e9dio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26903\" class=\"elementor elementor-26903\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d7217 e-con-full e-flex e-con e-parent\" data-id=\"e3d7217\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-033d994 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"033d994\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/goias.gov.br\/educacao\/wp-content\/uploads\/sites\/40\/2024\/10\/banner-1-2048x683.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-585d20d e-flex e-con-boxed e-con e-parent\" data-id=\"585d20d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee0322f elementor-widget elementor-widget-heading\" data-id=\"ee0322f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Novo Ensino M\u00e9dio: como vai funcionar em Goi\u00e1s a partir de 2024<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52f532c e-flex e-con-boxed e-con e-parent\" data-id=\"52f532c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a46a1e5 e-con-full e-flex e-con e-child\" data-id=\"a46a1e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9c54a5 elementor-widget elementor-widget-heading\" data-id=\"d9c54a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nova lei reestrutura o Ensino M\u00e9dio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5e531b elementor-widget elementor-widget-text-editor\" data-id=\"a5e531b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><h4><strong><span style=\"color: #ffcc00;\">Entenda as principais mudan\u00e7as<\/span> <\/strong><\/h4><p>A nova Pol\u00edtica Nacional de Ensino M\u00e9dio, institu\u00edda pela Lei n\u00ba 14.945\/2024, traz mudan\u00e7as significativas para essa etapa da Educa\u00e7\u00e3o no Brasil. Aprovada em 31 de julho de 2024, a lei altera a Lei de Diretrizes e Bases da Educa\u00e7\u00e3o Nacional (Lei n\u00ba 9.394\/1996) e revoga, parcialmente, a Lei n\u00ba 13.415\/2017, que estruturou a Reforma do Ensino M\u00e9dio.<\/p><p>O objetivo \u00e9 ajustar o curr\u00edculo e redistribuir a carga hor\u00e1ria destinada \u00e0 forma\u00e7\u00e3o dos estudantes, tornando o Ensino M\u00e9dio mais abrangente e alinhado \u00e0s necessidades contempor\u00e2neas. A implementa\u00e7\u00e3o da nova legisla\u00e7\u00e3o ser\u00e1 realizada de forma gradativa, a partir de 2025.<\/p><p><strong><span style=\"color: #ffcc00;\">Qual \u00e9 a carga hor\u00e1ria ?<\/span><\/strong><\/p><h4><strong><span style=\"color: #ffcc00;\">Forma\u00e7\u00e3o Geral B\u00e1sica (FGB) Mais Horas<\/span> <\/strong><\/h4><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-191b90c e-con-full e-flex e-con e-child\" data-id=\"191b90c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68fc43a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"68fc43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/goias.gov.br\/educacao\/imagem-novo-ensino-medio\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/goias.gov.br\/educacao\/wp-content\/uploads\/sites\/40\/2024\/10\/Fluxograma-Novo-Ensino-Medio.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c1b20e e-flex e-con-boxed e-con e-parent\" data-id=\"3c1b20e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f556119 elementor-widget elementor-widget-text-editor\" data-id=\"f556119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><p>O aumento da carga hor\u00e1ria destinada \u00e0 Forma\u00e7\u00e3o Geral B\u00e1sica (FGB) foi uma das principais altera\u00e7\u00f5es, contemplando componentes curriculares como L\u00edngua Portuguesa, Ingl\u00eas, Artes, Educa\u00e7\u00e3o F\u00edsica, Matem\u00e1tica, Biologia, F\u00edsica, Qu\u00edmica, Filosofia, Geografia, Hist\u00f3ria e Sociologia.<\/p><p>Anteriormente, a FGB contava com um m\u00ednimo de 1.800 horas ao longo dos tr\u00eas anos. Agora, o total m\u00ednimo ser\u00e1 de 2.400 horas, definidas pela Base Nacional Comum Curricular (BNCC), o que representa um fortalecimento dos objetos de conhecimento (conte\u00fados), comuns a todos os estudantes.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c10b346 e-flex e-con-boxed e-con e-parent\" data-id=\"c10b346\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-75a2103 e-flex e-con-boxed e-con e-child\" data-id=\"75a2103\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71a6216 elementor-widget elementor-widget-heading\" data-id=\"71a6216\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/goias.gov.br\/educacao\/novo-ensino-medio#itinerarios-formativos-if-mais-flexiveis\" rel=\"nofollow\">Itiner\u00e1rios Formativos (IF) Mais Flex\u00edveis<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca1d1d5 e-flex e-con-boxed e-con e-parent\" data-id=\"ca1d1d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09e17da elementor-widget elementor-widget-text-editor\" data-id=\"09e17da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><p>A nova legisla\u00e7\u00e3o tamb\u00e9m redefine os itiner\u00e1rios formativos, que continuar\u00e3o a ser um espa\u00e7o para o aprofundamento das \u00c1reas do Conhecimento e ou de forma\u00e7\u00e3o t\u00e9cnica e profissional.<\/p><p>Cada unidade escolar dever\u00e1 oferecer, ao menos, dois itiner\u00e1rios, com carga hor\u00e1ria m\u00ednima de 600 horas, sendo que, para os itiner\u00e1rios de forma\u00e7\u00e3o t\u00e9cnica e profissional, estes poder\u00e3o chegar at\u00e9 a 1.200 horas. As \u00e1reas de aprofundamento incluem:<\/p><ul><li><span style=\"color: #ff9900;\">Linguagens e suas Tecnologias;<\/span><\/li><li><span style=\"color: #ff9900;\">Matem\u00e1tica e suas Tecnologias;<\/span><\/li><li><span style=\"color: #ff9900;\">Ci\u00eancias da Natureza e suas Tecnologias;<\/span><\/li><li><span style=\"color: #ff9900;\">Ci\u00eancias Humanas e Sociais Aplicadas;<\/span><\/li><li><span style=\"color: #ff9900;\">Forma\u00e7\u00e3o T\u00e9cnica e Profissional.<\/span><\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5e69e5 e-flex e-con-boxed e-con e-parent\" data-id=\"b5e69e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cbb28c3 e-flex e-con-boxed e-con e-child\" data-id=\"cbb28c3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e237c58 elementor-widget elementor-widget-heading\" data-id=\"e237c58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">  Educa\u00e7\u00e3o Profissional e Tecnol\u00f3gica (EPT)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b01010 e-flex e-con-boxed e-con e-parent\" data-id=\"8b01010\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-439a6c4 elementor-widget elementor-widget-text-editor\" data-id=\"439a6c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><p>A atual legisla\u00e7\u00e3o prev\u00ea para a forma\u00e7\u00e3o t\u00e9cnica uma carga hor\u00e1ria de 2.100 horas na Forma\u00e7\u00e3o Geral B\u00e1sica. Os itiner\u00e1rios de forma\u00e7\u00e3o t\u00e9cnica poder\u00e3o ter a carga m\u00ednima de 900 at\u00e9 1.200 horas, conforme Cat\u00e1logo Nacional de Cursos T\u00e9cnicos, sendo que destas, 300 horas poder\u00e3o ser dedicadas ao aprofundamento de conte\u00fados da BNCC voltados \u00e0 forma\u00e7\u00e3o profissional.<\/p><p>Entenda mais sobre a Educa\u00e7\u00e3o Profissional e Tecnol\u00f3gica <a href=\"https:\/\/goias.gov.br\/educacao\/educacao-profissional-e-tecnologica\/\">clicando aqui<\/a>.\u00a0<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d88b5cf e-flex e-con-boxed e-con e-parent\" data-id=\"d88b5cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0249dad e-flex e-con-boxed e-con e-child\" data-id=\"0249dad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b609291 elementor-widget elementor-widget-heading\" data-id=\"b609291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">   Educa\u00e7\u00e3o \u00e0 Dist\u00e2ncia (EaD) no Ensino M\u00e9dio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69168df e-flex e-con-boxed e-con e-parent\" data-id=\"69168df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b840dfe elementor-widget elementor-widget-text-editor\" data-id=\"b840dfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><div><p>A atual legisla\u00e7\u00e3o n\u00e3o permite a Educa\u00e7\u00e3o \u00e0 Dist\u00e2ncia (EaD) para o Ensino M\u00e9dio regular, exceto em situa\u00e7\u00f5es excepcionais, como em \u00e1reas de dif\u00edcil acesso. Nestes casos, o Ensino M\u00e9dio poder\u00e1 ser mediado por tecnologia.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6668fa7 e-flex e-con-boxed e-con e-parent\" data-id=\"6668fa7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-92071e3 e-flex e-con-boxed e-con e-child\" data-id=\"92071e3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cf2111 elementor-widget elementor-widget-heading\" data-id=\"0cf2111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ensino Noturno<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35c9d4a e-flex e-con-boxed e-con e-parent\" data-id=\"35c9d4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d968530 elementor-widget elementor-widget-text-editor\" data-id=\"d968530\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><div><p>Para os estudantes que necessitam de ensino noturno, a lei garante que cada munic\u00edpio mantenha, pelo menos, uma escola p\u00fablica ofertando esse turno, caso haja demanda e atenda os pr\u00e9-requisitos para a abertura de turma.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f22d6fd e-flex e-con-boxed e-con e-parent\" data-id=\"f22d6fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-76ee664 e-flex e-con-boxed e-con e-child\" data-id=\"76ee664\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1486f elementor-widget elementor-widget-heading\" data-id=\"4c1486f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Atividades extraescolares<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2428ac4 e-flex e-con-boxed e-con e-parent\" data-id=\"2428ac4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be62ada elementor-widget elementor-widget-text-editor\" data-id=\"be62ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><div><p>As experi\u00eancias fora da escola, como est\u00e1gios, trabalho volunt\u00e1rio e ou participa\u00e7\u00e3o em projetos universit\u00e1rios, desde que alinhadas ao curr\u00edculo, contar\u00e3o como carga hor\u00e1ria regular para os estudantes do Ensino M\u00e9dio.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de28c06 e-flex e-con-boxed e-con e-parent\" data-id=\"de28c06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2c10521 e-flex e-con-boxed e-con e-child\" data-id=\"2c10521\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69556dc elementor-widget elementor-widget-heading\" data-id=\"69556dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inclus\u00e3o da Educa\u00e7\u00e3o do Campo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-788c002 e-flex e-con-boxed e-con e-parent\" data-id=\"788c002\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27d3b8b elementor-widget elementor-widget-text-editor\" data-id=\"27d3b8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><div><p>Um destaque importante da nova legisla\u00e7\u00e3o \u00e9 a inclus\u00e3o dos estudantes do Ensino M\u00e9dio matriculados em escolas comunit\u00e1rias do campo, ao Programa Universidade para Todos (Prouni). Esses estudantes poder\u00e3o contar com bolsas integrais em faculdades privadas e vagas reservadas nas institui\u00e7\u00f5es federais de ensino superior, assim como o acesso \u00e0 poupan\u00e7a do Programa P\u00e9-de-Meia.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-364543f e-flex e-con-boxed e-con e-parent\" data-id=\"364543f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef2209c e-flex e-con-boxed e-con e-child\" data-id=\"ef2209c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f93ef84 elementor-widget elementor-widget-heading\" data-id=\"f93ef84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Implementa\u00e7\u00e3o no Estado de Goi\u00e1s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e016a90 e-flex e-con-boxed e-con e-parent\" data-id=\"e016a90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-560b425 elementor-widget elementor-widget-text-editor\" data-id=\"560b425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><div><p>A oferta do Ensino M\u00e9dio na rede p\u00fablica estadual de Goi\u00e1s se d\u00e1 em conson\u00e2ncia \u00e0s normativas regulamentadas pela Lei n\u00ba 14.945 e, com isso, as altera\u00e7\u00f5es no ensino p\u00fablico estadual goiano ser\u00e3o, de fato, m\u00ednimas.<\/p><p>\u00c9 importante lembrar que, desde o in\u00edcio de 2024, todas as unidades escolares que ofertam o Ensino M\u00e9dio t\u00eam em seu curr\u00edculo os doze componentes curriculares da Forma\u00e7\u00e3o Geral B\u00e1sica, mais Estudo Orientado de L\u00edngua Portuguesa e de Matem\u00e1tica e, ainda, as Eletivas, entre as quais os estudantes escolhem a tem\u00e1tica que cursar\u00e3o, a cada semestre, a partir de um Cat\u00e1logo disponibilizado pela Seduc\/GO.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a147595 e-flex e-con-boxed e-con e-parent\" data-id=\"a147595\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a0931fc e-flex e-con-boxed e-con e-child\" data-id=\"a0931fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b140ba elementor-widget elementor-widget-heading\" data-id=\"2b140ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eletivas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d63592 e-flex e-con-boxed e-con e-parent\" data-id=\"7d63592\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca801ae elementor-widget elementor-widget-text-editor\" data-id=\"ca801ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><div><p>\u00c9 um componente curricular que faz parte dos Itiner\u00e1rios Formativos ofertados, semestralmente, nas turmas de Ensino M\u00e9dio. Os estudantes podem escolher a que mais lhes interessa a partir do Cat\u00e1logo das Eletivas, disponibilizado pela Secretaria de Estado de Educa\u00e7\u00e3o de Goi\u00e1s.<\/p><p>Essa a\u00e7\u00e3o tem por objetivo propiciar a amplia\u00e7\u00e3o e o desenvolvimento de compet\u00eancias e habilidades cognitivas e socioemocionais, bem como oferecer uma oportunidade de abordagem pr\u00e1tica do curr\u00edculo da Rede. Para o desenvolvimento das Eletivas cada unidade escolar prop\u00f5e uma tem\u00e1tica considerando a sua realidade, as formas de implementa\u00e7\u00e3o e ambienta\u00e7\u00e3o dos espa\u00e7os para o desenvolvimento deste componente.<\/p><p><a href=\"https:\/\/goias.gov.br\/educacao\/wp-content\/uploads\/sites\/40\/2025\/07\/1.-CATALOGO-DAS-ELETIVAS.pdf\">CAT\u00c1LOGO DAS ELETIVAS 2025<\/a><\/p><p><a href=\"https:\/\/goias.gov.br\/educacao\/wp-content\/uploads\/sites\/40\/2025\/07\/2.-CATALOGO-DAS-ELETIVAS-FIC-2025.pdf\">CAT\u00c1LOGO DAS ELETIVAS FICS 2025<\/a><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eac0e82 e-flex e-con-boxed e-con e-parent\" data-id=\"eac0e82\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef862f4 e-flex e-con-boxed e-con e-child\" data-id=\"ef862f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb07ca elementor-widget elementor-widget-heading\" data-id=\"8bb07ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Estudo Orientado de L\u00edngua Portuguesa e de Matem\u00e1tica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-531c5c9 e-flex e-con-boxed e-con e-parent\" data-id=\"531c5c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3efe63f elementor-widget elementor-widget-text-editor\" data-id=\"3efe63f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><div><div><p>\u00a0Os componentes curriculares Estudo Orientado de L\u00edngua Portuguesa e de Matem\u00e1tica tem por objetivo promover o fortalecimento das aprendizagens dos estudantes com foco na recomposi\u00e7\u00e3o e, ao mesmo tempo, na continuidade de seu percurso formativo previsto para a s\u00e9rie em curso.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e8142ca e-flex e-con-boxed e-con e-parent\" data-id=\"e8142ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d795dfc e-flex e-con-boxed e-con e-child\" data-id=\"d795dfc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86bc1fd elementor-widget elementor-widget-heading\" data-id=\"86bc1fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hist\u00f3rico do Novo Ensino M\u00e9dio em Goi\u00e1s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5cb0d6 e-flex e-con-boxed e-con e-parent\" data-id=\"a5cb0d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d538a5 elementor-widget elementor-widget-shortcode\" data-id=\"1d538a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div data-post-id=\"96039\" class=\"insert-page insert-page-96039 \"><div class=\"align wp-block-tlgb-b-timeline-block\" id='BTimelineBlock-1'\r\n  data-attributes='{&quot;cId&quot;:&quot;afbb7c3a-0&quot;,&quot;timelines&quot;:[{&quot;label&quot;:&quot;Escuta de Estudantes&quot;,&quot;description&quot;:&quot;2019 - Escuta de estudantes e in\\u00edcio da elabora\\u00e7\\u00e3o do documento curricular para Goi\\u00e1s - Etapa Ensino M\\u00e9dio (DC - GOEM), que normatiza novo Ensino M\\u00e9dio.&quot;},{&quot;label&quot;:&quot;Consulta P\\u00fablica&quot;,&quot;description&quot;:&quot;2020 - Consulta P\\u00fablica da vers\\u00e3o preliminar do DC-GOEM, que recebeu mais de 20 mil contribui\\u00e7\\u00f5es de professores, gestores, estudantes, pais e representantes dos sistemas de ensino.&quot;},{&quot;label&quot;:&quot;Amplia\\u00e7\\u00e3o da carga hor\\u00e1ria&quot;,&quot;description&quot;:&quot;2020 - Amplia\\u00e7\\u00e3o da carga hor\\u00e1ria e oferta de Projeto de Vida e Eletivas em 596 escolas estaduais nas turmas de 1\\u00ba s\\u00e9rie.&quot;},{&quot;label&quot;:&quot;Implanta\\u00e7\\u00e3o do Itiner\\u00e1rio Formativo T\\u00e9cnico&quot;,&quot;description&quot;:&quot;2021 - Implanta\\u00e7\\u00e3o do Itiner\\u00e1rio Formativo T\\u00e9cnico - Profissionalizante em 48 turmas, de forma piloto, com a oferta das Trilhas de Aprofundamento de Administra\\u00e7\\u00e3o, Qu\\u00cdmica e Informatica.&quot;},{&quot;label&quot;:&quot;Audi\\u00eancia P\\u00fablica&quot;,&quot;description&quot;:&quot;2021 - Audi\\u00eancia P\\u00fablica e aprova\\u00e7\\u00e3o do DC-GOEM pelo Conselho Estadual de Educa\\u00e7\\u00e3o de Goi\\u00e1s.&quot;},{&quot;label&quot;:&quot;2022 - Implanta\\u00e7\\u00e3o de Trilhas&quot;,&quot;description&quot;:&quot;22 - Implanta\\u00e7\\u00e3o de Trilhas de Aprofunamento em mais 367  escolas  estaduais, na 2\\u00aa s\\u00e9rie, de forma piloto.&quot;},{&quot;label&quot;:&quot;2023 - Amplia\\u00e7\\u00e3o das Trilhas&quot;,&quot;description&quot;:&quot;2023 - Implata\\u00e7\\u00e3o de Trilhas de Aprofunamento em todas as escolas estaduais e implanta\\u00e7\\u00e3o completa do novo Ensino M\\u00e9dio.&quot;},{&quot;label&quot;:&quot;2023: Aprovada a Lei PL 5.230\\\/2023&quot;,&quot;description&quot;:&quot;2024: Implanta\\u00e7\\u00e3o da (Lei PL 5.230\\\/2023) nova carga hor\\u00e1ria e Itiner\\u00e1rios Formativos mais flex\\u00edveis. &quot;}],&quot;type&quot;:&quot;horizontal&quot;,&quot;labelLocation&quot;:&quot;top&quot;,&quot;barBackground&quot;:&quot;rgba(53, 135, 43, 1)&quot;,&quot;barDotColor&quot;:&quot;rgba(53, 135, 43, 1)&quot;,&quot;itemBg&quot;:&quot;rgba(255, 180, 60, 1)&quot;,&quot;itemColor&quot;:&quot;#ffffff&quot;,&quot;itemTypo&quot;:{&quot;fontSize&quot;:{&quot;desktop&quot;:14,&quot;tablet&quot;:14,&quot;mobile&quot;:14},&quot;isUploadFont&quot;:true,&quot;textTransform&quot;:&quot;none&quot;,&quot;fontStyle&quot;:&quot;normal&quot;,&quot;fontWeight&quot;:600,&quot;fontVariant&quot;:&quot;600&quot;},&quot;labelTypo&quot;:{&quot;fontSize&quot;:{&quot;desktop&quot;:16,&quot;tablet&quot;:16,&quot;mobile&quot;:16},&quot;fontWeight&quot;:600,&quot;fontVariant&quot;:&quot;600&quot;},&quot;labelColor&quot;:&quot;rgba(36, 86, 194, 1)&quot;,&quot;align&quot;:&quot;&quot;,&quot;itemPosition&quot;:&quot;right&quot;,&quot;startIndex&quot;:1,&quot;visibleItems&quot;:4,&quot;vigibleItems&quot;:4,&quot;moveItem&quot;:2,&quot;verticalTrigger&quot;:&quot;150px&quot;,&quot;rtlMode&quot;:false,&quot;horizontalDatePosition&quot;:&quot;bottom&quot;,&quot;itemBorder&quot;:{&quot;width&quot;:&quot;1px&quot;,&quot;color&quot;:&quot;#cccccc&quot;},&quot;contentBorder&quot;:{&quot;width&quot;:&quot;1px&quot;,&quot;style&quot;:&quot;solid&quot;,&quot;color&quot;:&quot;#72aee6&quot;},&quot;theme&quot;:&quot;default&quot;,&quot;timelineBar&quot;:{&quot;width&quot;:&quot;3px&quot;,&quot;dotSize&quot;:20,&quot;progressBarbgColor&quot;:{&quot;color&quot;:&quot;linear-gradient(to bottom, #ff6a00, #ee0979)&quot;}},&quot;dateStyles&quot;:{&quot;dateTypo&quot;:{&quot;fontSize&quot;:{&quot;desktop&quot;:14,&quot;tablet&quot;:14,&quot;mobile&quot;:14}},&quot;dateColor&quot;:&quot;black&quot;,&quot;dateContainerSize&quot;:50,&quot;dateBg&quot;:{&quot;color&quot;:&quot;#06b6d4&quot;}}}'><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c790e4 e-flex e-con-boxed e-con e-parent\" data-id=\"1c790e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d8fd834 e-flex e-con-boxed e-con e-child\" data-id=\"d8fd834\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-674c20b elementor-widget elementor-widget-heading\" data-id=\"674c20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Documento Curricular<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c966f2b e-flex e-con-boxed e-con e-parent\" data-id=\"c966f2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb9fbe5 elementor-widget elementor-widget-heading\" data-id=\"eb9fbe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leia o Documento Curricular do novo Ensino M\u00e9dio na \u00edntegra:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4da29c elementor-widget elementor-widget-image\" data-id=\"c4da29c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/goias.gov.br\/wp-content\/uploads\/sites\/40\/2024\/NovoEnsinoMedio\/DocumentoCurricular\/DOCUMENTO_CURRICULAR_PARA_GOIAS_ETAPA_ENSINO_MEDIO.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/goias.gov.br\/educacao\/wp-content\/uploads\/sites\/40\/2024\/01\/documento-curricular-brasao-01.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59fffee elementor-widget elementor-widget-text-editor\" data-id=\"59fffee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Aten\u00e7\u00e3o, professor! Encontre orienta\u00e7\u00f5es pedag\u00f3gicos sobre o novo Ensino M\u00e9dio clicando <a href=\"https:\/\/goias.gov.br\/wp-content\/uploads\/sites\/40\/2024\/NovoEnsinoMedio\/DocumentoCurricular\/DOCUMENTO_CURRICULAR_PARA_GOIAS_ETAPA_ENSINO_MEDIO.pdf\">aqui<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Novo Ensino M\u00e9dio: como vai funcionar em Goi\u00e1s a partir de 2024 Nova lei reestrutura o Ensino M\u00e9dio Entenda as principais mudan\u00e7as A nova Pol\u00edtica Nacional de Ensino M\u00e9dio, institu\u00edda pela Lei n\u00ba 14.945\/2024, traz mudan\u00e7as significativas para essa etapa da Educa\u00e7\u00e3o no Brasil. Aprovada em 31 de julho de 2024, a lei altera a [&hellip;]<\/p>\n","protected":false},"author":222,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-26903","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"diegomsilva","author_link":"https:\/\/goias.gov.br\/educacao\/author\/diegomsilva\/"},"rttpg_comment":0,"rttpg_category":"","rttpg_excerpt":"Novo Ensino M\u00e9dio: como vai funcionar em Goi\u00e1s a partir de 2024 Nova lei reestrutura o Ensino M\u00e9dio Entenda as principais mudan\u00e7as A nova Pol\u00edtica Nacional de Ensino M\u00e9dio, institu\u00edda pela Lei n\u00ba 14.945\/2024, traz mudan\u00e7as significativas para essa etapa da Educa\u00e7\u00e3o no Brasil. Aprovada em 31 de julho de 2024, a lei altera a&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/pages\/26903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/users\/222"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=26903"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/pages\/26903\/revisions"}],"predecessor-version":[{"id":764495,"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/pages\/26903\/revisions\/764495"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=26903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}