

{"id":5426,"date":"2011-12-08T11:13:47","date_gmt":"2011-12-08T13:13:47","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/controladoria\/titular-da-cge-defende-total-transparencia-na-gestao-publica\/"},"modified":"2011-12-08T11:13:47","modified_gmt":"2011-12-08T13:13:47","slug":"titular-da-cge-defende-total-transparencia-na-gestao-publica","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/controladoria\/titular-da-cge-defende-total-transparencia-na-gestao-publica\/","title":{"rendered":"Titular da CGE defende total transpar\u00eancia na gest\u00e3o p\u00fablica"},"content":{"rendered":"<p>\n<!--more--><\/p>\n<p>Ao fazer palestra na abertura da 2\u00aa edi\u00e7\u00e3o do CGE Orienta, na manh\u00e3 de ter\u00e7a-feira (6\/12), no audit\u00f3rio da Celg, o secret\u00e1rio-chefe da Controladoria Geral do Estado, Jos\u00e9 Carlos Siqueira, foi enf\u00e1tico ao afirmar para os mais de 250 servidores de todos os \u00f3rg\u00e3os estaduais que transpar\u00eancia na gest\u00e3o p\u00fablica, al\u00e9m de ser um imperativo legal, \u00e9 na atualidade uma forte demanda da sociedade. Segundo ele, a popula\u00e7\u00e3o se organiza cada vez mais e quer ter acesso a dados claros e compreens\u00edveis, de modo a exercer melhor controle sobre a arrecada\u00e7\u00e3o e os gastos da administra\u00e7\u00e3o p\u00fablica, para aferir os resultados.<\/p>\n<p>O semin\u00e1rio CGE Orienta reuniu t\u00e9cnicos e assessores que atuam nas \u00e1reas de planejamento, execu\u00e7\u00e3o or\u00e7ament\u00e1ria, corregedoria e ouvidoria, lotados em secretarias de Estado, autarquias, funda\u00e7\u00f5es e empresas p\u00fablicas. O tema central do evento foi relativo ao Decreto 7.501\/2011, que trata da presta\u00e7\u00e3o de contas anuais, mas tamb\u00e9m foram apresentados e discutidos temas sobre corregedoria, preven\u00e7\u00e3o \u00e0 corrup\u00e7\u00e3o e ouvidoria no \u00e2mbito da Controladoria Geral do Estado.<\/p>\n<p>O secret\u00e1rio Jos\u00e9 Carlos Siqueira pediu empenho a todos no sentido de trabalharem os dados com acur\u00e1cia, consolidando relat\u00f3rios bem fundamentados das contas do governador e de todos os demais respons\u00e1veis pela administra\u00e7\u00e3o direta e indireta do Estado, especialmente porque tudo ser\u00e1 disponibilizado para a popula\u00e7\u00e3o no site da transpar\u00eancia. Ele tamb\u00e9m falou da necessidade de se dar mais import\u00e2ncia \u00e0s a\u00e7\u00f5es da Corregedoria Geral do Estado e de maior envolvimento dos \u00f3rg\u00e3os no recebimento, encaminhamento e oferta de respostas \u00e0s demandas da Ouvidoria Geral do Estado.<\/p>\n<p>Palestras<\/p>\n<p>Ap\u00f3s a abertura dos trabalhos, o superintendente de Controle Interno, Andr\u00e9 da Silva G\u00f3es, detalhou o Decreto de Contas Anuais (7.501), destacando os pontos mais importantes a serem observados na elabora\u00e7\u00e3o dos relat\u00f3rios. Na sequ\u00eancia, a gestora de Finan\u00e7as e Controle da CGE, Elaine de F\u00e1tima Aires de Oliveira e Silva, falou sobre o relat\u00f3rio que acompanha as Contas do Governador, a ser encaminhado posteriormente ao Tribunal de Contas do Estado e \u00e0 Assembleia Legislativa.<\/p>\n<p>No per\u00edodo da tarde, os trabalhos foram abertos pela superintendente de Preven\u00e7\u00e3o da Corrup\u00e7\u00e3o e Informa\u00e7\u00f5es Estrat\u00e9gicas, Maria D&#8217;Abadia de Oliveira Brand\u00e3o, discorreu sobre os projetos desenvolvidos ao longo deste ano. Em seguida, o superintendente de Corregedoria Geral, Jos\u00e9 Roberto Ferreira Alves, falou sobre Procedimentos B\u00e1sicos de Execu\u00e7\u00e3o do Processo Administrativo Disciplinar (PAD). O \u00faltimo palestrante foi o superintendente de Ouvidoria Geral, Gustavo Franco Martins Monteiro, que fez um balan\u00e7o sobre as atividades da Ouvidoria em 2011 e como os diversos \u00f3rg\u00e3os podem colaborar para o melhor desempenho na solu\u00e7\u00e3o das demandas da popula\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":54,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-5426","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"hosanagodoy","author_link":"https:\/\/goias.gov.br\/controladoria\/author\/hosanagodoy\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/controladoria\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":null,"_links":{"self":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/5426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/comments?post=5426"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/5426\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/media?parent=5426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/categories?post=5426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/tags?post=5426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}