

{"id":4312,"date":"2016-04-07T04:01:34","date_gmt":"2016-04-07T07:01:34","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/controladoria\/operacao-araguaia-busca-garantir-a-cota-zero\/"},"modified":"2016-04-07T04:01:34","modified_gmt":"2016-04-07T07:01:34","slug":"operacao-araguaia-busca-garantir-a-cota-zero","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/controladoria\/operacao-araguaia-busca-garantir-a-cota-zero\/","title":{"rendered":"Opera\u00e7\u00e3o Araguaia busca garantir a cota zero"},"content":{"rendered":"<p>\n<!--more--><\/p>\n<p>No per\u00edodo entre 30 de mar\u00e7o e 5 de abril, fiscais ambientais da Secima realizaram a Opera\u00e7\u00e3o Araguaia, com objetivo de coibir a pesca ilegal e predat\u00f3ria, nas regi\u00f5es de Aruan\u00e3, Brit\u00e2nia, Itacaiu e Aragar\u00e7as, Lago Jurumirim, Rio Claro e Rio \u00c1gua Limpa. Ao todo, sete fiscais navegaram por 120 quil\u00f4metros de lagos e rios da regi\u00e3o. Foram abordados 133 pessoas em embarca\u00e7\u00f5es, tablados e nos barrancos. Durante as abodagens, foi verificada a posse da licen\u00e7a de pesca, a cota zero para transporte de pescado e o respeito ao tamanho dos pescados.<\/p>\n<p>Outras 109 pessoas foram abordadas nos postos de fiscaliza\u00e7\u00e3o de Itacaiu, Brit\u00e2nia e na GO-324. Assim como nas abordagens n\u00e1uticas, o objetivo da opera\u00e7\u00e3o foi alertar a popula\u00e7\u00e3o sobre a Instru\u00e7\u00e3o normativa Estadual n\u00ba 0002\/2013, que disp\u00f5e sobre a cota zero de transporte para pesca no Estado de Goi\u00e1s.<\/p>\n<p>Ao todo, 242 foram pessoas abordadas; o que resultou em sete Autos de Infra\u00e7\u00e3o Contra a Fauna Silvestre e R$ 8.782,00 em multas. Foi apreendida uma grande quantidade de material predat\u00f3rio, sendo 17 redes; 76 pindas; quatro tarrafas; dois arp\u00f5es; uma espingarda com 11 muni\u00e7\u00f5es; 21 boias; dois espinh\u00e9is, 60 anz\u00f3is para espinhel. Tamb\u00e9m foram apreendidas uma zagaia e nove cambu\u00eds, materiais de pesca predat\u00f3ria. Apesar do grande n\u00famero de material predat\u00f3rio encontrado, apenas sete quilos de pescado foram apreendidos.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":54,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-4312","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"hosanagodoy","author_link":"https:\/\/goias.gov.br\/controladoria\/author\/hosanagodoy\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/controladoria\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":null,"_links":{"self":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/4312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/comments?post=4312"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/4312\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/media?parent=4312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/categories?post=4312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/tags?post=4312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}