{"id":41,"date":"2019-07-18T13:49:57","date_gmt":"2019-07-18T16:49:57","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/controladoria\/tetano\/"},"modified":"2019-07-18T13:49:57","modified_gmt":"2019-07-18T16:49:57","slug":"tetano","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/controladoria\/tetano\/","title":{"rendered":"T\u00e9tano"},"content":{"rendered":"<p>Normalmente come&ccedil;a com espasmos brandos nos m&uacute;sculos maxilares (trismos), m&uacute;sculos do pesco&ccedil;o e da face. A rigidez rapidamente se espalha para os m&uacute;sculos do peito, das costas e do abdome e, por vezes, para os m&uacute;sculos da laringe (o que interfere com a respira&ccedil;&atilde;o).<\/p>\n<p>Doen&ccedil;a causada pela toxina da bact&eacute;ria Clostidium tetani que afeta o sistema nervoso central e que, por vezes, pode levar &agrave; morte.<\/p>\n<h3>Preven&ccedil;&atilde;o<\/h3>\n<p>&Eacute; totalmente evit&aacute;vel com uma imuniza&ccedil;&atilde;o antitet&acirc;nica (vacina) ativa. As imuniza&ccedil;&otilde;es antitet&acirc;nicas t&ecirc;m in&iacute;cio na inf&acirc;ncia, com uma s&eacute;rie de inje&ccedil;&otilde;es da vacina tr&iacute;plice ( difteria, coqueluche ou tosse comprida e t&eacute;tano).<\/p>\n<h3>Sintomas<\/h3>\n<ul>\n<li>Espasmos e tensionamento do m&uacute;sculo mandibular;<\/li>\n<li>Enrigecimento dos m&uacute;sculos do pesco&ccedil;o e outros;<\/li>\n<li>Espasmo dos m&uacute;sculos do pesco&ccedil;o e outros;<\/li>\n<li>Rigidez dos m&uacute;sculos tor&aacute;cicos;<\/li>\n<li>Rigidez dos m&uacute;sculos abdominais (rigidez abdominal);<\/li>\n<li>Espasmos e rigidez dos m&uacute;sculos das costas, freq&uuml;entemente causando dores (opist&oacute;tonos);<\/li>\n<li>Convuls&otilde;es tet&acirc;nicas (contra&ccedil;&otilde;es musculares fortes e doloridas);<\/li>\n<li>Irritabilidade;<\/li>\n<li>Febre.<\/li>\n<\/ul>\n<h3>Tratamento<\/h3>\n<p>Controlar e reverter a tetania com o uso de antitoxinas; remover e destruir a fonte de toxina; tratar os sintomas com terapia de suporte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Normalmente come&ccedil;a com espasmos brandos nos m&uacute;sculos maxilares (trismos), m&uacute;sculos do pesco&ccedil;o e da face. A rigidez rapidamente se espalha para os m&uacute;sculos do peito, das costas e do abdome e, por vezes, para os m&uacute;sculos da laringe (o que interfere com a respira&ccedil;&atilde;o). Doen&ccedil;a causada pela toxina da bact&eacute;ria Clostidium tetani que afeta o [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-41","post","type-post","status-publish","format-standard","hentry","category-biblioteca"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"hosanagodoy","author_link":"https:\/\/goias.gov.br\/controladoria\/author\/hosanagodoy\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/controladoria\/categoria\/biblioteca\/\" rel=\"category tag\">Biblioteca<\/a>","rttpg_excerpt":"Normalmente come&ccedil;a com espasmos brandos nos m&uacute;sculos maxilares (trismos), m&uacute;sculos do pesco&ccedil;o e da face. A rigidez rapidamente se espalha para os m&uacute;sculos do peito, das costas e do abdome e, por vezes, para os m&uacute;sculos da laringe (o que interfere com a respira&ccedil;&atilde;o). Doen&ccedil;a causada pela toxina da bact&eacute;ria Clostidium tetani que afeta o&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/41\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/categories?post=41"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/tags?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}