

{"id":10251,"date":"2023-05-12T16:28:23","date_gmt":"2023-05-12T19:28:23","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/controladoria\/controlador-geral-conhece-modelos-de-gestao-em-saude-na-paraiba-e-pernambuco\/"},"modified":"2023-05-12T16:28:23","modified_gmt":"2023-05-12T19:28:23","slug":"controlador-geral-conhece-modelos-de-gestao-em-saude-na-paraiba-e-pernambuco","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/controladoria\/controlador-geral-conhece-modelos-de-gestao-em-saude-na-paraiba-e-pernambuco\/","title":{"rendered":"Controlador-geral conhece modelos de gest\u00e3o em Sa\u00fade na Para\u00edba e Pernambuco"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-10250\" src=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/WhatsApp_Image_2023-05-12_at_101216_1jpeg-42f.jpg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/WhatsApp_Image_2023-05-12_at_101216_1jpeg-42f.jpg 768w, https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/WhatsApp_Image_2023-05-12_at_101216_1jpeg-42f-225x300.jpg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p>\n<p style=\"text-align: justify;\">O controlador-geral do Estado, Henrique Ziller, encerrou a agenda da semana visitando duas capitais da regi&atilde;o Nordeste do Pa&iacute;s: Jo&atilde;o Pessoa (PB) e Recife (PE). Na quinta-feira (11\/5), ele esteve no Hospital Metropolitano Dom Jos&eacute; Maria Pires, unidade gerida pela Funda&ccedil;&atilde;o Paraibana de Gest&atilde;o em Sa&uacute;de (PB Sa&uacute;de), acompanhando uma visita t&eacute;cnica da Secretaria de Sa&uacute;de local. O objetivo foi entender o funcionamento do modelo de gest&atilde;o de sa&uacute;de p&uacute;blica feito pela Funda&ccedil;&atilde;o.<\/p>\n<p style=\"text-align: justify;\">Ziller foi recebido pela secret&aacute;ria-adjunta de Sa&uacute;de da Para&iacute;ba, Renata N&oacute;brega; pelo diretor t&eacute;cnico do Hospital Metropolitano, Matheus Agra; e demais dirigentes da unidade hospitalar e da PB Sa&uacute;de. Em seguida participou de reuni&atilde;o com o diretor-superintendente da Funda&ccedil;&atilde;o, Luiz Gustavo C&eacute;sar.<\/p>\n<p style=\"text-align: justify;\">&ldquo;Conhecemos a elabora&ccedil;&atilde;o do modelo jur&iacute;dico que permitiu a cria&ccedil;&atilde;o da Funda&ccedil;&atilde;o, como ela est&aacute; estruturada e como &eacute; poss&iacute;vel prestar um servi&ccedil;o de sa&uacute;de com boa qualidade e agilidade com esse novo modelo de gest&atilde;o. Tanto nas contrata&ccedil;&otilde;es de pessoal quanto na aquisi&ccedil;&atilde;o de materiais hospitalares, por exemplo&rdquo;, elencou o controlador-geral do Estado de Goi&aacute;s. &ldquo;S&atilde;o informa&ccedil;&otilde;es relevantes que vamos levar em nossa bagagem para estudar a implanta&ccedil;&atilde;o de um projeto semelhante&rdquo;, completou.&nbsp;<\/p>\n<p style=\"text-align: justify;\">O diretor-superintendente da PB Sa&uacute;de, Luiz Gustavo C&eacute;sar, avaliou como positiva a visita da comitiva de Goi&aacute;s. &ldquo;O Governo da Para&iacute;ba tem feito investimentos important&iacute;ssimos em sa&uacute;de. O Hospital Metropolitano realiza transplantes de cora&ccedil;&atilde;o, al&eacute;m de procedimentos de alta complexidade. Tudo isso s&oacute; &eacute; poss&iacute;vel porque temos uma gest&atilde;o eficiente de insumos, de leitos e de pessoas. E essa reuni&atilde;o mostra que estamos no caminho certo, exportando modelo de gest&atilde;o em sa&uacute;de&rdquo;, avaliou.<\/p>\n<p style=\"text-align: justify;\"><strong>Controladoria-Geral do Estado &#8211; Governo de Goi&aacute;s<\/strong><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O controlador-geral do Estado, Henrique Ziller, encerrou a agenda da semana visitando duas capitais da regi&atilde;o Nordeste do Pa&iacute;s: Jo&atilde;o Pessoa (PB) e Recife (PE). Na quinta-feira (11\/5), ele esteve no Hospital Metropolitano Dom Jos&eacute; Maria Pires, unidade gerida pela Funda&ccedil;&atilde;o Paraibana de Gest&atilde;o em Sa&uacute;de (PB Sa&uacute;de), acompanhando uma visita t&eacute;cnica da Secretaria de [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":10249,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-10251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f.jpg",768,576,false],"landscape":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f.jpg",768,576,false],"portraits":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f.jpg",768,576,false],"thumbnail":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f-300x225.jpg",300,225,true],"large":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f.jpg",768,576,false],"1536x1536":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f.jpg",768,576,false],"2048x2048":["https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/05\/ziller_na_PBjpeg-c7f.jpg",768,576,false]},"rttpg_author":{"display_name":"joaossantos","author_link":"https:\/\/goias.gov.br\/controladoria\/author\/joaossantos\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/controladoria\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"O controlador-geral do Estado, Henrique Ziller, encerrou a agenda da semana visitando duas capitais da regi&atilde;o Nordeste do Pa&iacute;s: Jo&atilde;o Pessoa (PB) e Recife (PE). Na quinta-feira (11\/5), ele esteve no Hospital Metropolitano Dom Jos&eacute; Maria Pires, unidade gerida pela Funda&ccedil;&atilde;o Paraibana de Gest&atilde;o em Sa&uacute;de (PB Sa&uacute;de), acompanhando uma visita t&eacute;cnica da Secretaria de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/10251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/comments?post=10251"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/10251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/media\/10249"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/media?parent=10251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/categories?post=10251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/tags?post=10251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}