{"id":10076,"date":"2023-02-06T10:47:40","date_gmt":"2023-02-06T13:47:40","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/controladoria\/aditivos-2023-2\/"},"modified":"2023-02-06T10:47:40","modified_gmt":"2023-02-06T13:47:40","slug":"aditivos-2023-2","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/controladoria\/aditivos-2023-2\/","title":{"rendered":"Aditivos 2023"},"content":{"rendered":"<p>\n<a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_14283_1-74a.pdf\" target=\"\" rel=\"noopener\">PRIMEIRO TERMO ADITIVO AO CONTRATO N&ordm; 006\/2022-CGE &#8211; Aditamento de aproximadamente 23,93% do Contrato 006\/2022 &#8211; CGE, em raz&atilde;o de acr&eacute;scimos de deslocamentos para a participa&ccedil;&atilde;o em cursos, eventos, semin&aacute;rios, congressos, principalmente eventos do Conselho Nacional de Controle Interno (CONACI), visando o desenvolvimento profissional dos servidores, capacita&ccedil;&otilde;es t&eacute;cnicas e afins, conforme art. 65, &sect; 1&ordm;, da Lei Federal n&ordm; 8.666\/1993.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_14053-14c.pdf\" id=\"\" style=\"\" target=\"_blank\" title=\"\" rel=\"noopener\">Primeiro Termo Aditivo ao Contrato n&ordm; 03\/2020-CGE &#8211; Dila&ccedil;&atilde;o do prazo de vig&ecirc;ncia do \u200bContrato n&ordm; 03\/2020 &#8211; CGE por um per&iacute;odo de mais 18 (dezoito) meses, conforme previs&atilde;o da Cl&aacute;usula Quinta do referido Contrato e em obedi&ecirc;ncia ao disposto no art. 57, inciso II, da Lei Federal n&ordm; 8.666\/1993, bem como a aplica&ccedil;&atilde;o do &iacute;ndice de reajuste IPCA &ndash; IBGE, no percentual de aproximadamente 5,79% (cinco v&iacute;rgula setenta e nove por cento), referente ao per&iacute;odo de janeiro de 2022 a dezembro de 2022, em conformidade com o Parecer Jur&iacute;dico ADSET n&ordm; 620\/2022 do &Oacute;rg&atilde;o Gerenciador da Ata de Registro de Pre&ccedil;os que deu origem ao Contrato.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_14019-c5e.pdf\" style=\"\" target=\"_blank\" title=\"\" rel=\"noopener\">Segundo Termo Aditivo ao Contrato n&ordm; 002\/2021 &#8211; Dila&ccedil;&atilde;o do prazo de vig&ecirc;ncia do Contrato n&ordm; 002\/2021-CGE, que trata da contrata&ccedil;&atilde;o de empresa especializada na presta&ccedil;&atilde;o de servi&ccedil;o de gerenciamento eletr&ocirc;nico e controle de abastecimento de combust&iacute;veis, pelo per&iacute;odo de mais 12 meses, conforme Cl&aacute;usula Sexta do referido Contrato e art. 57, II, da Lei Federal n&ordm; 8.666\/1993.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_13976-0eb.pdf\" style=\"\" target=\"_blank\" title=\"\" rel=\"noopener\">Terceiro Termo Aditivo ao Contrato n&ordm; 01\/2020-CGE &#8211; Dila&ccedil;&atilde;o do prazo de vig&ecirc;ncia do Contrato n&ordm; 01\/2020-CGE, conforme Cl&aacute;usula Sexta do referido Contrato e conforme disposto no art. 57, inciso II, da Lei Federal n&ordm; 8.666\/1993, por um per&iacute;odo de 12 (doze) meses, com aplica&ccedil;&atilde;o da corre&ccedil;&atilde;o no valor da taxa de administra&ccedil;&atilde;o com base no IPCA\/IBGE em obedi&ecirc;ncia &agrave; Clausula 5&ordf; , item 05.14, do instrumento contratual.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_14460-9d7.pdf\" target=\"\" rel=\"noopener\">PRIMEIRO TERMO ADITIVO AO CONTRATO N&ordm; 001\/2022-CGE &#8211; Dila&ccedil;&atilde;o do prazo de vig&ecirc;ncia do Contrato n&ordm; 001\/2022-CGE, de presta&ccedil;&atilde;o de servi&ccedil;os de estacionamento, por um per&iacute;odo de mais 12 (doze) meses, conforme Cl&aacute;usula Vig&eacute;sima Sexta e em obedi&ecirc;ncia ao disposto no art. 57, inciso II, da Lei Federal n&ordm; 8.666\/1993, bem como o reajuste do valor do Contrato pela varia&ccedil;&atilde;o do IPC-A (IBGE) dos &uacute;ltimos 12 meses, conforme previs&atilde;o da Cl&aacute;usula D&eacute;cima Primeira do referido ajuste.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_14501-3ab.pdf\" target=\"_blank\" rel=\"noopener\">EXTRATO DO PRIMEIRO TERMO ADITIVO AO CONTRATO 02\/2022 &#8211; CGE &#8211; Dila&ccedil;&atilde;o do prazo de vig&ecirc;ncia do \u200bContrato n&ordm; 02\/2022 &#8211; CGE, cujo objeto &eacute; o fornecimento da ferramenta Banco de Pre&ccedil;os para o fornecimento da ferramenta Banco de Pre&ccedil;os, atrav&eacute;s do site Neg&oacute;cios P&uacute;blicos (www.bancodeprecos.com.br), para aux&iacute;lio nas pesquisas e compara&ccedil;&otilde;es de pre&ccedil;os praticados pela Administra&ccedil;&atilde;o P&uacute;blica, por um per&iacute;odo de mais 12 (doze) meses, conforme previs&atilde;o da Cl&aacute;usula D&eacute;cima Segunda do referido Contrato e em obedi&ecirc;ncia ao disposto no art. 57, inciso II, da Lei Federal n&ordm; 8.666\/1993, bem como o reajuste do valor contratado mediante a aplica&ccedil;&atilde;o do &Iacute;ndice Nacional de Pre&ccedil;os ao Consumidor Amplo &#8211; IPCA.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_14503-407.pdf\" id=\"\" style=\"\" target=\"_blank\" title=\"\" rel=\"noopener\">PRIMEIRO TERMO ADITIVO AO CONTRATO N&ordm; 004\/2020 &#8211; CGE &#8211; Dila&ccedil;&atilde;o do prazo de vig&ecirc;ncia do \u200bContrato n&ordm; 04\/2020 &#8211; CGE por um per&iacute;odo de mais 30 (trinta) meses, com aplica&ccedil;&atilde;o da corre&ccedil;&atilde;o no valor dos servi&ccedil;os de Telefonia Fixa Comutada &#8211; STFC com base no &Iacute;ndice Nacional de Pre&ccedil;os ao Consumidor Amplo &#8211; IPCA\/IBGE.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_14519-c19.pdf\" target=\"\" rel=\"noopener\">SEGUNDO TERMO ADITIVO AO CONTRATO N&ordm; 001\/2021-CGE &#8211; Prorroga&ccedil;&atilde;o do prazo de vig&ecirc;ncia do Contrato n &ordm; 001\/2021-CGE, cujo objeto &eacute; a presta&ccedil;&atilde;o de servi&ccedil;os de loca&ccedil;&atilde;o de ve&iacute;culos, por um per&iacute;odo de mais 4 (quatro) meses, com fulcro no art. 57, inciso II e &sect; 2&ordm; , da Lei Federal n.&ordm; 8.666\/93.<\/a><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/controladoria\/wp-content\/uploads\/sites\/31\/2023\/02\/Anexo1_15331-451.pdf\" id=\"\" style=\"\" target=\"_blank\" title=\"\" rel=\"noopener\">Segundo Termo Aditivo ao Contrato n&ordm; 006\/2022 &#8211; Prorroga&ccedil;&atilde;o do Contrato n&ordm; 006\/2022-CGE por um per&iacute;odo de mais 12 (doze) meses, compreendendo o per&iacute;odo entre os dias 21 de outubro de 2023 a 20 de outubro de 2024, conforme previs&atilde;o do item 3.2, da CL&Aacute;USULA TERCEIRA &#8211; DO PRAZO DE VIG&Ecirc;NCIA, do instrumento Contratual e nos termos do no art. 57, II, da Lei n&deg; 8.666\/93.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRIMEIRO TERMO ADITIVO AO CONTRATO N&ordm; 006\/2022-CGE &#8211; Aditamento de aproximadamente 23,93% do Contrato 006\/2022 &#8211; CGE, em raz&atilde;o de acr&eacute;scimos de deslocamentos para a participa&ccedil;&atilde;o em cursos, eventos, semin&aacute;rios, congressos, principalmente eventos do Conselho Nacional de Controle Interno (CONACI), visando o desenvolvimento profissional dos servidores, capacita&ccedil;&otilde;es t&eacute;cnicas e afins, conforme art. 65, &sect; 1&ordm;, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-10076","post","type-post","status-publish","format-standard","hentry","category-pregoes-eletronicos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"jackelinebastos","author_link":"https:\/\/goias.gov.br\/controladoria\/author\/jackelinebastos\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/controladoria\/categoria\/pregoes-eletronicos\/\" rel=\"category tag\">Preg\u00f5es Eletr\u00f4nicos<\/a>","rttpg_excerpt":"PRIMEIRO TERMO ADITIVO AO CONTRATO N&ordm; 006\/2022-CGE &#8211; Aditamento de aproximadamente 23,93% do Contrato 006\/2022 &#8211; CGE, em raz&atilde;o de acr&eacute;scimos de deslocamentos para a participa&ccedil;&atilde;o em cursos, eventos, semin&aacute;rios, congressos, principalmente eventos do Conselho Nacional de Controle Interno (CONACI), visando o desenvolvimento profissional dos servidores, capacita&ccedil;&otilde;es t&eacute;cnicas e afins, conforme art. 65, &sect; 1&ordm;,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/10076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/comments?post=10076"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/posts\/10076\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/media?parent=10076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/categories?post=10076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/controladoria\/wp-json\/wp\/v2\/tags?post=10076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}