

{"id":352,"date":"2021-03-30T15:27:25","date_gmt":"2021-03-30T18:27:25","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/comunicacao\/secom-realiza-chamada-de-sessao-publica\/"},"modified":"2023-09-13T15:18:23","modified_gmt":"2023-09-13T18:18:23","slug":"secom-realiza-chamada-de-sessao-publica","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/comunicacao\/secom-realiza-chamada-de-sessao-publica\/","title":{"rendered":"Secom realiza chamada de sess\u00e3o p\u00fablica"},"content":{"rendered":"<p style=\"text-align: justify;\">A SECRETARIA DE ESTADO DE COMUNICA&Ccedil;&Atilde;O (SECOM), pessoa jur&iacute;dica de direito p&uacute;blico, inscrita no CNPJ sob o n&ordm; 32.785.209\/0001-02, torna p&uacute;blico, para conhecimento dos interessados, que far&aacute; realizar sess&atilde;o p&uacute;blica para coleta e abertura dos envelopes de or&ccedil;amentos de bens ou servi&ccedil;os especializados, previstos no artigo 14, &sect; 2&ordm;, da Lei federal n&ordm; 12.232, de 29 de abril de 2010, resultando na sele&ccedil;&atilde;o, com base em crit&eacute;rios t&eacute;cnicos, da proposta de menor pre&ccedil;o.<br \/>\nData: 31\/03\/2021<br \/>\nHora: 15h (hor&aacute;rio de Bras&iacute;lia-DF)<br \/>\nLocal: Logos Propaganda situada em 1&ordf; Av. n&deg; 10 &ndash; 2&deg; andar &ndash; Condom&iacute;nio Cidade Empresarial &ndash; Cidade Vera Cruz &ndash; Aparecida de Goi&acirc;nia &ndash; GO. CEP 74.935-900.<br \/>\nPara mais informa&ccedil;&otilde;es sobre o objeto da contrata&ccedil;&atilde;o os interessados dever&atilde;o baixar o documento da sess&atilde;o p&uacute;blica, LINK: (<a href=\"https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/ChamamentoPublico-bf8.pdf\" id=\"\" style=\"\" target=\"\" title=\"\" rel=\"noopener\">CHAMAMENTO&nbsp;P&Uacute;BLICO N&ordm;: 05\/2021 \/2021 &#8211; SECOM<\/a>)&nbsp;e seguir as orienta&ccedil;&otilde;es constante no documento.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A SECRETARIA DE ESTADO DE COMUNICA&Ccedil;&Atilde;O (SECOM), pessoa jur&iacute;dica de direito p&uacute;blico, inscrita no CNPJ sob o n&ordm; 32.785.209\/0001-02, torna p&uacute;blico, para conhecimento dos interessados, que far&aacute; realizar sess&atilde;o p&uacute;blica para coleta e abertura dos envelopes de or&ccedil;amentos de bens ou servi&ccedil;os especializados, previstos no artigo 14, &sect; 2&ordm;, da Lei federal n&ordm; 12.232, de [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122.jpg",516,316,false],"landscape":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122.jpg",516,316,false],"portraits":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122.jpg",516,316,false],"thumbnail":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122-300x184.jpg",300,184,true],"large":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122.jpg",516,316,false],"1536x1536":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122.jpg",516,316,false],"2048x2048":["https:\/\/goias.gov.br\/comunicacao\/wp-content\/uploads\/sites\/10\/2021\/03\/Cha4-122.jpg",516,316,false]},"rttpg_author":{"display_name":"andrelrv","author_link":"https:\/\/goias.gov.br\/comunicacao\/author\/andrelrv\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/comunicacao\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"A SECRETARIA DE ESTADO DE COMUNICA&Ccedil;&Atilde;O (SECOM), pessoa jur&iacute;dica de direito p&uacute;blico, inscrita no CNPJ sob o n&ordm; 32.785.209\/0001-02, torna p&uacute;blico, para conhecimento dos interessados, que far&aacute; realizar sess&atilde;o p&uacute;blica para coleta e abertura dos envelopes de or&ccedil;amentos de bens ou servi&ccedil;os especializados, previstos no artigo 14, &sect; 2&ordm;, da Lei federal n&ordm; 12.232, de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/posts\/352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/comments?post=352"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/posts\/352\/revisions"}],"predecessor-version":[{"id":761,"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/posts\/352\/revisions\/761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/media\/350"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/media?parent=352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/categories?post=352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/comunicacao\/wp-json\/wp\/v2\/tags?post=352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}