{"id":7537,"date":"2023-10-16T12:01:04","date_gmt":"2023-10-16T15:01:04","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/ceasa\/plano-estrategia-institucional\/"},"modified":"2026-05-29T11:46:50","modified_gmt":"2026-05-29T14:46:50","slug":"plano-estrategia-institucional","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/ceasa\/plano-estrategia-institucional\/","title":{"rendered":"Plano de Neg\u00f3cios\/Estrat\u00e9gia Institucional"},"content":{"rendered":"<p data-start=\"228\" data-end=\"567\">A Centrais de Abastecimento de Goi\u00e1s S\/A \u2013 CEASA-GO informa que, por ser uma empresa com receita operacional bruta inferior a R$ 90.000.000,00 (noventa milh\u00f5es de reais) no exerc\u00edcio social anterior, <strong data-start=\"428\" data-end=\"496\">n\u00e3o est\u00e1 obrigada \u00e0 elabora\u00e7\u00e3o e divulga\u00e7\u00e3o de Plano Estrat\u00e9gico<\/strong>, conforme os par\u00e2metros legais aplic\u00e1veis a empresas de pequeno porte.<\/p>\n<p data-start=\"569\" data-end=\"753\">Essa orienta\u00e7\u00e3o visa adequar as exig\u00eancias de planejamento e governan\u00e7a \u00e0 realidade e ao porte da empresa, respeitando a legisla\u00e7\u00e3o vigente e promovendo a efici\u00eancia na gest\u00e3o p\u00fablica.<\/p>\n<ul>\n<li><a href=\"https:\/\/goias.gov.br\/ceasa\/wp-content\/uploads\/sites\/48\/2025\/07\/Estrategicas_a_Logo_Prazo.pdf\">Estrat\u00e9gia de longo prazo e Plano de neg\u00f3cios\u00a0 2025<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/ceasa\/wp-content\/uploads\/sites\/48\/2024\/07\/Estrategicas_a_Logo_Prazo_2024_2028-1_compressed.pdf\">Estrat\u00e9gia de longo prazo e Plano de neg\u00f3cios\u00a0 2024<\/a><\/li>\n<li><a title=\"\" href=\"https:\/\/goias.gov.br\/ceasa\/wp-content\/uploads\/sites\/48\/2023\/10\/Plano_de_Negocios_2023_e_Estrategia_de_Longo_Prazo_2023_2027_CEASA_GO-9b6.pdf\" target=\"_blank\" rel=\"noopener\">Estrat\u00e9gia de longo prazo e Plano de neg\u00f3cios\u00a0 2023<\/a><\/li>\n<li><a title=\"\" href=\"https:\/\/goias.gov.br\/ceasa\/wp-content\/uploads\/sites\/48\/2023\/10\/MINUTA_Plano_de_Negocios_2022_e_Estrategia_de_longo_prazo_2022_a_2026-ceb.pdf\" target=\"_blank\" rel=\"noopener\">Estrat\u00e9gia de longo prazo e Plano de neg\u00f3cios\u00a0 2022<\/a><\/li>\n<li><a title=\"\" href=\"https:\/\/goias.gov.br\/ceasa\/wp-content\/uploads\/sites\/48\/2023\/10\/Estrategia_de_longo_prazo_2021_2025_versao_final-0b8.pdf\" target=\"_blank\" rel=\"noopener\">Estrat\u00e9gia de longo prazo e Plano de neg\u00f3cios\u00a0 2021<\/a><\/li>\n<\/ul>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Centrais de Abastecimento de Goi\u00e1s S\/A \u2013 CEASA-GO informa que, por ser uma empresa com receita operacional bruta inferior a R$ 90.000.000,00 (noventa milh\u00f5es de reais) no exerc\u00edcio social anterior, n\u00e3o est\u00e1 obrigada \u00e0 elabora\u00e7\u00e3o e divulga\u00e7\u00e3o de Plano Estrat\u00e9gico, conforme os par\u00e2metros legais aplic\u00e1veis a empresas de pequeno porte. Essa orienta\u00e7\u00e3o visa adequar [&hellip;]<\/p>\n","protected":false},"author":1158,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,64],"tags":[],"class_list":["post-7537","post","type-post","status-publish","format-standard","hentry","category-acesso-a-informacao","category-planejamento-e-prestacao-de-contas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"","author_link":"https:\/\/goias.gov.br\/ceasa\/author\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/ceasa\/categoria\/acesso-a-informacao\/\" rel=\"category tag\">Acesso \u00e0 Informa\u00e7\u00e3o<\/a> <a href=\"https:\/\/goias.gov.br\/ceasa\/categoria\/acesso-a-informacao\/planejamento-e-prestacao-de-contas\/\" rel=\"category tag\">Planejamento e Presta\u00e7\u00e3o de Contas<\/a>","rttpg_excerpt":"A Centrais de Abastecimento de Goi\u00e1s S\/A \u2013 CEASA-GO informa que, por ser uma empresa com receita operacional bruta inferior a R$ 90.000.000,00 (noventa milh\u00f5es de reais) no exerc\u00edcio social anterior, n\u00e3o est\u00e1 obrigada \u00e0 elabora\u00e7\u00e3o e divulga\u00e7\u00e3o de Plano Estrat\u00e9gico, conforme os par\u00e2metros legais aplic\u00e1veis a empresas de pequeno porte. Essa orienta\u00e7\u00e3o visa adequar&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/posts\/7537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/users\/1158"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/comments?post=7537"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/posts\/7537\/revisions"}],"predecessor-version":[{"id":39869,"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/posts\/7537\/revisions\/39869"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/media?parent=7537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/categories?post=7537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/ceasa\/wp-json\/wp\/v2\/tags?post=7537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}