{"id":21981,"date":"2017-11-08T13:11:01","date_gmt":"2017-11-08T15:11:01","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/casacivil\/contrato-no-015-2017\/"},"modified":"2017-11-08T13:11:01","modified_gmt":"2017-11-08T15:11:01","slug":"contrato-no-015-2017","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/casacivil\/contrato-no-015-2017\/","title":{"rendered":"CONTRATO N\u00ba 015-2017"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p><strong>CONTRATO N&deg; 015\/2017 &ndash; LIMPENCOL SERVI&Ccedil;OS GERAIS EIRELI &ndash; EPP &#8211; CNPJ: 03.790.751\/0001-47.<\/strong><\/p>\n<p><strong>Objeto:&nbsp;<\/strong>presta&ccedil;&atilde;o de servi&ccedil;os de limpeza, asseio e conserva&ccedil;&atilde;o de &aacute;reas internas\/externas, fornecimento de m&atilde;o-de-obra materiais e equipamentos, com &ecirc;nfase em manuten&ccedil;&otilde;es prediais preventivas e corretivas nas Unidades desta Secretaria, via ades&atilde;o &agrave; Ata de Registro de Pre&ccedil;os n&ordm;012\/2017, na condi&ccedil;&atilde;o de part&iacute;cipe &ldquo;a posteriori&rdquo;, da Secretaria Municipal da Educa&ccedil;&atilde;o Cultura, Esporte e Lazer da Prefeitura Municipal de Aragua&iacute;na-TO, pelo per&iacute;odo de 12 (doze) meses.<\/p>\n<p><strong>&nbsp;Valor Total: <\/strong>R$ 506.592,96 (quinhentos e seis mil, novecentos e dois reais e noventa e seis centavos).<\/p>\n<p><strong>Data da Assinatura: <\/strong>07 de novembro de 2017.<\/p>\n<p><strong>Vig&ecirc;ncia: <\/strong>07 de novembro de 2017 a 06 de novembro de 2018.<\/p>\n<p><strong>Processo n&ordm; <\/strong>201700013003711, de 23\/08\/2017.<\/p>\n<p><strong><a href=\"https:\/\/goias.gov.br\/casacivil\/wp-content\/uploads\/sites\/47\/2017\/11\/contrato-no_-015-2017-limpecol-limpeza-arquivo-2017000013003711-c08.pdf\">CONTRATO<\/a><\/strong>&nbsp;<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONTRATO N&deg; 015\/2017 &ndash; LIMPENCOL SERVI&Ccedil;OS GERAIS EIRELI &ndash; EPP &#8211; CNPJ: 03.790.751\/0001-47. Objeto:&nbsp;presta&ccedil;&atilde;o de servi&ccedil;os de limpeza, asseio e conserva&ccedil;&atilde;o de &aacute;reas internas\/externas, fornecimento de m&atilde;o-de-obra materiais e equipamentos, com &ecirc;nfase em manuten&ccedil;&otilde;es prediais preventivas e corretivas nas Unidades desta Secretaria, via ades&atilde;o &agrave; Ata de Registro de Pre&ccedil;os n&ordm;012\/2017, na condi&ccedil;&atilde;o de part&iacute;cipe [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[313],"tags":[],"class_list":["post-21981","post","type-post","status-publish","format-standard","hentry","category-contratos-2017"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/casacivil\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/casacivil\/categoria\/licitacoes-e-contratos\/contratos\/contratos-2017\/\" rel=\"category tag\">CONTRATOS 2017<\/a>","rttpg_excerpt":"CONTRATO N&deg; 015\/2017 &ndash; LIMPENCOL SERVI&Ccedil;OS GERAIS EIRELI &ndash; EPP &#8211; CNPJ: 03.790.751\/0001-47. Objeto:&nbsp;presta&ccedil;&atilde;o de servi&ccedil;os de limpeza, asseio e conserva&ccedil;&atilde;o de &aacute;reas internas\/externas, fornecimento de m&atilde;o-de-obra materiais e equipamentos, com &ecirc;nfase em manuten&ccedil;&otilde;es prediais preventivas e corretivas nas Unidades desta Secretaria, via ades&atilde;o &agrave; Ata de Registro de Pre&ccedil;os n&ordm;012\/2017, na condi&ccedil;&atilde;o de part&iacute;cipe&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/21981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/comments?post=21981"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/21981\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/media?parent=21981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/categories?post=21981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/tags?post=21981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}