

{"id":14500,"date":"2014-09-29T07:09:29","date_gmt":"2014-09-29T10:09:29","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/casacivil\/ato-de-inexigibilidade-de-licitacao-016-2014\/"},"modified":"2024-03-01T12:24:08","modified_gmt":"2024-03-01T15:24:08","slug":"ato-de-inexigibilidade-de-licitacao-016-2014","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/casacivil\/ato-de-inexigibilidade-de-licitacao-016-2014\/","title":{"rendered":"ATO DE INEXIGIBILIDADE DE LICITA\u00c7\u00c3O 016\/2014"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p><strong>ATO DE INEXIGIBILIDADE DE LICITA&Ccedil;&Atilde;O 016\/2014<\/strong><\/p>\n<p><strong>Objeto:&nbsp;<\/strong>Referente &agrave; contrata&ccedil;&atilde;o da empresa S-A O ESTADO DE S&Atilde;O PAULO, para fornecimento de 01 (uma) assinatura do jornal O ESTADO DE S&Atilde;O PAULO, para fornecimentos de edi&ccedil;&otilde;es di&aacute;rias por um per&iacute;odo de 12 (doze) meses, visando atender &agrave;s necessidades da Secretaria de Estado da Casa Civil.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contratada: EMPRESA &nbsp;S-A O ESTADO DE S&Atilde;O PAULO, CNPJ:61.533.949\/0001-41, valor de<\/strong>&nbsp;<strong>R$ 1.727,10 ( um mil setesentos e vinte e sete rais e dez centavos).<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/goias.gov.br\/casacivil\/?p=15991\"><img decoding=\"async\" src=\"images\/imagens_migradas\/seplan\/img\/pdf.gif\" alt=\"\" align=\"middle\" border=\"0\">Download do Ato de Inexigibilidade de Licita&ccedil;&atilde;o<\/a><\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ATO DE INEXIGIBILIDADE DE LICITA&Ccedil;&Atilde;O 016\/2014 Objeto:&nbsp;Referente &agrave; contrata&ccedil;&atilde;o da empresa S-A O ESTADO DE S&Atilde;O PAULO, para fornecimento de 01 (uma) assinatura do jornal O ESTADO DE S&Atilde;O PAULO, para fornecimentos de edi&ccedil;&otilde;es di&aacute;rias por um per&iacute;odo de 12 (doze) meses, visando atender &agrave;s necessidades da Secretaria de Estado da Casa Civil. &nbsp; Contratada: [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[303],"tags":[],"class_list":["post-14500","post","type-post","status-publish","format-standard","hentry","category-inexigibilidade-de-licitacao-2014"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/casacivil\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/casacivil\/categoria\/licitacoes-e-contratos\/inexigibilidade-de-licitacao\/inexigibilidade-de-licitacao-2014\/\" rel=\"category tag\">Inexigibilidade de Licita\u00e7\u00e3o 2014<\/a>","rttpg_excerpt":"ATO DE INEXIGIBILIDADE DE LICITA&Ccedil;&Atilde;O 016\/2014 Objeto:&nbsp;Referente &agrave; contrata&ccedil;&atilde;o da empresa S-A O ESTADO DE S&Atilde;O PAULO, para fornecimento de 01 (uma) assinatura do jornal O ESTADO DE S&Atilde;O PAULO, para fornecimentos de edi&ccedil;&otilde;es di&aacute;rias por um per&iacute;odo de 12 (doze) meses, visando atender &agrave;s necessidades da Secretaria de Estado da Casa Civil. &nbsp; Contratada:&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/14500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/comments?post=14500"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/14500\/revisions"}],"predecessor-version":[{"id":26014,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/14500\/revisions\/26014"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/media?parent=14500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/categories?post=14500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/tags?post=14500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}