{"id":13554,"date":"2012-07-26T08:07:39","date_gmt":"2012-07-26T11:07:39","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/casacivil\/ato-de-inexigibilidade-022-2012\/"},"modified":"2012-07-26T08:07:39","modified_gmt":"2012-07-26T11:07:39","slug":"ato-de-inexigibilidade-022-2012","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/casacivil\/ato-de-inexigibilidade-022-2012\/","title":{"rendered":"ATO DE INEXIGIBILIDADE 022\/2012"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<div id=\"texto\">\n<p><strong>ATO DE INEXIGIBILIDADE 022\/2012<\/strong><\/p>\n<p><strong>Objeto: <\/strong>contrata&ccedil;&atilde;o de empresa&nbsp; para o fornecimento de 01 (uma) assinatura do jornal &ldquo;O ESTADO DE S&Atilde;O PAULO&rdquo;, para fornecimento de edi&ccedil;&otilde;es di&aacute;rias, por um per&iacute;odo de 12 (doze) meses, visando atender &agrave;s necessidades da Secretaria de Estado da Casa Civil.<\/p>\n<p><strong><\/strong><strong>Contratada<\/strong>:<strong>S\/A O ESTADO DE S&Atilde;O PAULO, CNPJ: 61.533.949\/0001-41<\/strong>&nbsp;. <strong>Valor: R$ 1.635,00 (um mil, seiscentos e trinta e cinco reais).<\/strong><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/casacivil\/wp-content\/uploads\/sites\/47\/2012\/07\/022-estado-de-sao-paulo-6e6.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"images\/imagens_migradas\/seplan\/img\/pdf.gif\" alt=\"\" align=\"middle\" border=\"0\">&nbsp;Download do Ato de Inexigibilidade<\/a><\/p>\n<\/div>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ATO DE INEXIGIBILIDADE 022\/2012 Objeto: contrata&ccedil;&atilde;o de empresa&nbsp; para o fornecimento de 01 (uma) assinatura do jornal &ldquo;O ESTADO DE S&Atilde;O PAULO&rdquo;, para fornecimento de edi&ccedil;&otilde;es di&aacute;rias, por um per&iacute;odo de 12 (doze) meses, visando atender &agrave;s necessidades da Secretaria de Estado da Casa Civil. Contratada:S\/A O ESTADO DE S&Atilde;O PAULO, CNPJ: 61.533.949\/0001-41&nbsp;. Valor: R$ [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[295],"tags":[],"class_list":["post-13554","post","type-post","status-publish","format-standard","hentry","category-inexigibilidade-de-licitacao-2012"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/casacivil\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/casacivil\/categoria\/licitacoes-e-contratos\/inexigibilidade-de-licitacao\/inexigibilidade-de-licitacao-2012\/\" rel=\"category tag\">Inexigibilidade de Licita\u00e7\u00e3o 2012<\/a>","rttpg_excerpt":"ATO DE INEXIGIBILIDADE 022\/2012 Objeto: contrata&ccedil;&atilde;o de empresa&nbsp; para o fornecimento de 01 (uma) assinatura do jornal &ldquo;O ESTADO DE S&Atilde;O PAULO&rdquo;, para fornecimento de edi&ccedil;&otilde;es di&aacute;rias, por um per&iacute;odo de 12 (doze) meses, visando atender &agrave;s necessidades da Secretaria de Estado da Casa Civil. Contratada:S\/A O ESTADO DE S&Atilde;O PAULO, CNPJ: 61.533.949\/0001-41&nbsp;. Valor: R$&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/13554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/comments?post=13554"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/13554\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/media?parent=13554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/categories?post=13554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/tags?post=13554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}