{"id":13259,"date":"2012-04-13T11:04:49","date_gmt":"2012-04-13T14:04:49","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/casacivil\/compra-direta-no-013-2012\/"},"modified":"2012-04-13T11:04:49","modified_gmt":"2012-04-13T14:04:49","slug":"compra-direta-no-013-2012","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/casacivil\/compra-direta-no-013-2012\/","title":{"rendered":"COMPRA DIRETA N\u00ba 013\/2012"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p><strong>COMPRA DIRETA N&ordm; 013\/2012<\/strong><strong><br \/><strong>Tipo: <\/strong><\/strong>Menor&nbsp;pre&ccedil;o<strong>.<\/strong><strong><br \/><strong>Abertura: <\/strong><\/strong>18\/04\/2012 &agrave;s 09:00 horas. <span style=\"color: #ff0000;\">FRACASSADO.<\/span><br \/><strong>Objeto:<\/strong> Contrata&ccedil;&atilde;o de empresa especializada na confec&ccedil;&atilde;o de cart&otilde;es de visita para atender as necessidades da Secretaria de Estado da Casa Civil.<\/p>\n<p><strong>Nova abertura: 23<\/strong>\/04\/2012 &agrave;s 08:00 horas. <span style=\"color: #ff0000;\">FRACASSADO<\/span><\/p>\n<p><span style=\"color: #000000;\">Nova abertura: 27\/04\/2012 &agrave;s 08:00 horas<\/span><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/casacivil\/wp-content\/uploads\/sites\/47\/2012\/04\/termo-de-referencia-cartao-visita-cilene-guim-modificado-cf7.doc\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"images\/imagens_migradas\/seplan\/img\/pdf.gif\" alt=\"\" align=\"middle\" border=\"0\">&nbsp;Download do Termo de Refer&ecirc;ncia<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMPRA DIRETA N&ordm; 013\/2012Tipo: Menor&nbsp;pre&ccedil;o.Abertura: 18\/04\/2012 &agrave;s 09:00 horas. FRACASSADO.Objeto: Contrata&ccedil;&atilde;o de empresa especializada na confec&ccedil;&atilde;o de cart&otilde;es de visita para atender as necessidades da Secretaria de Estado da Casa Civil. Nova abertura: 23\/04\/2012 &agrave;s 08:00 horas. FRACASSADO Nova abertura: 27\/04\/2012 &agrave;s 08:00 horas &nbsp;Download do Termo de Refer&ecirc;ncia &nbsp;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[286],"tags":[],"class_list":["post-13259","post","type-post","status-publish","format-standard","hentry","category-compra-direta-2012"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/casacivil\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/casacivil\/categoria\/licitacoes-e-contratos\/compra-direta\/compra-direta-2012\/\" rel=\"category tag\">Compra Direta 2012<\/a>","rttpg_excerpt":"COMPRA DIRETA N&ordm; 013\/2012Tipo: Menor&nbsp;pre&ccedil;o.Abertura: 18\/04\/2012 &agrave;s 09:00 horas. FRACASSADO.Objeto: Contrata&ccedil;&atilde;o de empresa especializada na confec&ccedil;&atilde;o de cart&otilde;es de visita para atender as necessidades da Secretaria de Estado da Casa Civil. Nova abertura: 23\/04\/2012 &agrave;s 08:00 horas. FRACASSADO Nova abertura: 27\/04\/2012 &agrave;s 08:00 horas &nbsp;Download do Termo de Refer&ecirc;ncia &nbsp;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/13259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/comments?post=13259"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/posts\/13259\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/media?parent=13259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/categories?post=13259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/casacivil\/wp-json\/wp\/v2\/tags?post=13259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}