

{"id":69601,"date":"2021-09-29T09:52:42","date_gmt":"2021-09-29T12:52:42","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/agr\/comportamento-etico-e-sobretudo-uma-questao-cultural\/"},"modified":"2021-09-29T09:52:42","modified_gmt":"2021-09-29T12:52:42","slug":"comportamento-etico-e-sobretudo-uma-questao-cultural","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/agr\/comportamento-etico-e-sobretudo-uma-questao-cultural\/","title":{"rendered":"\u201cComportamento \u00e9tico \u00e9, sobretudo, uma quest\u00e3o cultural\u201d"},"content":{"rendered":"<hr \/>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-69600\" alt=\"\" height=\"314\" id=\"\" src=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6.png\" title=\"\" width=\"558\" srcset=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6.png 1280w, https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6-300x169.png 300w, https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6-1024x576.png 1024w, https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6-768x432.png 768w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/p>\n<p style=\"text-align: center;\">Card: <em>AGR<\/em><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><em>Afirma&ccedil;&atilde;o &eacute; do professor Rafael Rocha de Macedo, doutor em Teoria Geral do Direito e Filosofia pela USP e chefe de Gabinete da Ag&ecirc;ncia Goiana de Regula&ccedil;&atilde;o, em palestra nesta ter&ccedil;a-feira (28\/09) sobre o tema &ldquo;A &Eacute;tica e o Programa de Compliance P&uacute;blico na AGR&rdquo;<\/em><\/p>\n<p style=\"text-align: justify;\">A Ag&ecirc;ncia Goiana de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos (AGR) realizou, nesta ter&ccedil;a-feira (28\/09), mais um evento no &acirc;mbito do Programa de Compliance P&uacute;blico do Governo de Goi&aacute;s. Desta vez, a palestra on-line foi feita pelo professor Rafael Rocha de Macedo, doutor em Teoria Geral do Direito e Filosofia, diretor presidente da Uni&atilde;o dos Escoteiros do Brasil e chefe de Gabinete da Presid&ecirc;ncia da AGR. Ele tratou do tema &ldquo;A &Eacute;tica e o Programa de Compliance P&uacute;blico na AGR&rdquo;, reunindo 39 servidores.<\/p>\n<p style=\"text-align: justify;\">Ap&oacute;s uma breve explica&ccedil;&atilde;o sobre o movimento de combate &agrave; corrup&ccedil;&atilde;o no mundo, que teve a ades&atilde;o do Brasil, e a cria&ccedil;&atilde;o de programas de compliance pelas empresas, pelos estados, munic&iacute;pios, e pela Uni&atilde;o, Rafael Rocha de Macedo falou do que significa o programa de compliance no ambiente de trabalho. &ldquo;Diz respeito ao comportamento &eacute;tico, que diz respeito &agrave; consci&ecirc;ncia moral; estamos falando, sobretudo, de uma quest&atilde;o cultural&rdquo;, destacou.<\/p>\n<p style=\"text-align: justify;\">Segundo o palestrante, esse comportamento diz respeito a quem somos, aos nossos valores morais, ao que &eacute; pessoal e o que &eacute; coletivo, ao que &eacute; natural e ao que se refere &agrave;s nossas escolhas, diz respeito a sopesar a vida pessoal e a profissional. Rafael Rocha de Macedo falou tamb&eacute;m dos padr&otilde;es, que, conforme explicou, &ldquo;definem o julgamento da conduta humana e o que a gente leva em considera&ccedil;&atilde;o no momento de tomar decis&otilde;es&rdquo;. Para ele, o padr&atilde;o de comportamento diz respeito, ainda, ao nosso entendimento do que &eacute; certo e do que &eacute; errado, do que &eacute; bom ou &eacute; mau, do que &eacute; justo ou injusto, do que &eacute; legal ou ilegal.<\/p>\n<p style=\"text-align: justify;\">\n&ldquo;Quando falamos de programa de integridade, estamos falando de cultura. Quando a gente fala de programa de integridade dentro do ambiente de trabalho, a gente est&aacute; falando da cria&ccedil;&atilde;o e da dissemina&ccedil;&atilde;o de um consenso do que &eacute; correto ou incorreto dentro do ambiente de trabalho, em que se respeita os valores e princ&iacute;pios da institui&ccedil;&atilde;o&rdquo;, observou o palestrante. E lembrou que, para isso, os pilares da &eacute;tica profissional s&atilde;o universais: a honestidade, a coragem de assumir decis&otilde;es, a toler&acirc;ncia\/flexibilidade, a integridade na adversidade, humildade e trabalho em equipe.<\/p>\n<p style=\"text-align: justify;\">Em seguida, Rafael Rocha explicou que a maioria das pessoas pode ser convencida a aderir a um programa de integridade. Apresentou uma pesquisa sobre a flexibilidade das pessoas diante de uma nova ideia, como a do programa de integridade, mostrando que 69% s&atilde;o flex&iacute;veis desde que sejam convencidas; 20% aderem prontamente e outras 11% n&atilde;o aderem. Ele apresentou um v&iacute;deo ilustrativo para refor&ccedil;ar essa quest&atilde;o da flexibilidade.<\/p>\n<p style=\"text-align: justify;\">Ao falar da &Eacute;tica na Pr&aacute;tica, o palestrante enfatizou que um programa de Compliance precisa do comprometimento da alta administra&ccedil;&atilde;o com o programa para ser exemplo para os demais. &Eacute; preciso, tamb&eacute;m, disseminar a cultura da &eacute;tica organizacional; pol&iacute;ticas internas com regras simples a serem seguidas; o c&oacute;digo de &eacute;tica; treinamentos e cursos sobre &eacute;tica, integridade, gest&atilde;o de riscos; acompanhamento de conselheiros externos e independentes; e mecanismos de controle, ouvidoria e canais de den&uacute;ncia.<\/p>\n<p style=\"text-align: justify;\">Rafael de Macedo tamb&eacute;m refor&ccedil;ou os benef&iacute;cios de uma organiza&ccedil;&atilde;o &eacute;tica. &ldquo;Boas pr&aacute;ticas de governan&ccedil;a, preven&ccedil;&atilde;o e redu&ccedil;&atilde;o de riscos, redu&ccedil;&atilde;o do grau de responsabilidade e exposi&ccedil;&atilde;o da alta administra&ccedil;&atilde;o, aumento da efici&ecirc;ncia e grau de satisfa&ccedil;&atilde;o no trabalho, redu&ccedil;&atilde;o da incid&ecirc;ncia de fraudes, evita san&ccedil;&otilde;es legais e perdas financeiras, resguarda a integridade dos servidores, atrai talentos e ret&eacute;m bons profissionais&rdquo;.&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Comportamentos anti&eacute;ticos<\/strong><br \/>\nDepois, o palestrante explicou porque ocorrem os comportamentos anti&eacute;ticos, a partir da imagem do tri&acirc;ngulo da fraude, refor&ccedil;ando que tr&ecirc;s fatores contribuem para esses comportamentos. O primeiro deles &eacute; a oportunidade de cometimento (capacidade, habilidade, fun&ccedil;&atilde;o, n&iacute;vel hier&aacute;rquico, conhecimento, informa&ccedil;&otilde;es necess&aacute;rias para a pessoa cometer a fraude, al&eacute;m da fragilidade do controle interno da institui&ccedil;&atilde;o).<\/p>\n<p style=\"text-align: justify;\">&nbsp;O segundo fator &eacute; a motiva&ccedil;&atilde;o ou press&atilde;o, podendo ser de cunho pessoal ou organizacional (problemas pessoais, revers&atilde;o dos neg&oacute;cios, isolamento f&iacute;sico, busca por status financeiro e relacionamento entre empregador e empregado). E o terceiro &eacute; a racionaliza&ccedil;&atilde;o (para que a fraude seja cometida, o indiv&iacute;duo precisa encontrar uma justificativa para si e para os outros que determina que a a&ccedil;&atilde;o n&atilde;o &eacute; errada). Aqui ocorre, n&atilde;o raro, a flexibiliza&ccedil;&atilde;o da &eacute;tica.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Rafael Rocha de Macedo apresentou, tamb&eacute;m, uma pesquisa global sobre os crimes econ&ocirc;micos no Brasil, que mostra que 44% as empresas brasileiras possuem fraudes no processo de compras; que 74% dizem que a oportunidade &eacute; o fator principal que leva o fraudador a cometer um crime econ&ocirc;mico, seguido da press&atilde;o e da racionaliza&ccedil;&atilde;o, ambas com 13%.&nbsp;<\/p>\n<p style=\"text-align: justify;\">A mesma pesquisa mostra que 64% das fraudes s&atilde;o de origem interna, ou seja, com a participa&ccedil;&atilde;o de funcion&aacute;rios; que 35% dos fraudadores s&atilde;o gestores e o mesmo percentual s&atilde;o de membros da equipe; que 87% s&atilde;o homens; que 52% t&ecirc;m entre 31 e 40 anos de idade; e que 74% dos entrevistados acreditam que os crimes ocorreram porque houve falhas que permitiram a fraude.<\/p>\n<p style=\"text-align: justify;\"><strong>Ag&ecirc;ncia Goiana de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos (AGR) &ndash; Governo de Goi&aacute;s<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Card: AGR Afirma&ccedil;&atilde;o &eacute; do professor Rafael Rocha de Macedo, doutor em Teoria Geral do Direito e Filosofia pela USP e chefe de Gabinete da Ag&ecirc;ncia Goiana de Regula&ccedil;&atilde;o, em palestra nesta ter&ccedil;a-feira (28\/09) sobre o tema &ldquo;A &Eacute;tica e o Programa de Compliance P&uacute;blico na AGR&rdquo; A Ag&ecirc;ncia Goiana de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o [&hellip;]<\/p>\n","protected":false},"author":874,"featured_media":69600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-69601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6.png",1280,720,false],"landscape":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6.png",1280,720,false],"portraits":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6.png",1280,720,false],"thumbnail":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6-150x150.png",150,150,true],"medium":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6-300x169.png",300,169,true],"large":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6-1024x576.png",1024,576,true],"1536x1536":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6.png",1280,720,false],"2048x2048":["https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2021\/09\/comportamento-etico-PCP-cb6.png",1280,720,false]},"rttpg_author":{"display_name":"anafsouza","author_link":"https:\/\/goias.gov.br\/agr\/author\/anafsouza\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/agr\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Card: AGR Afirma&ccedil;&atilde;o &eacute; do professor Rafael Rocha de Macedo, doutor em Teoria Geral do Direito e Filosofia pela USP e chefe de Gabinete da Ag&ecirc;ncia Goiana de Regula&ccedil;&atilde;o, em palestra nesta ter&ccedil;a-feira (28\/09) sobre o tema &ldquo;A &Eacute;tica e o Programa de Compliance P&uacute;blico na AGR&rdquo; A Ag&ecirc;ncia Goiana de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/69601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/users\/874"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/comments?post=69601"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/69601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/media\/69600"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/media?parent=69601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/categories?post=69601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/tags?post=69601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}