{"id":66096,"date":"2018-09-04T11:21:47","date_gmt":"2018-09-04T14:21:47","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/agr\/atos-do-presidente-do-conselho-regulador\/"},"modified":"2024-02-06T16:56:18","modified_gmt":"2024-02-06T19:56:18","slug":"atos-do-presidente-do-conselho-regulador","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/agr\/atos-do-presidente-do-conselho-regulador\/","title":{"rendered":"Atos do Presidente do Conselho Regulador"},"content":{"rendered":"<h2>2014<\/h2>\n<ul>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselheiro-presidente-de-2014\/\">Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2014<\/a><\/li>\n<\/ul>\n<h2>2013<\/h2>\n<ul>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselheiro-presidente-de-2013\/\">Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2013<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/portarias-de-2013\/\">Portarias de 2013<\/a><\/li>\n<\/ul>\n<h2>2012<\/h2>\n<ul>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselheiro-presidente-de-2012\/\">Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 001-100<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselheiro-presidente-de-2012-101-200\/\">Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 101-200<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselheiro-presidente-de-2012-201-300\/\">Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 201-300<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselheiro-presidente-de-2012-301-400\/\">Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 301-400<\/a><\/li>\n<\/ul>\n<h2>2011<\/h2>\n<ul>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/avisos-de-2011\/\">Avisos<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/portarias-2011\/\">Portarias<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/notificacoes\/\">Notifica&ccedil;&otilde;es<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/resolucoes-2011\/\">Resolu&ccedil;&otilde;es<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>2014 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2014 2013 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2013 Portarias de 2013 2012 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 001-100 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 101-200 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 201-300 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 301-400 2011 [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-66096","post","type-post","status-publish","format-standard","hentry","category-conselho-regulador"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/agr\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/agr\/categoria\/institucional\/conselho-regulador\/\" rel=\"category tag\">Conselho Regulador<\/a>","rttpg_excerpt":"2014 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2014 2013 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2013 Portarias de 2013 2012 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 001-100 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 101-200 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 201-300 Resolu&ccedil;&otilde;es do Conselheiro Presidente de 2012 &#8211; de 301-400 2011&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/66096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/comments?post=66096"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/66096\/revisions"}],"predecessor-version":[{"id":73155,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/66096\/revisions\/73155"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/media?parent=66096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/categories?post=66096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/tags?post=66096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}