{"id":65495,"date":"2014-04-01T07:04:57","date_gmt":"2014-04-01T10:04:57","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/agr\/re\/"},"modified":"2014-04-01T07:04:57","modified_gmt":"2014-04-01T10:04:57","slug":"re","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/agr\/re\/","title":{"rendered":"Resolu\u00e7\u00f5es do Conselho Regulador 2013 de 1901 &#8211; 2000"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<ul>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1901-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2012-8719-expresso-satelite-norte-ltda-db0.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1901 de 13 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856480, em nome da empresa Expresso Sat&eacute;lite Norte Ltda, conforme processo n&ordm; 201200029008719.&nbsp;&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1902-2013-cr-manter-c-def.-res.-233-antt-2012-9625-turismo-abc-ltda-me-7ad.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1902 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.546, em nome da empresa Turismo ABC Ltda &#8211; ME, conforme processo n&ordm; 201200029009625.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1903-2013-cr-manter-c-def.-res.-233-antt-2012-7387-guilherme-e-carmo-ltda-937.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1903 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.358, em nome da empresa Guilherme e Carmo Ltda, conforme processo n&ordm; 201200029007387.&nbsp;&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1904-2013-cr-manter-c-def.-res.-233-antt-2012-5685-marcos-antonio-alves-941.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1904 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.992, em nome de Marcos Ant&ocirc;nio Alves, conforme processo n&ordm; 201200029005685.&nbsp;&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1905-2013-cr-manter-c-def.-res.-233-antt-2012-9273-brasil-turismo-ltda-5e4.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1905 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.932, em nome da empresa Brasil Turismo e Fretamento Ltda, conforme processo n&ordm; 201200029009273.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1906-2013-cr-manter-c-def.-res.-233-antt-2009-11796-sanara-transporte-ltda-8de.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1906 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 822015, em nome da empresa Sanara Transporte e Turismo Ltda, conforme processo n&ordm; 201200029011796.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1907-2013-cr-manter-c-def.-res.-233-antt-2012-7399-center-tur-turismo-ltda-21d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1907 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.361, em nome da empresa Center Tur Turismo Ltda &#8211; EPP, conforme processo n&ordm; 201200029007399.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1908-2013-cr-anulacao-c-rec.-res.-231-2011-0283-saneago-avocado-1ff.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1908 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre a decis&atilde;o referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 051\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201100029000283.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1909-2013-cr-manter-pedido-revisao-trcf-2013-0691-expresso-maia-ltda-2f9.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1909 de 16 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o apresentado pela empresa Expresso Maia Ltda, referente ao Termo de Lan&ccedil;amento n&ordm; 176\/2013, conforme Processo n&ordm; 201300029000691.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1910-2013-cr-manter-c-rec.-res.-231-2009-5252-saneago-4b5.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1910 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 122\/2009, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029005252.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1911-2013-cr-manter-c-rec.-res.-231-2009-3250-saneago-055.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1911 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 090\/2009, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029003250.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1912-2013-cr-manter-c-rec.-res.-231-2009-3518-saneago-5ba.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1912 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 080\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029003518.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1913-2013-cr-manter-c-rec.-res.-231-2009-11255-saneago-7d0.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1913 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 064\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029011255.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1914-2013-cr-manter-c-rec.-res.-231-2011-3027-saneago-245.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1914 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 038\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201100029003027.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1915-2013-cr-manter-c-rec.-res.-231-2011-4110-saneago-1c8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1915 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 027\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201100029004110.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1916-2013-cr-manter-c-rec.-res.-231-2011-3064-saneago-7ba.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1916 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 039\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201100029003064.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1917-2013-cr-manter-c-rec.-res.-231-2011-5163-saneago-917.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1917 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 043\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201100029005163.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1918-2013-cr-manter-c-rec.-res.-231-2010-7721-saneago-501.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1918 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 010\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029007721.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1919-2013-cr-manter-c-rec.-res.-231-2009-5242-saneago-f31.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1919 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 107\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029005242.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1920-2013-cr-manter-c-rec.-res.-231-2009-5284-saneago-5d1.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1920 de 17 de dezembro de 2013<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 070\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029005284.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1921-2013-cr-manter-c-r-res.-005-2009-1991-master-transportes-ltda-4aa.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1921 de 18 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14104, em nome da empresa M&aacute;ster Transportes Ltda., conforme processo n&deg; 200900029011991&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1922-2013-cr-manter-c-r-res.-005-2010-3218-mangela-e-sousa-transportes-604.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1922 de 18 de dezembro de 2013<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14604, em nome da empresa Mangela e Sousa Transportes Ltda., conforme processo n&deg; 201000029003218<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1923-2013-cr-manter-c-r-res.-005-2011-4936-master-transporte-9cd.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1923 de 18 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22669, em nome da empresa UTB Uni&atilde;o Transporte Bras&iacute;lia Ltda., conforme processo n&deg; 201100029004936&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1924-2013-cr-manter-c-r-res.-005-2011-5534-cooperativa-dos-transportadores-566.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1924 de 18 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22856, em nome da empresa Cooperativa dos Transportadores de Passageiros do Estado de Goi&aacute;s.., conforme processo n&deg; 201100029005534&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1925-2013-cr-manter-c-r-res.-005-2012-5078-quality-transporte-df7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1925 de 18 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 24337, em nome da empresa Quality Transporte Escolar e Turismo Ltda.., conforme processo n&deg; 201200029005078&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1926-2013-cr-manter-c-r-res.-005-2009-1906-rio-tropical-transportes-ltda-e2f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1926 de 18 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 09283, em nome da empresa Rio Tropical Transportes Ltda., conforme processo n&deg; 200900029001906&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1927-2013-cr-manter-c-r-res.-005-2009-8969-andre-transporte-turismo-ltda-00b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1927 de 18 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 13742, em nome da empresa Andre Transporte Turismo Ltda., conforme processo n&deg; 200900029008969&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1928-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2009-9053-saneago-399.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1928 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 093\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029009053.&nbsp;&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1929-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2010-0226-saneago-e6c.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1929 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 074\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029000226.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1930-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2010-4917-saneago-7b7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1930 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 011\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029004917.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1931-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2010-8475-saneago-456.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1931 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 057\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029008475.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1932-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2010-8726-saneago-b0e.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1932 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 023\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029008726.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1933-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2009-11257-saneago-e00.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1933 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 082\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029011257.&nbsp;&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1934-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2009-6654-saneago-63b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1934 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 092\/2009, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029006654.&nbsp;<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2014\/04\/resolucao-no.-1935-2013-cr-manter-pedido-revisao-c-rec.-res.-231-2010-7499-saneago-dac.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1935 de 20 de dezembro de 2013<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre Pedido de Revis&atilde;o do Auto de Infra&ccedil;&atilde;o n&ordm; 127\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029007499.&nbsp;<\/li>\n<\/ul>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resolu&ccedil;&atilde;o n&deg; 1901 de 13 de dezembro de 2013&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856480, em nome da empresa Expresso Sat&eacute;lite Norte Ltda, conforme processo n&ordm; 201200029008719.&nbsp;&nbsp; Resolu&ccedil;&atilde;o n&deg; 1902 de 16 de dezembro de 2013&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.546, em nome da empresa Turismo ABC Ltda &#8211; ME, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-65495","post","type-post","status-publish","format-standard","hentry","category-conselho-regulador"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/agr\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/agr\/categoria\/institucional\/conselho-regulador\/\" rel=\"category tag\">Conselho Regulador<\/a>","rttpg_excerpt":"Resolu&ccedil;&atilde;o n&deg; 1901 de 13 de dezembro de 2013&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856480, em nome da empresa Expresso Sat&eacute;lite Norte Ltda, conforme processo n&ordm; 201200029008719.&nbsp;&nbsp; Resolu&ccedil;&atilde;o n&deg; 1902 de 16 de dezembro de 2013&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.546, em nome da empresa Turismo ABC Ltda &#8211; ME,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/65495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/comments?post=65495"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/65495\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/media?parent=65495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/categories?post=65495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/tags?post=65495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}