{"id":64050,"date":"2013-10-18T06:10:01","date_gmt":"2013-10-18T09:10:01","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/agr\/resolucoes-do-conselho-regulador-2013-de-1301-1400-2\/"},"modified":"2013-10-18T06:10:01","modified_gmt":"2013-10-18T09:10:01","slug":"resolucoes-do-conselho-regulador-2013-de-1301-1400-2","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselho-regulador-2013-de-1301-1400-2\/","title":{"rendered":"Resolu\u00e7\u00f5es do Conselho Regulador 2013 de 1301 &#8211; 1400"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<ul>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1301-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2012-6733-viacao-montes-belos-ltda-f09.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1301 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.503, em nome da empresaVia&ccedil;&atilde;o Montes Belos Ltda, conforme processo n&ordm; 201200029006733.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1302-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2012-6083-viacao-montes-belos-ltda-f60.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1302 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.490.477, em nome da empresa Via&ccedil;&atilde;o Montes Belos Ltda, conforme processo n&ordm; 201200029006083.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1303-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2012-5184-noerte-sul-adm.-em-transporte-0ff.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1303 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.460.226, em nome da empresa Norte Sul Administra&ccedil;&atilde;o em Transporte Rodovi&aacute;rio de Passageiros Ltda &#8211; ME, conforme processo n&ordm; 201200029005184.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1304-2013-cr-manter-c-def.-res.-233-antt-2009-6159-contagem-turismo-ltda-efd.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&deg; 1304 de 19 de setembro de 2013<\/strong><\/span>.<\/a>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 809265, em nome da empresa Contagem Turismo Ltda, conforme processo n&ordm; 200900029006159.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1305-2013-cr-manter-c-def.-res.-233-antt-2013-0042-ubiratan-transporte-e-turismo-ltda-742.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1305 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.959, em nome da empresa Ubiratan Transporte e Turismo Ltda, conforme processo n&ordm; 201300029000042.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1306-2013-cr-manter-c-def.-res.-233-antt-2012-6617-realsul-transporte-e-turismo-ltda-4c2.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1306 de 19 de setembro de 2013.<\/span><\/a>&nbsp;<\/strong><\/span>Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.402, em nome da empresa Realsul Transporte e Turismo Ltda, conforme processo n&ordm; 201200029006617.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1307-2013-cr-manter-c-def.-res.-233-antt-2010-6469-maicolm-silva-souza-841.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1307 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855002, em nome da empresa Maicolm Silva de Souza, conforme processo n&ordm; 201000029006469.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1308-2013-cr-manter-c-def.-res.-233-antt-2012-1014-expresso-sao-luiz-ltda-ac9.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1308 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.140, em nome da empresa Expresso S&atilde;o Luiz Ltda, conforme processo n&ordm; 201200029001014.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1309-2013-cr-manter-c-def.-res.-233-antt-2008-6117-transbrasiliana-transporte-ltda-409.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1309 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 582342, em nome da empresa Transbrasiliana Transporte e Turismo Ltda, conforme processo n&ordm; 200800029006117.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1310-2013-cr-manter-c-def.-res.-233-antt-2008-6115-transbrasiliana-transporte-ltda-fe3.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1310 de 19 de setembro de 2013<\/span><\/a>.<\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 581976, em nome da empresa Transbrasiliana Transporte e Turismo Ltda, conforme processo n&ordm; 200800029006115.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1311-2013-cr-manter-c-def.-res.-3075-antt-2011-7741-empresa-sto.-antonio-ltda-9f8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1311 de 19 de setembro de 2013.<\/span><\/a>&nbsp;<\/strong><\/span>Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.430.998, em nome da Empresa Santo Ant&ocirc;nio Transportes e Turismo Ltda, conforme processo n&ordm; 201100029007741.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1312-2013-cr-manter-c-def.-res.-3075-antt-2010-1184-expresso-satelite-norte-ltda-4c3.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1312 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 822390, em nome da empresa Expresso Sat&eacute;lite Norte Ltda, conforme processo n&ordm; 201000029001184.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1313-2013-cr-manter-c-def.-res.-3075-antt-2010-5400-viacao-xavante-ltda-518.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1313 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856411, em nome da empresa Via&ccedil;&atilde;o Xavante Ltda, conforme processo n&ordm; 201000029005400.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1314-2013-cr-manter-c-def.-res.-3075-antt-2010-6134-viacao-sao-luiz-ltda-a08.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1314 de 19 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 809545, em nome daempresa Via&ccedil;&atilde;o S&atilde;o Luiz Ltda, conforme processo n&ordm; 201000029006134.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1315-2013-cr-manter-c-rec.-intempestivo-trcf-2013-0690-expresso-araguari-ltda-098.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1315 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do recurso interposto referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 175\/2013, em nome da empresa Expresso Araguari Ltda, conforme processo n&ordm; 201300029000690.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1316-2013-cr-manter-c-rec.-intempestivo-trcf-2013-2606-empresa-moreira-ltda-0af.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1316 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do recurso interposto referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 230\/2013, em nome da Empresa Moreira Ltda, conforme processo n&ordm; 201300029002606.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1317-2013-cr-manter-c-rec.-intempestivo-trcf-2012-4331-atantica-construcoes-ltda-683.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1317 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Bens e Servi&ccedil;os Desestatizados &ndash; CSBSD, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 039\/2012, em nome da empresa Atl&acirc;ntica Constru&ccedil;&otilde;es, Com&eacute;rcio e Servi&ccedil;o Ltda, conforme processo n&deg;201200029004331.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1318-2013-cr-manter-arquivo-s-rec.-res.-14.480-2012-0241-enedino-jose-da-silva-hotel-me-e37.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1318 de 26 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 23380, em nome de empresa Enedino Jos&eacute; da Silva Hotel &#8211; ME, conforme Processo n&ordm; 201200029000241.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1319-2013-cr-manter-c-rec.-intempestivo-res.-297-2011-4706-viacao-araguarina-cbc.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1319 de 24 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22605, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda.., conforme processo n&deg; 201100029004706.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1320-2013-cr-manter-c-rec.-nao-conhecido-res.-005-2008-9840-francisco-moreira-pimenta-me-dcf.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1320 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 09675, em nome da empresa Francisco Moreira Pimenta ME, conforme processo n&deg; 200800029009840.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1321-2013-cr-manter-c-rec.-nao-conhecido-res.-005-2009-2044-auto-viacao-goianesia-ltda.-0a4.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1321 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 09255, em nome da empresa Manoel Vaz Teodoro (Auto Via&ccedil;&atilde;o Goianesia Ltda.), conforme processo n&deg; 200900029002044 .<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1322-2013-cr-manter-c-r-lei-14480-2009-2688-jose-geraldo-de-medeiros-43f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1322 de 20 de setembro de 2013.<\/span><\/a>&nbsp;<\/strong><\/span>Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 10491, em nome da empresa Jos&eacute; Geraldo de Medeiros, conforme processo n&deg; 200900029002688.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1323-2013-cr-manter-c-r-lei-14480-2009-4652-carlos-alberto-costa-77b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1323 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 12538, em nome da empresa Carlos Alberto Costa, conforme processo n&deg; 200900029004652.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1324-2013-cr-manter-c-r-lei-14480-2010-6630-sandoval-santos-a0d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1324 de 20 de setembro de 2013.<\/span><\/a>&nbsp;<\/strong><\/span>Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 20566, em nome da empresa Sandoval Santos Silva, conforme processo n&deg; 201000029006630.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1325-2013-cr-manter-c-r-lei-14480-2010-3595-viacao-osasco-ltda.-688.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1325 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 16068, em nome da empresa Via&ccedil;&atilde;o Osasco Ltda., conforme processo n&deg; 201000029003595.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1326-2013-cr-manter-c-r-lei-14480-2010-5719-viacao-araguarina-ltda-20d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1326 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22637, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029004926.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1327-2013-cr-manter-c-r-lei-14480-2010-5719-viacao-araguarina-ltda-e13.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1327 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 15075, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029005719.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1328-2013-cr-manter-c-r-lei-14480-2010-1403-viacao-araguarina-ltda-2c6.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1328 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14294, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029001403.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1329-2013-cr-manter-c-r-lei-14480-2010-7100-viacao-araguarina-ltda-9f5.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1329 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21663, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029007100.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1330-2013-cr-manter-c-r-lei-14480-2010-4146-viacao-araguarina-ltda-f31.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1330 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14902, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029004146.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1331-2013-cr-manter-c-r-lei-14480-2010-7086-viacao-araguarina-ltda-d49.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1331 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21677, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029007086.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1332-2013-cr-manter-c-r-lei-14480-2010-0120-viacao-araguarina-ltda-df6.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1332 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23709, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201200029000120.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1333-2013-cr-manter-c-r-lei-14480-2011-6712-viacao-araguarina-ltda-459.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1333 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23125, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029006712.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1334-2013-cr-manter-c-r-lei-14480-2011-4974-viacao-araguarina-ltda-052.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1334 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22639, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029004974.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1335-2013-cr-manter-c-rec.-nao-conhecido-trcf-2013-1727-empresa-moreira-ltda-6c5.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&deg; 1335 de 20 de setembro de 2013<\/strong><\/span>.<\/a>&nbsp;Disp&otilde;e sobre julgamento do recurso interposto pela Empresa Moreira Ltda, referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 201\/2013, conforme processo n&ordm; 201300029001727.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1336-2013-cr-manter-c-rec.-nao-conhecido-trcf-2013-0688-empresa-moreira-ltda-801.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1336 de 23 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do recurso interposto pela Empresa Moreira Ltda, referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 173\/2013, conforme processo n&ordm; 201300029000688.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1337-2013-cr-manter-c-rec.-nao-conhecido-trcf-2013-0691-expresso-maia-ltda-fd6.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&deg; 1337 de 23 de setembro de 2013<\/strong><\/span>.<\/a>&nbsp;Disp&otilde;e sobre julgamento do recurso interposto pela empresa Expresso Maia Ltda, referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 176\/2013, conforme processo n&ordm; 201300029000691.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1338-2013-cr-manter-c-rec.-nao-conhecido-trcf-2012-7170-viacao-araguarina-ltda-11c.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1338 de 23 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do recurso interposto pela empresa Via&ccedil;&atilde;o Araguarina Ltda, referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 77\/2012, conforme processo n&ordm; 201200029007170.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1339-2013-cr-manter-c-rec.-nao-conhecido-trcf-2013-0712-viacao-asa-verde-ltda-d4e.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1339 de 23 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre julgamento do recurso interposto pela empresa Via&ccedil;&atilde;o Asa Verde Ltda, referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 190\/2013, conforme processo n&ordm; 201300029000712.<\/li>\n<li><span style=\"color: #000080;\"><strong>&nbsp;<a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1340-2013-cr-manter-c-r-lei-14480-2010-6645-expresso-maia-ltda-a71.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1340 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21709, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029007806.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1341-2013-cr-manter-c-r-lei-14480-2010-6645-expresso-maia-ltda-50d.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&deg; 1341 de 20 de setembro de 2013<\/strong><\/span>.<\/a>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 15152, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029006645.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1342-2013-cr-manter-c-r-lei-14480-2010-3231-expresso-maia-ltda-590.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1342 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14730, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029003231.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1343-2013-cr-manter-c-r-lei-14480-2010-1897-expresso-maia-ltda-464.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1343 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14347, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029001897.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1344-2013-cr-manter-c-r-lei-14480-2010-7818-expresso-maia-ltda-32b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1344 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21752, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029007818.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1345-2013-cr-manter-c-r-lei-14480-2008-0092-expresso-maia-ltda-3eb.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&deg; 1345 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span>&nbsp;Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 09734, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 200800029010092.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1346-2013-cr-manter-c-r-lei-14480-2011-4178-expresso-maia-ltda-845.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1346 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22366, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201100029004178.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1347-2013-cr-manter-c-r-lei-14480-2010-4463-expresso-maia-ltda-b3e.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1347 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23750, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201200029000463.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1348-2013-cr-manter-c-r-lei-14480-2010-3568-expresso-maia-ltda-9e1.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1348 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14808, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029003568.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1349-2013-cr-manter-c-r-lei-14480-2010-3558-expresso-maia-ltda-da4.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1349 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14803, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029003558.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1350-2013-cr-manter-c-r-lei-14480-2010-4658-expresso-maia-ltda-e9d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1350 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14962, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029004658.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1351-2013-cr-manter-c-r-lei-14480-2011-8296-expresso-maia-ltda-26a.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1351 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23687, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201100029008296.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1352-2013-cr-manter-c-r-lei-14480-2008-0093-expresso-maia-ltda-0db.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1352 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 09735, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029004658.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1353-2013-cr-manter-c-r-lei-14480-2010-1037-expresso-maia-ltda-2a9.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1353 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14259, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029001037.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1354-2013-cr-manter-c-r-lei-14480-2010-1134-expresso-maia-ltda-738.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1354 de 20 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14256, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029001134.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1357-2013-cr-manter-c-rec.-res.-231-2009-3248-saneago-07d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1357 de 23 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 121\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029003248.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1358-2013-cr-manter-c-rec.-res.-231-2009-1631-saneago-36a.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1358 de 23 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 037\/2009, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029001631.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1359-2013-cr-manter-c-rec.-res.-231-2009-5483-saneago-4b8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1359 de 23 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 022\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029005483.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1360-2013-cr-manter-pedido-revisao-res.-526-2012-0947-atlantica-construcoes-comercio-e-de4.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1360 de 23 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre Pedido de Revis&atilde;o apresentado pela empresa Atl&acirc;ntica Constru&ccedil;&otilde;es, Com&eacute;rcio e Servi&ccedil;os Ltda, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 009\/2012, conforme Processo n&ordm; 201200029000943.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1362-2013-cr-manter-c-rec.-res.-231-2010-2184-saneago-8fa.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1362 de 24 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 028\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029002184.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1363-2013-cr-manter-c-rec.-trcf-2013-0703-nacional-expresso-ltda-d76.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1363 de 24 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do recurso interposto referente a d&eacute;bitos de Taxa de Regula&ccedil;&atilde;o, Controle e Fiscaliza&ccedil;&atilde;o de Servi&ccedil;os P&uacute;blicos &ndash; TRCF, Termo de Lan&ccedil;amento n&ordm; 184\/2013, em nome da empresa Nacional Expresso Ltda, conforme processo n&ordm; 201300029000703.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1365-2013-cr-manter-c-rec.-res.-231-2009-1642-saneago-6c8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1365 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 036\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 200900029001642.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1366-2013-cr-manter-c-rec.-res.-231-2010-4798-saneago-8b3.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1366 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 048\/2011, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029004798.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1367-2013-cr-manter-c-rec.-res.-231-2010-0294-saneago-avocado-5a4.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1367 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 102\/2010, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201000029000294.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1368-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2012-7645-empresa-sto.-antonio-ltda-7c3.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1368 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.515, em nome da Empresa Santo Ant&ocirc;nio Transportes e Turismo Ltda, conforme processo n&ordm; 201200029007645.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1369-2013-cr-manter-s-def.-res.-233-antt-2012-0496-cm-trans-44a.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1369 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.121, em nome da empresa CM Trans, conforme processo n&ordm; 201200029000496.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1370-2013-cr-manter-s-def.-res.-233-antt-2012-3795-cm-trans-6da.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1370 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.929, em nome da empresa CM Trans, conforme processo n&ordm; 201200029003795.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1371-2013-cr-manter-s-def.-res.-233-antt-2012-0477-cm-trans-7ed.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1371 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.111, em nome da empresa CM Trans, conforme processo n&ordm; 201200029000477.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1372-2013-cr-manter-s-def.-res.-233-antt-2012-3791-cm-trans-be7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1372 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.930, em nome da empresa CM Trans, conforme processo n&ordm; 201200029003791.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1373-2013-cr-manter-s-def.-res.-233-antt-2012-0476-cm-trans-29a.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1373 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.110, em nome da empresa CM Trans, conforme processo n&ordm; 201200029000476.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1374-2013-cr-manter-s-def.-res.-233-antt-2012-0256-cm-trans-327.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1374 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856015, em nome da empresa CM Trans, conforme processo n&ordm; 201200029000256.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1375-2013-cr-manter-s-def.-res.-233-antt-2012-1024-cm-trans-2d2.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1375 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.155, em nome da empresa CM Trans, conforme processo n&ordm; 201200029001024.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1376-2013-cr-manter-s-def.-res.-3075-antt-2012-0474-viacao-novo-horizonte-ltda-c6e.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1376 de 25 de setembro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.098, em nome da empresa Via&ccedil;&atilde;o Novo Horizonte Ltda, conforme processo n&ordm; 201200029000474.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1377-2013-cr-manter-c-r-lei-14480-2010-2398-viacao-itajai-ltda-c7b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1377 de 01 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14704, em nome da empresa Via&ccedil;&atilde;o Itaja&iacute; Ltda., conforme processo n&deg; 201000029002398.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1378-2013-cr-manter-c-r-lei-14480-2011-4954-viacao-araguarina-ltda-a71.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1378 de 01 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22640, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029004954.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1379-2013-cr-caducidade-2010-8707-papas-tur-ltda-me-313.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1379 de 01 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre aplica&ccedil;&atilde;o de penalidade &agrave; empresa Papa&rsquo;s Transporte Tur&iacute;stico Ltda &#8211; ME, conforme Processo n&ordm; 201000029008707.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1380-2013-cr-manter-c-r-res.-005-2010-3569-fmb-logistica-ltda.-35b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1380 de 03 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14841, em nome da empresa FMB Log&iacute;stica Ltda., conforme processo n&deg; 201000029003569.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1381-2013-cr-manter-pedido-revisao-res.-005-2009-1847-coop.transp.passageiros-novo-c0b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1381 de 03 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre Pedido de Revis&atilde;o interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes &#8211; CST referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14081, em nome da empresa Cooperativa dos Transportadores de Passageiros do Estado de Goi&aacute;s, conforme Processo n&ordm; 200900029011847.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1382-2013-cr-manter-pedido-revisao-res.-005-2011-4593-coop.transp.passageiros-novo-868.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1382 de 03 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre Pedido de Revis&atilde;o interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes &#8211; CST referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22554, em nome da empresa Cooperativa dos Transportadores de Passageiros do Estado de Goi&aacute;s, conforme Processo n&ordm; 201100029004593.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1383-2013-cr-manter-pedido-revisao-res.-005-2011-1024-coop.transp.passageiros-novo-74d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1383 de 03 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre Pedido de Revis&atilde;o interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes &#8211; CST referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22210, em nome da empresa Cooperativa dos Transportadores de Passageiros do Estado de Goi&aacute;s, conforme Processo n&ordm; 20110002901024.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1384-2013-cr-manter-c-r-res.-297-2013-6640-viacao-araguarina-ltda-d1c.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1384 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23105, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029006640.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1385-2013-cr-manter-c-r-res.-297-2013-6659-viacao-araguarina-ltda-8e7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1385 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23106, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029006659.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1386-2013-cr-manter-c-r-res.-297-2011-4976-viacao-araguarina-ltda-ad2.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1386 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22635, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029004976.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1387-2013-cr-manter-c-r-res.-297-2011-6655-viacao-araguarina-ltda-b9a.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1387 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22914, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029006655.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1388-2013-cr-manter-c-r-res.-297-2013-5477-viacao-araguarina-ltda-166.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1388 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22833, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029005477.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1389-2013-cr-manter-c-r-res.-297-2011-6179-viacao-araguarina-ltda-32b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1389 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22974, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029006179.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1390-2013-cr-manter-c-r-res.-297-2011-7007-viacao-araguarina-ltda-6ed.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1390 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22697, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029007001.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1391-2013-cr-manter-c-r-res.-297-2011-4951-viacao-araguarina-ltda-2c9.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1391 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial deTransportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22641, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029004951.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1392-2013-cr-manter-c-r-res.-297-2011-7966-viacao-araguarina-ltda-7a2.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1392 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23487, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029007966.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1393-2013-cr-manter-c-r-res.-297-2011-7955-viacao-araguarina-ltda-358.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1393 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23491, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201100029007955.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1394-2013-cr-manter-c-r-res.-297-2012-0470-expresso-maia-ltda-fef.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1394 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial deTransportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23828, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201200029000470.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1395-2013-cr-manter-c-r-res.-297-2011-8018-expresso-maia-ltda-abe.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1395 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23314, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201100029008018.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1396-2013-cr-manter-c-r-res.-297-2010-5028-expresso-maia-ltda-285.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1396 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14956, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201000029005028.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1397-2013-cr-manter-c-r-res.-297-2011-4928-expresso-maia-ltda-3f0.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1397 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22658, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201100029004928.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1398-2013-cr-manter-c-r-res.-297-2012-0152-expresso-maia-ltda-a49.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1398 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23703, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201200029000152.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1399-2013-cr-manter-c-r-res.-297-2009-1704-expresso-sao-luiz-ltda-f6f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1399 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 14055, em nome da empresa Expresso S&atilde;o Luiz Ltda., conforme processo n&deg; 200900029011704.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/10\/resolucao-no.-1400-2013-cr-manter-c-r-res.-297-2010-8570-viacao-goianesia-ltda-60d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 1400 de 04 de outubro de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21953, em nome da empresa Auto Via&ccedil;&atilde;o Goianesia Ltda., conforme processo n&deg; 201000029008570.\n<p>&nbsp;<\/p>\n<\/li>\n<\/ul>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resolu&ccedil;&atilde;o n&deg; 1301 de 19 de setembro de 2013.&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.503, em nome da empresaVia&ccedil;&atilde;o Montes Belos Ltda, conforme processo n&ordm; 201200029006733. Resolu&ccedil;&atilde;o n&deg; 1302 de 19 de setembro de 2013.&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.490.477, em nome da empresa Via&ccedil;&atilde;o Montes Belos Ltda, conforme processo [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-64050","post","type-post","status-publish","format-standard","hentry","category-conselho-regulador"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/agr\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/agr\/categoria\/institucional\/conselho-regulador\/\" rel=\"category tag\">Conselho Regulador<\/a>","rttpg_excerpt":"Resolu&ccedil;&atilde;o n&deg; 1301 de 19 de setembro de 2013.&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.503, em nome da empresaVia&ccedil;&atilde;o Montes Belos Ltda, conforme processo n&ordm; 201200029006733. Resolu&ccedil;&atilde;o n&deg; 1302 de 19 de setembro de 2013.&nbsp;Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.490.477, em nome da empresa Via&ccedil;&atilde;o Montes Belos Ltda, conforme processo&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/64050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/comments?post=64050"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/64050\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/media?parent=64050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/categories?post=64050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/tags?post=64050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}