{"id":63105,"date":"2013-07-10T06:07:32","date_gmt":"2013-07-10T09:07:32","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/agr\/resolucoes-do-conselho-regulador-2013-de-501-600-2\/"},"modified":"2013-07-10T06:07:32","modified_gmt":"2013-07-10T09:07:32","slug":"resolucoes-do-conselho-regulador-2013-de-501-600-2","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselho-regulador-2013-de-501-600-2\/","title":{"rendered":"Resolu\u00e7\u00f5es do Conselho Regulador 2013 de 501 &#8211; 600"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<ul>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0501-2013-cr-manter-c-d-intempestiva-res.-233-antt-2011-7736-lm-de-souza-transportes-243.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 501 de 02 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855717, em nome da empresa LM de Souza Transportes., conforme Processo n&ordm; 201100029007736.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0502-2013-cr-manter-c-d-intempestiva-res.-233-antt-2010-7767-empresa-santo-anjo-da-guarda-48a.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 502 de 02 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 821830, em nome da Empresa Santo Anjo da Guarda Ltda., conforme Processo n&ordm; 201000029007767.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0503-2013-cr-manter-s-d-res.-233-antt-2011-4326-transporte-coletivo-brasil-ltda-572.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 503 de 02 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855124, em nome da empresa Transporte Coletivo Brasil Ltda, conforme processo n&ordm; 201100029004326.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0504-2013-cr-manter-s-d-res.-233-antt-2011-0541-fabio-carvalho-dos-santos-silva-turismo-fba.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 504 de 02 de maio de 2013.&nbsp;<\/span><\/a><\/strong><\/span>Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855800, em nome da empresa F&aacute;bio Carvalho dos Santos Silva &#8211; Turismo, conforme processo n&ordm; 201100029000541.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0505-2013-cr-manter-s-d-res.-233-antt-2011-7527-laercio-de-souza-edf.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 505 de 02 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.430.994, em nome de La&eacute;rcio de Souza, conforme processo n&ordm; 201100029007527.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0506-2013-cr-manter-s-d-res.-233-antt-2011-2936-julio-cesar-da-silva-7d6.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 506 de 02 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 581448, em nome de J&uacute;lio C&eacute;sar da Silva, conforme processo n&ordm; 201100029002936.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0507-2013-cr-manter-s-d-res.-233-antt-2011-2420-toptur-transporte-e-turismo-ltda-88b.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 507 de 02 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 581433, em nome da empresa Toptur Transporte e Turismo Ltda, conforme processo n&ordm; 201100029002420.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0508-2013-cr-manter-s-d-res.-3075-antt-2011-3196-expresso-santa-marta-ltda-032.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 508 de 02 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854895, em nome da empresa Expresso Santa Marta Ltda, conforme processo n&ordm; 201100029003196.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0509-2013-cr-manter-s-d-res.-3075-antt-2011-2170-viacao-motta-ltda-3ff.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 509 de 02 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 809573, em nome da empresa Via&ccedil;&atilde;o Motta Ltda, conforme processo n&ordm; 201100029002170.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0510-2013-cr-manter-s-d-res.-3075-antt-2011-1263-planalto-transportes-ltda-978.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 510 de 02 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855731, em nome da empresa Planalto Transportes Ltda, conforme processo n&ordm; 201100029001263.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0511-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-3806-rapido-marajo-ltda-459.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 511 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 763744, em nome da empresa R&aacute;pido Maraj&oacute; Ltda, conforme processo n&ordm; 201100029003806.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0512-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-3793-empresa-gontijo-de-transport-f75.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 512 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 822854, em nome da Empresa Gontijo de Transporte Ltda, conforme processo n&ordm; 201100029003793.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0513-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-4755-transbrasiliana-transp.-turi-cc1.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 513 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856129, em nome da empresa Transbrasiliana Transportes e Turismo Ltda, conforme processo n&ordm; 201100029004755.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0514-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-0647-auto-viacao-goianesia-ltda-7e0.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 514 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856421, em nome da empresa Auto Via&ccedil;&atilde;o Goian&eacute;sia Ltda, conforme processo n&ordm; 201100029000647.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0515-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-1523-viacao-xavante-ltda-963.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 515 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855693, em nome da empresa Via&ccedil;&atilde;o Xavante Ltda, conforme processo n&ordm; 201100029001523.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0516-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2010-8744-rapido-girassol-transportes-l-6da.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 516 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854885, em nome da empresa R&aacute;pido Girassol Transportes Ltda, conforme processo n&ordm; 201000029008744.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0517-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-6794-m.a.b.l.-dos-santos-me-cb7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 517 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.430.953, em nome da empresa M.A.B.L. dos Santos ME, conforme processo n&ordm; 201100029006794.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0518-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-8159-toptur-transporte-ltda-16e.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 518 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854958, em nome da empresa Toptur Transporte e Turismo Ltda, conforme processo n&ordm; 201000029008159.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0519-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2010-9014-toptur-transportes-ltda-3a9.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 519 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854856, em nome da empresa Toptur Transporte e Turismo Ltda, conforme processo n&ordm; 201000029009014.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0520-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-2640-toptur-transportes-ltda-ea5.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 520 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855154, em nome da empresa Toptur Transporte e Turismo Ltda, conforme processo n&ordm; 201100029002640.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0521-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2012-0486-julice-lucia-moreira-pinto-d29.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 521 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.117, em nome de Julice L&uacute;cia Moreira Pinto, conforme processo n&ordm; 201200029000486.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0522-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-4215-fabio-viagens-e-turismo-mococ-85b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 522 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854907, em nome da empresa F&aacute;bio Viagens e Turismo Mococa Ltda, conforme processo n&ordm; 201100029004215.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0523-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-2632-toptur-transportes-ltda-a95.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 523 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 821612, em nome da empresa Toptur Transportes e Turismo Ltda, conforme processo n&ordm; 201100029002632.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0524-2013-cr-manter-c-d-res.-233-antt-2010-2904-brizatur-ltda-c7d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 524 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 822649, em nome da empresa Brizatur Ltda conforme processo n&ordm; 201000029002904.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0525-2013-cr-manter-c-d-res.-233-antt-2011-4002-m.m.-coutinho-viagens-ltda-fbd.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 525 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855849, em nome da empresa M.M. Coutinho Viagens e Turismo Ltda conforme processo n&ordm; 201100029004002.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0526-2013-cr-manter-c-d-res.-3075-antt-2012-8221-expresso-maia-ltda-2c8.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 526 de 03 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.602, em nome da empresa Expresso Maia Ltda conforme processo n&ordm; 201200029008221.<\/li>\n<li><strong><span style=\"color: #000080;\"><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0527-2013-cr-manter-c-d-res.-3075-antt-2012-8213-expresso-maia-ltda-4e1.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 527 de 03 de maio de 2013.<\/span><\/a><\/span><\/strong> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.616, em nome da empresa Expresso Maia Ltda conforme processo n&ordm; 201200029008213.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0528-2013-cr-manter-c-d-res.-3075-antt-2011-0939-expresso-maia-ltda-a1a.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 528 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855682, em nome da empresa Expresso Maia Ltda conforme processo n&ordm; 201100029000939.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0529-2013-cr-manter-c-d-res.-3075-antt-2012-8212-transbrasiliana-transporte-ltda-112.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 529 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.859, em nome da empresa Transbrasiliana Transporte e Turismo Ltda conforme processo n&ordm; 201200029008212.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0530-2013-cr-manter-c-d-res.-3075-antt-2011-4362-helios-coletivos-e-cargas-ltda-e41.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 530 de 03 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 763750, em nome da empresa H&eacute;lios Coletivos e Cargas Ltda conforme processo n&ordm; 201100029004362.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0531-2013-cr-manter-c-d-res.-3075-antt-2011-1998-expresso-maia-ltda-14f.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 531 de 03 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854792, em nome da empresa Expresso Maia Ltda conforme processo n&ordm; 201100029001998.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0532-2013-cr-manter-c-d-res.-3075-antt-2011-4331-viacao-sao-luiz-ltda-003.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 532 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855235, em nome da empresa Via&ccedil;&atilde;o S&atilde;o Luiz Ltda conforme processo n&ordm; 201100029004331.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0533-2013-cr-manter-c-d-res.-3075-antt-2012-8247-expresso-maia-ltda-ec5.pdf\"><strong><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 533 de 03 de maio de 2013<\/span><\/strong>.<\/a> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.612, em nome da empresa Expresso Maia Ltda conforme processo n&ordm; 201200029008247.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0534-2013-cr-manter-c-r-res.-231-2012-4456-saneago-3a2.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 534 de 07 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 017\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201200029004456.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0535-2013-cr-manter-c-r-res.-231-2012-4454-saneago-ef6.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 535 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 015\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201200029004454.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0536-2013-cr-manter-c-r-res.-231-2012-4453-saneago-f23.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 536 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 016\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201200029004453<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0537-2013-cr-manter-c-r-maioria-2011-4731-celg-d-modelo-2-892.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 537 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra o Auto de Infra&ccedil;&atilde;o n&ordm; 008\/2011-AGR, em nome da Concession&aacute;ria CELG Distribui&ccedil;&atilde;o S\/A &#8211; CELG D , conforme Processo n&ordm; 201100029004731.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0538-2013-cr-manter-c-r-res.-297-2011-4168-expresso-maia-ltda-534.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 538 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 22341, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201100029004168.<\/li>\n<li><strong><span style=\"color: #000080;\"><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0539-2013-cr-manter-c-r-res.-297-2010-5416-viacao-araguarina-ltda-4d8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 539 de 07 de maio de 2013.<\/span><\/a><\/span><\/strong> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 15026, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029005416.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0540-2013-cr-manter-c-r-res.-297-2010-8569-auto-viacao-goianesia-3ad.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 540 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21954, em nome da empresa Auto Via&ccedil;&atilde;o Goian&eacute;sia Ltda., conforme processo n&deg; 201000029008569.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0541-2013-cr-manter-c-r-res.-297-2010-8403-viacao-araguarina-ltda-a41.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 541 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21976, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029008403.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0542-2013-cr-manter-c-r-res.-297-2011-7961-expresso-maia-ltda-998.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 542 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 23492, em nome da empresa Expresso Maia Ltda., conforme processo n&deg; 201100029007961.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0543-2013-cr-manter-reducao-da-multa-2009-10681-celg-d-modelo-1-708.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 543 de 07 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Energia &#8211; CSE, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 002\/2010-AGR, em nome da Concession&aacute;ria CELG Distribui&ccedil;&atilde;o S\/A &#8211; CELG D, conforme Processo n&ordm; 200900029010681.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0544-2013-cr-manter-c-r-2011-5422-celg-d-modelo-2-ec1.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 544 de 07 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra o Auto de Infra&ccedil;&atilde;o n&ordm; 005\/2012-AGR, em nome da Concession&aacute;ria CELG Distribui&ccedil;&atilde;o S\/A &#8211; CELG D , conforme Processo n&ordm; 201100029005422.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0545-2013-cr-manter-c-r-res.-231-2012-4455-saneago-e23.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 545 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Saneamento da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 014\/2012, em nome da concession&aacute;ria Saneamento de Goi&aacute;s S\/A &ndash; SANEAGO, conforme processo n&deg; 201200029004455.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0546-2013-cr-manter-c-r-res.-297-2009-1931-nacional-expresso-ltda-4f0.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 546 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 2033, em nome da empresa Nacional Expresso Ltda., conforme processo n&deg; 200900029001931.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0547-2013-cr-manter-c-r-res.-297-2011-3070-real-expresso-ltda-6af.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 547 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21309, em nome da empresa Real Expresso Ltda., conforme processo n&deg; 201100029003070.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0548-2013-cr-manter-c-r-res.-297-2010-5548-viacao-araguarina-ltda-32d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 548 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 15108, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029005548.<\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0549-2013-cr-manter-c-r-res.-297-2010-8178-viacao-araguarina-ltda-c35.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 549 de 08 de maio de 2013<\/strong><\/span>.<\/a> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 21749, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029008178.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0550-2013-cr-manter-c-r-res.-297-2010-5740-viacao-araguarina-ltda-ec5.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 550 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o da C&acirc;mara Setorial de Transportes da AGR, referente ao Auto de Infra&ccedil;&atilde;o n&ordm; 15060, em nome da empresa Via&ccedil;&atilde;o Araguarina Ltda., conforme processo n&deg; 201000029005740.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0551-2013-cr-manter-c-d-res.-233-antt-2012-7390-brasil-center-turismo-ltda-6b1.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 551 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.331, em nome da empresa Brasil Center Turismo Ltda EPP conforme processo n&ordm; 201200029007390.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0552-2013-cr-manter-c-d-res.-233-antt-2012-6527-center-tur-turismo-ltda-3e6.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 552 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.460.222, em nome da empresa Center Tur Turismo Ltda &#8211; EPP conforme processo n&ordm; 201200029006527.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0553-2013-cr-manter-c-d-res.-233-antt-2011-3147-west-side-representacoes-ltda-b61.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 553 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855073, em nome da empresa West Side Representa&ccedil;&otilde;es Viagens e Turismo Ltda conforme processo n&ordm; 201100029003147.<\/li>\n<li style=\"color: #000080;\"><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0554-2013-cr-manter-c-d-res.-233-antt-2011-4211-expresso-sao-luiz-ltda-113.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 554 de 08 de maio de 2013.<\/span><\/a><\/strong><\/span> <span style=\"color: #000000;\">Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855929, em nome da empresa Expresso S&atilde;o Luiz Ltda conforme processo n&ordm; 201100029004211.<\/span><\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0555-2013-cr-manter-c-d-res.-3075-antt-2012-8258-expresso-maia-ltda-d05.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 555 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.609, em nome da empresa Expresso Maia Ltda conforme processo n&ordm; 201200029008258.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0556-2013-cr-manter-c-d-res.-3075-antt-2012-3206-expresso-sao-luiz-ltda-1c3.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 556 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 822433, em nome da empresa Expresso S&atilde;o Luiz Ltda conforme processo n&ordm; 201200029003206.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0557-2013-cr-manter-c-d-res.-3075-antt-2012-2836-expresso-sao-luiz-ltda-eb4.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 557 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.335, em nome da empresa Expresso S&atilde;o Luiz Ltda conforme processo n&ordm; 201200029002836.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0558-2013-cr-manter-c-d-res.-3075-antt-2011-3201-viacao-sao-luiz-ltda-83f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 558 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856262, em nome da empresa Via&ccedil;&atilde;o S&atilde;o Luiz Ltda conforme processo n&ordm; 201100029003201.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0559-2013-cr-manter-c-d-res.-3075-antt-2011-0529-expresso-sao-luiz-ltda-9b4.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 559 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856257, em nome da empresa Expresso S&atilde;o Luiz Ltda- conforme processo n&ordm; 201100029000529.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0560-2013-cr-manter-c-d-res.-3075-antt-2012-3351-expresso-sao-luiz-ltda-eea.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 560 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.459.312, em nome da empresa Expresso S&atilde;o Luiz Ltda- conforme processo n&ordm; 201200029003351.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0561-2013-cr-manter-c-d-res.-3075-antt-2010-8442-expresso-sao-luiz-ltda-2f8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 561 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854782, em nome da empresa Expresso S&atilde;o Luiz Ltda- conforme processo n&ordm; 201000029008442.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0562-2013-cr-manter-c-d-res.-3075-antt-2012-8741-expresso-maia-ltda-6f1.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 562 de 03 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.928, em nome da empresa Expresso Maia Ltda conforme processo n&ordm; 201200029008741.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0563-2013-cr-manter-c-d-res.-3075-antt-2009-8959-transbrasiliana-transporte-ltda-152.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 563 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 582467, em nome da empresa Transbrasiliana Transporte e Turismo Ltda conforme processo n&ordm; 2009200029008959.<\/li>\n<li><span style=\"color: #000080;\"><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0564-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-5002-transbrasiliana-transporte-l-4e2.pdf\"><span style=\"color: #000080;\"><strong>Resolu&ccedil;&atilde;o n&ordm; 564 de 09 de maio de 2013<\/strong>.<\/span><\/a><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855705, em nome da empresa Transbrasiliana Transporte e Turismo Ltda, conforme processo n&ordm; 201100029005002.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0565-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-4334-expresso-araguari-ltda-0b3.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 565 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854906, em nome da empresa Expresso Araguari Ltda, conforme processo n&ordm; 201100029004334.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0566-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2010-5890-jg-turismo-ltda-me-3e7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 566 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854733, em nome da empresa JG Turismo Ltda &#8211; ME, conforme processo n&ordm; 201000029005890.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0567-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2012-7416-toptur-transporte-ltda-697.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 567 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.464.460, em nome da empresa Toptur Transporte e Turismo Ltda, conforme processo n&ordm; 201200029007416.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0568-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2010-1666-coopertrans-ltda-150.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 568 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856276, em nome da empresa COOPERTRANS &#8211; Cooperativa dos Transportadores Rodovi&aacute;rios em Fretamento, conforme processo n&ordm; 201000029001666.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0569-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-0651-jesus-gomes-de-carvalho-b43.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 569 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 821603, em nome da empresa Jesus Gomes de Carvalho e Cia. Ltda, conforme processo n&ordm; 201100029000651.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0570-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2012-9623-massangana-viagens-ltda-00f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 570 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.547, em nome da empresa Massangana Viagens e Turismo Ltda, conforme processo n&ordm; 201200029009623.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0571-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-0034-jesus-goms-de-carvalho-b17.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 571 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856375, em nome da empresa Jesus Gomes de Carvalho e Cia. Ltda, conforme processo n&ordm; 201100029000034.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0572-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-2411-empresa-de-transporte-douzinh-02d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 572 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855221, em nome da Empresa de Transporte Douzinho Ltda, conforme processo n&ordm; 201100029002411.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0573-2013-cr-manter-c-d-intempestiva-res.-233-antt-2010-6352-r-g-locacao-de-veiculos-lt-f64.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 573 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854926, em nome da empresa R &amp; G Loca&ccedil;&atilde;o de Ve&iacute;culos e Transporte Tur&iacute;stico Ltda., conforme Processo n&ordm; 201000029006352.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0574-2013-cr-manter-c-d-intempestiva-res.-233-antt-2012-8793-expresso-santa-marta-ltda-1be.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 574 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.475.527, em nome da empresa Expresso Santa Marta Ltda., conforme Processo n&ordm; 201200029008793.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0575-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-4753-viacao-nacional-sa-be7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 575 de 09 de maio de 2013.<\/span><\/a>&nbsp;<\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856132, em nome da empresa Via&ccedil;&atilde;o Nacional S\/A, conforme processo n&ordm; 201100029004753.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0576-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-5083-empresa-santo-antonio-ltda-040.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 576 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.457.332, em nome da Empresa Santo Ant&ocirc;nio Transporte e Turismo Ltda, conforme processo n&ordm; 201100029005083.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0577-2013-cr-manter-c-d-nao-conhecida-res.-3075-antt-2011-3804-transbrasiliana-transporte-l-1b6.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 577 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855919, em nome da empresa Transbrasiliana Transporte e Turismo Ltda, conforme processo n&ordm; 201100029003804.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0578-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-0054-empresa-gontijo-ltda-4d5.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 578 de 09 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 809106, em nome da Empresa Gontijo de Transportes Ltda, conforme processo n&ordm; 201100029000054.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0579-2013-cr-manter-s-d-res.-233-antt-2011-8175-cm-trans-940.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 579 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.431.042, em nome da empresa CM Trans, conforme processo n&ordm; 201100029008175.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0580-2013-cr-manter-s-d-res.-233-antt-2011-1416-dias-coelho-transporte-ltda-767.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 580 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855815, em nome da empresa Dias Coelho Transporte Ltda &#8211; ME, conforme processo n&ordm; 201100029001416.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0581-2013-cr-manter-s-d-res.-233-antt-2011-3541-rubens-pereira-da-silva-330.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 581 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 822851, em nome de Rubens Pereira da Silva, conforme processo n&ordm; 201100029003541.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0582-2013-cr-manter-s-d-res.-233-antt-2011-0355-monica-avelar-antunes-neto-47f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 582 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 822212, em nome de M&ocirc;nica Avelar Antunes Neto, conforme processo n&ordm; 201100029000355.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0583-2013-cr-manter-s-d-res.-233-antt-2011-0644-viacao-montes-belos-a92.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 583 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 809160, em nome da empresa Via&ccedil;&atilde;o Montes Belos Ltda, conforme processo n&ordm; 201100029000644.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0584-2013-cr-manter-s-d-res.-233-antt-2011-1119-viacao-brasil-real-ltda-dda.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 584 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854686, em nome da empresa Via&ccedil;&atilde;o Brasil Real Ltda, conforme processo n&ordm; 201100029001119.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0585-2013-cr-manter-s-d-res.-233-antt-2011-4802-iristur-transporte-ltda-4e7.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 585 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856137, em nome da empresa Iristur Transportes e Turismo Ltda, conforme processo n&ordm; 201100029004802.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0586-2013-cr-manter-s-d-res.-233-antt-2011-4626-jeverson-freitas-dos-santos-b4e.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 586 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856270, em nome de Jeverson Freitas dos Santos, conforme processo n&ordm; 201100029004626.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0587-2013-cr-manter-s-d-res.-233-antt-2011-4635-viacao-novo-horizonte-ltda-946.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 587 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856105, em nome da empresa Via&ccedil;&atilde;o Novo Horizonte Ltda, conforme processo n&ordm; 201100029004635.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0588-2013-cr-manter-s-d-res.-233-antt-2011-6308-bastos-locadora-de-veiculo-ltda-656.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 588 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855712, em nome da empresa Bastos Locadora de Ve&iacute;culo Ltda &#8211; ME, conforme processo n&ordm; 201100029006308.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0589-2013-cr-manter-s-d-res.-233-antt-2011-2410-expresso-maia-ltda-b7b.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 589 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 854651, em nome da empresa Expresso Maia Ltda, conforme processo n&ordm; 201100029002410.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0590-2013-cr-manter-s-d-res.-233-antt-2011-6738-kawaguchi-eventos-ltda-579.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 590 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.430.957, em nome da empresa Kawaguchi Eventos Transportes e Turismo Ltda, conforme processo n&ordm; 201100029006738.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0591-2013-cr-manter-s-d-res.-233-antt-2011-1267-zanchettur-agencia-de-viagens-ltda-c05.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 591 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856428, em nome da empresa Zanchettur Ag&ecirc;ncia de Viagens e Turismo Ltda, conforme processo n&ordm; 201100029001267<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0592-2013-cr-manter-s-d-res.-233-antt-2011-4324-fabio-carvalho-dos-santos-8c8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 592 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855129, em nome da empresa F&aacute;bio Carvalho dos Santos Silva Turismo, conforme processo n&ordm; 201100029004324.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0593-2013-cr-manter-s-d-res.-233-antt-2011-1832-terra-e-sol-transporte-ltda-c85.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 593 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855772, em nome da empresa Terra e Sol Transporte e Turismo Ltda, conforme processo n&ordm; 201100029001832.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0594-2013-cr-manter-s-d-res.-3075-antt-2011-3549-viacao-anapolina-ltda-b1f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 594 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855225, em nome da empresa Via&ccedil;&atilde;o Anapolina Ltda, conforme processo n&ordm; 201100029003549.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0595-2013-cr-manter-s-d-res.-3075-antt-2011-0361-expresso-sao-luiz-ltda-4f8.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 595 de 10 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856255, em nome da empresa Expresso S&atilde;o Luiz Ltda, conforme processo n&ordm; 201100029000361.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0596-2013-cr-alteracao-tnr-c-r-2009-3044-celg-d-modelo-3-c2d.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 596 de 21 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre recurso interposto contra a decis&atilde;o que estabeleceu o valor do TNR, contido no Of. N&ordm; 500\/2009-DED da AGR, em nome da Concession&aacute;ria CELG Distribui&ccedil;&atilde;o S\/A &#8211; CELG D , conforme Processo n&ordm; 200900029003044.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0597-2013-cr-manter-c-d-nao-conhecida-res.-233-antt-2011-5009-expresso-santa-marta-ltda-f5f.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 597 de 21 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 856149, em nome da empresa Expresso Santa Marta Ltda, conforme processo n&ordm; 201100029005009.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0598-2013-cr-anular-s-d-res.-233-antt-2012-6968-luiz-carlos-tomaz-477.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 598 de 20 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 1.460.274, em nome de Luiz Carlos Tomaz, conforme processo n&ordm; 201200029006968.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0599-2013-cr-manter-s-d-res.-233-antt-2011-2700-guilherme-e-carmo-ltda-d26.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 599 de 21 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 581438, em nome da empresa Guilherme e Carmo Ltda, conforme processo n&ordm; 201100029002700.<\/li>\n<li><span style=\"color: #000080;\"><strong><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/07\/resolucao-no.-0600-2013-cr-manter-s-d-res.-233-antt-2011-4656-welliton-vinhal-caetano-450.pdf\"><span style=\"color: #000080;\">Resolu&ccedil;&atilde;o n&ordm; 600 de 21 de maio de 2013.<\/span><\/a><\/strong><\/span> Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 808727, em nome de Welliton Vinhal Caetano, conforme processo n&ordm; 201100029004656.<\/li>\n<li>\n<\/ul>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resolu&ccedil;&atilde;o n&ordm; 501 de 02 de maio de 2013. Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855717, em nome da empresa LM de Souza Transportes., conforme Processo n&ordm; 201100029007736. Resolu&ccedil;&atilde;o n&ordm; 502 de 02 de maio de 2013. Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 821830, em nome da Empresa Santo Anjo da [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-63105","post","type-post","status-publish","format-standard","hentry","category-conselho-regulador"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/agr\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/agr\/categoria\/institucional\/conselho-regulador\/\" rel=\"category tag\">Conselho Regulador<\/a>","rttpg_excerpt":"Resolu&ccedil;&atilde;o n&ordm; 501 de 02 de maio de 2013. Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 855717, em nome da empresa LM de Souza Transportes., conforme Processo n&ordm; 201100029007736. Resolu&ccedil;&atilde;o n&ordm; 502 de 02 de maio de 2013. Disp&otilde;e sobre julgamento do Auto de Infra&ccedil;&atilde;o n&ordm; 821830, em nome da Empresa Santo Anjo da&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/63105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/comments?post=63105"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/63105\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/media?parent=63105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/categories?post=63105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/tags?post=63105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}