{"id":60519,"date":"2013-01-21T10:01:14","date_gmt":"2013-01-21T12:01:14","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/agr\/resolucoes-do-conselho-regulador-2012-de-12001-1200\/"},"modified":"2013-01-21T10:01:14","modified_gmt":"2013-01-21T12:01:14","slug":"resolucoes-do-conselho-regulador-2012-de-12001-1200","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/agr\/resolucoes-do-conselho-regulador-2012-de-12001-1200\/","title":{"rendered":"Resolu\u00e7\u00f5es do Conselho Regulador 2012 de 1201 &#8211; 1300"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<ul>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/01\/resolucao-no.-1201-2012-cr-manter-s-d-res.-3075-antt-2009-9231-transporte-coletivo-brasil-ltda-46f.pdf\">Resolu&ccedil;&atilde;o n&ordm; 1201 de 28 de dezembro de 2012<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/01\/resolucao-no.-1202-2012-cr-manter-s-d-res.-3075-antt-2011-4349-expresso-santa-marta-ltda-b45.pdf\">Resolu&ccedil;&atilde;o n&ordm; 1202 de 28 de dezembro de 2012<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/01\/resolucao-no.-1203-2012-cr-manter-s-d-res.-3075-antt-2011-4000-expresso-sao-luiz-ltda-41b.pdf\">Resolu&ccedil;&atilde;o n&ordm; 1203 de 28 de dezembro de 2012<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/01\/resolucao-no.-1204-2012-cr-manter-s-d-res.-3075-antt-2011-3808-emtram-empresa-de-transp.-macaubense-2d4.pdf\">Resolu&ccedil;&atilde;o n&ordm; 1204 de 28 de dezembro de 2012<\/a><\/li>\n<li><a href=\"https:\/\/goias.gov.br\/agr\/wp-content\/uploads\/sites\/43\/2013\/01\/resolucao-no.-1205-2012-cr-manter-s-d-res.-3075-antt-2011-7554-viacao-central-bahia-748.pdf\">Resolu&ccedil;&atilde;o n&ordm; 1205 de 28 de dezembro de 2012<\/a><\/li>\n<\/ul>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resolu&ccedil;&atilde;o n&ordm; 1201 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1202 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1203 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1204 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1205 de 28 de dezembro de 2012<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-60519","post","type-post","status-publish","format-standard","hentry","category-conselho-regulador"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/agr\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/agr\/categoria\/institucional\/conselho-regulador\/\" rel=\"category tag\">Conselho Regulador<\/a>","rttpg_excerpt":"Resolu&ccedil;&atilde;o n&ordm; 1201 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1202 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1203 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1204 de 28 de dezembro de 2012 Resolu&ccedil;&atilde;o n&ordm; 1205 de 28 de dezembro de 2012","_links":{"self":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/60519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/comments?post=60519"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/posts\/60519\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/media?parent=60519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/categories?post=60519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/agr\/wp-json\/wp\/v2\/tags?post=60519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}